{"id":9463,"date":"2022-12-09T19:49:22","date_gmt":"2022-12-09T18:49:22","guid":{"rendered":"https:\/\/areopage.net\/blog\/?p=9463"},"modified":"2022-12-09T19:49:58","modified_gmt":"2022-12-09T18:49:58","slug":"il-dio-della-bibbia-arduini-et-al-2022","status":"publish","type":"post","link":"https:\/\/areopage.net\/blog\/2022\/12\/09\/il-dio-della-bibbia-arduini-et-al-2022\/","title":{"rendered":"Il Dio della Bibbia (Arduini et al., 2022)"},"content":{"rendered":"<p><script src='https:\/\/www.bibleparser.net\/BP_Scripturize.js'><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/script><a href=\"https:\/\/amzn.to\/3W0ikcM\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9464\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912221.png?resize=188%2C300\" alt=\"\" width=\"188\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912221.png?resize=188%2C300&amp;ssl=1 188w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912221.png?w=564&amp;ssl=1 564w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" \/><\/a><\/p>\n<p align=\"justify\">\u00a0\u00a0\u00a0J&rsquo;ai le plaisir de vous annoncer la parution de l&rsquo;ouvrage de <a href=\"https:\/\/landeditore.it\/landuniversitypress\/ildiodellabibbia\/\">F. Arduini et al., <em>Il Dio della Bibbia<\/em> (Land University Press, 2022)<\/a>. Cet ouvrage collectif, en italien, s&rsquo;articule autour de l&rsquo;analyse d\u00e9taill\u00e9e de quelques textes cl\u00e9s qui concernent l&rsquo;identit\u00e9 de Dieu et de son Fils, et je suis honor\u00e9 d&rsquo;avoir \u00e9t\u00e9 de la partie, pour la chapitre 9 sur Phi 2.6.<\/p>\n<blockquote>\n<p align=\"justify\">In un contesto socioculturale come il nostro, dove l\u2019inclusione e la pluralit\u00e0 di idee e approcci non sono pi\u00f9 fattori trascurabili, sottolineare letture esegetiche che si discostano da quello che \u00e8 il consensus accademico \u00e8 un dovere che gli autori di questo libro sentono in maniera particolare.<\/p>\n<p align=\"justify\">Chi \u00e8 il Dio della Bibbia?<\/p>\n<p align=\"justify\">\u00e8 una domanda a cui gli autori rispondono con un\u2019attenta analisi del testo, aiutando il lettore a identificare e a distinguere in maniera chiara le figure divine del Padre e del Figlio.<\/p>\n<p align=\"justify\">Con competenza e scrupolosit\u00e0, verranno analizzati i principali versetti biblici, che fanno luce sulla questione ontologica e ipostatica tra Padre e Figlio, aiutando il lettore a comprendere al meglio lo shem\u00e0 Israel e quindi l&rsquo;unicit\u00e0 di Dio.<\/p>\n<\/blockquote>\n<p align=\"justify\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912222.png\" data-rel=\"lightbox-gallery-81yWIzy1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9478\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912222.png?resize=213%2C300\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912222.png?resize=213%2C300&amp;ssl=1 213w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912222.png?w=712&amp;ssl=1 712w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/a><\/p>\n<p align=\"justify\">\u00a0\u00a0\u00a0Pour ceux qui ne ma\u00eetriseraient pas la langue de Dante, il est question d&rsquo;interroger le consensus autour de l&rsquo;identit\u00e9 du Dieu de la Bible, par un r\u00e9examen des textes les plus embl\u00e9matiques qui renseignent sur les figures du P\u00e8re et du Fils. A cet \u00e9gard, il n&rsquo;est pas anodin que le <em>Shema Israel<\/em> (Dt 6.4) soit plus que jamais pr\u00e9sent dans le NT (ex. Mr 12.29, Mt 22.37, Lc 10.27, Jn 17.3, 1Co 8.4-6, Rom 16.27, Eph 4.6, Jc 2.19, 1Ti 2.5, Jud 1.25, Rev 15.4 ; cf. <strong>pp.116-125<\/strong>). C&rsquo;est l&rsquo;indication \u00e9vidente que le christianisme a sans difficult\u00e9 repris cette profession &#8211; ou plut\u00f4t ce commandement \u00e0 professer un <em>Dieu unique<\/em> &#8211; \u00e0 son compte. J\u00e9sus l&rsquo;a rappel\u00e9 clairement, en lui donnant d&rsquo;ailleurs la primaut\u00e9 (Mr 12.29).<\/p>\n<p align=\"justify\">\u00a0\u00a0\u00a0Dans cette perspective, et sous la houlette comp\u00e9tente de Francesco Arduini &#8211; qui a initi\u00e9 ce projet en septembre 2020 &#8211; ce sont donc <strong>10 auteurs de 6 pays<\/strong> qui ce sont attel\u00e9s \u00e0 la t\u00e2che de r\u00e9examiner les textes, et m\u00eame de les passer au crible : <a href=\"https:\/\/orcid.org\/0000-0002-6592-682X\">Francesco <strong>Arduini<\/strong><\/a> et <a href=\"https:\/\/orcid.org\/0000-0002-5067-4471\">Felice <strong>Buon Spirito<\/strong><\/a> (Italie), <a href=\"https:\/\/orcid.org\/0000-0001-9989-6131\">Simone <strong>Frattini<\/strong><\/a> (Suisse), <a href=\"https:\/\/orcid.org\/0000-0002-6529-9512\">Pavlos <strong>Vasileiadis<\/strong><\/a> (Gr\u00e8ce), <a href=\"https:\/\/orcid.org\/0000-0003-3804-6656\">Dan-\u00c5ke <strong>Mattsson<\/strong><\/a>, <a href=\"https:\/\/orcid.org\/0000-0001-5245-8142\">Roman <strong>Montero<\/strong><\/a>, <a href=\"https:\/\/orcid.org\/0000-0002-1551-9804\">Alex <strong>Gonzalez<\/strong><\/a> (Norv\u00e8ge), William <strong>Kelly<\/strong> (\u00c9tats-Unis), <a href=\"https:\/\/orcid.org\/0000-0001-5916-0445\">G\u00e9rard <strong>Gertoux<\/strong><\/a> et <a href=\"https:\/\/orcid.org\/0000-0003-2817-0047\">Didier <strong>Fontaine<\/strong><\/a> [d\u00e9sol\u00e9 pour la 3e personne&#8230;] (France) [voir <strong>pp.3-5<\/strong> pour une liste des contributeurs et un r\u00e9sum\u00e9 de leurs parcours et comp\u00e9tences]. La pr\u00e9face est due \u00e0 <a href=\"https:\/\/sdce.academia.edu\/HalFlemings\">Hal <strong>Flemings<\/strong><\/a>, et la postface \u00e0 Steno <strong>Sari<\/strong>. L&rsquo;ouvrage est d\u00e9dicac\u00e9 \u00e0 la m\u00e9moire du regrett\u00e9 Stefano <strong>Pizzorni<\/strong>, qui avait rejoint l&rsquo;\u00e9quipe pour un chapitre sur Rev 3.14 mais qui est h\u00e9las d\u00e9c\u00e9d\u00e9 au tout d\u00e9but de ce projet. C&rsquo;\u00e9tait un personnage intelligent et haut en couleurs, que j&rsquo;ai eu l&rsquo;honneur de rencontrer en 2009 car il s&rsquo;\u00e9tait occup\u00e9 de la traduction de mon ouvrage sur le Nom <a href=\"https:\/\/www.unilibro.it\/libro\/fontaine-didier-pizzorni-s-cur-\/nome-dio-nuovo-testamento-perche-e-scomparso-testi-greci-ii-secolo-\/9788888907109\">en italien<\/a>, avec son \u00e9pouse. Je l&rsquo;ai malheureusement peu connu et j&rsquo;esp\u00e8re que ce travail collectif honorera sa m\u00e9moire.<\/p>\n<p align=\"justify\">Voici les mati\u00e8res abord\u00e9es, chapitre par chapitre :<\/p>\n<ol>\n<li><em><strong>Exode 3.13,14 &#8211; Quel est son Nom ? <\/strong><\/em>&#8211; <span style=\"color: #008000;\">pp.15-44<\/span>, Exo 3.13, Exo 3.14 &#8211; <span style=\"color: #0000ff;\">G\u00e9rard Gertoux<\/span>\u00a0&#8211; it. <em>Esodo 3:13,14 &#8211; Qual \u00e8 il suo noma ?<\/em><\/li>\n<li><strong><em>Exode 3.14, 15 &#8211; R\u00e9examen de la r\u00e9ponse de Dieu \u00e0 Mo\u00efse sur l&rsquo;Horeb <\/em><\/strong><em>&#8211; <\/em><span style=\"color: #008000;\">pp.45-100<\/span>, Exo 3.14, Exo 3.15 &#8211; <span style=\"color: #0000ff;\">Pavlos Vasileiadis<\/span>\u00a0&#8211; it. <em>Esodo 3:14,15 &#8211; Riesame della riposta di Dio a Mos\u00e8 sull&rsquo;Horeb<\/em><\/li>\n<li><strong><em>Deut\u00e9ronome 6.4 &#8211; Shem\u00e0 Israel<\/em><\/strong> &#8211; <span style=\"color: #008000;\">pp.101-126<\/span>, Dt 6.4 &#8211; <span style=\"color: #0000ff;\">Simone Frattini <\/span>&#8211; it. <em>Deuteronomio 6:4 &#8211; Shem\u00e0 Israel<\/em><\/li>\n<li><strong><em>Proverbes 8.22-31 &#8211; Quoi, Quand et Qui<\/em><\/strong> &#8211; <span style=\"color: #008000;\">pp.127-148<\/span>, Pro 8:22, Pro 8:23, Pro 8:24, Pro 8:25, Pro 8:26, Pro 8:27, Pro 8:28, Pro 8:29, Pro 8:30, Pro 8:31, Pro 8:32 &#8211; <span style=\"color: #0000ff;\">Dan-\u00c5ke Mattsson<\/span>&#8211; it. <em>Proverbi 8:22-31 &#8211; Cosa, Quando et Chi<\/em><\/li>\n<li><strong><em>Zacharie 12.10 &#8211; Ils regarderont vers \u00ab\u00a0moi\u00a0\u00bb ?<\/em><\/strong> &#8211; <span style=\"color: #008000;\">pp.149-170<\/span>, Zec 12.10 &#8211; <span style=\"color: #0000ff;\">Dan-\u00c5ke Mattsson<\/span>&#8211; <em>it. Zaccaria 12:10 &#8211; Guarderanno a \u00ab\u00a0me\u00a0\u00bb ?<\/em><\/li>\n<li><strong><em>Jean 1.1 &#8211; Et la Parole \u00e9tait Dieu ?<\/em><\/strong> &#8211; <span style=\"color: #008000;\">pp.171-214<\/span>, Jn 1.1 &#8211; <span style=\"color: #0000ff;\">Roman Montero<\/span> &#8211; it. <em>Giovanni 1:1 &#8211; La Parola era Dio ?<\/em><\/li>\n<li><strong>Jean 10.30,38 &#8211; Moi et le P\u00e8re nous sommes un<\/strong> &#8211; <span style=\"color: #008000;\">pp.215-224<\/span>, Jn 10.30, Jn 10.38 &#8211; <span style=\"color: #0000ff;\">Felice Buon Spirito<\/span> &#8211; it. <em>Giovanni 10:30,38 &#8211; Io et il Padre siamo uno<\/em><\/li>\n<li><strong><em>Romains 9.5 &#8211; Dieu, qui est au-dessus de tout<\/em> <\/strong>&#8211; <span style=\"color: #008000;\">pp.225-258<\/span>, Rom 9.5 &#8211; <span style=\"color: #0000ff;\">William Kelly<\/span> &#8211; it. <em>Romani 9:5 &#8211; Dio, che \u00e8 sopra tutte le cose<\/em><\/li>\n<li><strong><em>Philippiens 2.6 &#8211; L&rsquo;\u00e9galit\u00e9 avec Dieu<\/em><\/strong> &#8211; <span style=\"color: #008000;\">pp.259-350<\/span>, Phi 2.6 &#8211; <span style=\"color: #0000ff;\">Didier Fontaine<\/span> &#8211; it. <em>Filippesi 2:6 &#8211; Uguaglianza con Dio<\/em><\/li>\n<li><strong><em>Colossiens 1.15-20 &#8211; L&rsquo;image du Dieu invisible<\/em> <\/strong>&#8211; <span style=\"color: #008000;\">pp.351-386<\/span>, Col 1:15, Col 1:16, Col 1:17, Col 1:18, Col 1:19, Col 1:20 &#8211; <span style=\"color: #0000ff;\">Roman Montero<\/span> &#8211; it. <em>Colossesi 1:15-20 &#8211; Immagine del Dio invisibile<\/em><\/li>\n<li><strong><em>H\u00e9breux 1.8 &#8211; Vocatif ou nominatif ?<\/em> <\/strong>&#8211; <span style=\"color: #008000;\">pp.387-416<\/span>, Heb 1.8 &#8211; <span style=\"color: #0000ff;\">Alex Gonzalez<\/span> &#8211; it. <em>Ebrei 1:8 &#8211; Vocativo o nominativo ?<\/em><\/li>\n<\/ol>\n<p align=\"justify\">La liste des contributeurs est situ\u00e9e en <span style=\"color: #008000;\">pp.3-5<\/span>, la pr\u00e9face (<span style=\"color: #0000ff;\">Hal Flemings<\/span>) en <span style=\"color: #008000;\">pp.7-8<\/span>, l&rsquo;introduction (<span style=\"color: #0000ff;\">Francesco Arduini<\/span>), en <span style=\"color: #008000;\">pp.9-14<\/span>, la conclusion (<span style=\"color: #0000ff;\">Francesco Arduini<\/span>), en <span style=\"color: #008000;\">pp.413-416<\/span>, la postface (<span style=\"color: #0000ff;\">Steno Sari<\/span>) en <span style=\"color: #008000;\">pp.417-418<\/span>, la bibliographie en <span style=\"color: #008000;\">pp.419-442<\/span>, puis viennent les abr\u00e9viations <span style=\"color: #008000;\">pp.443-448<\/span>, les remerciements <span style=\"color: #008000;\">p.449<\/span>, et enfin la table des mati\u00e8res <span style=\"color: #008000;\">pp.451-452<\/span>.<\/p>\n<p align=\"justify\">\u00a0\u00a0\u00a0C&rsquo;est ce projet italien qui a initi\u00e9 le vaste chantier qu&rsquo;a \u00e9t\u00e9 pour moi le r\u00e9examen de Phi 2.6 (9 mois d&rsquo;intense travail avec plus de 650 ouvrages et \u00e9tudes consult\u00e9s !). Le chapitre 9 auquel j&rsquo;ai contribu\u00e9 reprend pour l&rsquo;essentiel le <strong><em>chapitre 2<\/em><\/strong> de <a href=\"https:\/\/areopage.net\/blog\/2022\/01\/24\/dieu-ou-comme-dieu-enquete-philologique-sur-%ce%b1%cc%94%cf%81%cf%80%ce%b1%ce%b3%ce%bc%ce%bf%cf%82-en-philippiens-2-6-fontaine-2022\/\">mon ouvrage paru en d\u00e9but d&rsquo;ann\u00e9e 2022<\/a>, ainsi que les \u00e9l\u00e9ments d&rsquo;introduction, de conclusion et quelques \u00e9l\u00e9ments de contexte dans les notes. Cette contribution est donc purement linguistique, et pour se faire une id\u00e9e exacte de l&rsquo;hymne christologique, j&rsquo;invite bien entendu les lecteurs \u00e0 se reporter \u00e0 l&rsquo;ouvrage complet, et ce notamment pour le contexte historique, et la synth\u00e8se d&rsquo;ordre th\u00e9ologique. Je profite de l&rsquo;occasion pour dire un grand merci \u00e0 Francesco Arduini, sans lequel ni le chapitre, ni l&rsquo;ouvrage complet n&rsquo;existeraient : <em>Grazie Francesco !<\/em><\/p>\n<p align=\"justify\">\u00a0\u00a0\u00a0Avec ces indications, vous savez \u00e0 peu pr\u00e8s tout ce qu&rsquo;il faut savoir pour vous donner envie de lire l&rsquo;ouvrage italien&#8230;<\/p>\n<p align=\"justify\">&#8230; et s&rsquo;il faut encore quelque argument, <a href=\"https:\/\/landeditore.it\/landuniversitypress\/arduiniinterviste\/\"><strong>une s\u00e9rie de vid\u00e9os dirig\u00e9es par F. Arduini<\/strong><\/a> sont en cours de pr\u00e9paration. Deux sont d\u00e9j\u00e0 disponibles, celles de R. Montero et de moi-m\u00eame.<\/p>\n<ul>\n<li><strong>Roman Montero<\/strong><\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=igbmjybYN8U&amp;t=6s\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9491\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912223.png?resize=300%2C172\" alt=\"\" width=\"300\" height=\"172\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912223.png?resize=300%2C172&amp;ssl=1 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912223.png?w=684&amp;ssl=1 684w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<ul>\n<li><strong>Didier Fontaine<\/strong> (vous remarquerez pour l&rsquo;occasion combien je suis <em>fluent<\/em> en <em>Frenglish<\/em>)<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=MW-_PW-oZac&amp;feature=emb_imp_woyt\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9492\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912224.png?resize=300%2C169\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912224.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2022\/12\/0912224.png?w=686&amp;ssl=1 686w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Ici seront ajout\u00e9es les vid\u00e9os suivantes.<\/em><\/p>\n<p align=\"justify\">Il ne vous reste plus qu&rsquo;\u00e0 vous procurer l&rsquo;ouvrage (<a href=\"https:\/\/amzn.to\/3W0ikcM\">pour une somme tout \u00e0 fait modique, comme vous le verrez<\/a>) et vous plonger dans sa passionnante lecture : <em>Tolle, lege !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0J&rsquo;ai le plaisir de vous annoncer la parution de l&rsquo;ouvrage de F. Arduini et al., Il Dio della Bibbia (Land University Press, 2022). Cet ouvrage collectif, en italien, s&rsquo;articule autour de l&rsquo;analyse d\u00e9taill\u00e9e de quelques textes cl\u00e9s qui concernent l&rsquo;identit\u00e9 de Dieu et de son Fils, et je suis honor\u00e9 d&rsquo;avoir \u00e9t\u00e9 de la partie, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,7,8,94],"tags":[],"class_list":["post-9463","post","type-post","status-publish","format-standard","hentry","category-actualites","category-grec-biblique","category-hebreu-biblique","category-liens"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-2sD","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":3434,"url":"https:\/\/areopage.net\/blog\/2015\/07\/01\/cours-dhebreu-biblique-randrianaivo-2015\/","url_meta":{"origin":9463,"position":0},"title":"Cours d&rsquo;h\u00e9breu biblique (Randrianaivo, 2015)","author":"areopage","date":"01\/07\/2015","format":false,"excerpt":"Ce livre est un manuel d\u2019apprentissage de l\u2019h\u00e9breu biblique et une introduction \u00e0 la langue h\u00e9bra\u00efque. Il est destin\u00e9 \u00e0 former des \u00e9tudiants de premi\u00e8re ann\u00e9e en th\u00e9ologie. L\u2019auteur a cr\u00e9\u00e9 ce manuel \u00e0 partir des cours dispens\u00e9s par les professeurs Henri Blocher et Bernard Huck \u00e0 la Facult\u00e9 Libre\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"https:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"CoursHebreuBibliqueRandrianaivo","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/07\/CoursHebreuBibliqueRandrianaivo-207x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1548,"url":"https:\/\/areopage.net\/blog\/2014\/04\/13\/la-bibbia-prima-del-dogma-f-arduini-s-pizzorni-s-frattini-2013\/","url_meta":{"origin":9463,"position":1},"title":"La Bibbia prima del dogma (F. Arduini, S. Pizzorni, S. Frattini, 2013)","author":"areopage","date":"13\/04\/2014","format":false,"excerpt":"Review disponible en PDF. Cet ouvrage paru fin 2013\u00a0int\u00e9ressera toutes les personnes intrigu\u00e9es par les probl\u00e8mes\u00a0de traduction de la Bible. Le titre \u00e9voque \u00e0 dessein un\u00a0ouvrage de M.-E. Boismard,\u00a0A l'aube du christianisme, avant la naissance des dogmes\u00a0(1998) - ce\u00a0qui, pour moi, est plut\u00f4t avenant. Quant au sous-titre, il pose la\u00a0Traduction\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"https:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"0904141","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/0904141.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5732,"url":"https:\/\/areopage.net\/blog\/2017\/01\/28\/grec-biblique-quelques-outils\/","url_meta":{"origin":9463,"position":2},"title":"Grec biblique : quelques outils","author":"areopage","date":"28\/01\/2017","format":false,"excerpt":"Les manuels pour apprendre le grec biblique ne manquent pas. \u00a0Cependant,\u00a0il est beaucoup plus d\u00e9licat de progresser. Je livre ici quelques pistes. La premi\u00e8re concerne un ouvrage sorti l'ann\u00e9e dernier, K\u00f6stenberger, Merkle et Plummer, Gooing Deeper\u00a0with New Testament Greek\u00a0(B&H Academic, 2016), qui est une parfaite illustration du genre d'usuel qui\u2026","rel":"","context":"Dans &quot;grec biblique&quot;","block_context":{"text":"grec biblique","link":"https:\/\/areopage.net\/blog\/category\/grec-biblique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2017\/01\/2801171-206x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4685,"url":"https:\/\/areopage.net\/blog\/2016\/03\/10\/les-langues-bibliques-avec-memrise\/","url_meta":{"origin":9463,"position":3},"title":"Les langues bibliques avec Memrise","author":"areopage","date":"10\/03\/2016","format":false,"excerpt":"C'est une application qui est facile \u00e0 adopter, intuitive et passablement addictive... Memrise. Cette application, disponible en ligne, sur Google Play et sur l'App Store, permet d'apprendre ou de r\u00e9viser du vocabulaire. Mais cela va plus loin : d\u00e9partements fran\u00e7ais, code de la route, \u00e9gyptien hi\u00e9roglyphique, peinture, chronologies diverses, tests\u2026","rel":"","context":"Dans &quot;grec biblique&quot;","block_context":{"text":"grec biblique","link":"https:\/\/areopage.net\/blog\/category\/grec-biblique\/"},"img":{"alt_text":"1","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2016\/03\/1-300x278.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4589,"url":"https:\/\/areopage.net\/blog\/2016\/02\/01\/vocabulaire-arameen-hebreu-etoughe-2011\/","url_meta":{"origin":9463,"position":4},"title":"Vocabulaire aram\u00e9en-h\u00e9breu (\u00c9tough\u00e9, 2011)","author":"areopage","date":"01\/02\/2016","format":false,"excerpt":"Pour qui s'int\u00e9resse \u00e0 l'apprentissage du vocabulaire de l'h\u00e9breu et de l'aram\u00e9en bibliques, cet ouvrage semble int\u00e9ressant. Je livre ici mon sentiment sur la m\u00e9thode, extrait de mon commentaire Amazon : Il n'y a pas d'outil adapt\u00e9 en fran\u00e7ais pour apprendre syst\u00e9matiquement le vocabulaire de l'h\u00e9breu biblique. Cet ouvrage de\u2026","rel":"","context":"Dans &quot;h\u00e9breu biblique&quot;","block_context":{"text":"h\u00e9breu biblique","link":"https:\/\/areopage.net\/blog\/category\/hebreu-biblique\/"},"img":{"alt_text":"010216","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2016\/02\/010216.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2791,"url":"https:\/\/areopage.net\/blog\/2014\/12\/20\/shebanq-recherche-syntaxique-pour-lhebreu-biblique\/","url_meta":{"origin":9463,"position":5},"title":"SHEBANQ : recherche syntaxique pour l&rsquo;h\u00e9breu biblique","author":"areopage","date":"20\/12\/2014","format":false,"excerpt":"Non, vous ne r\u00eavez pas :\u00a0SHEBANQ\u00a0(System for HEBrew Text: ANnotations for Queries and Markup) propose un outil de recherche syntaxique pour l'h\u00e9breu biblique, en ligne, qui non seulement est gratuit mais surtout tr\u00e8s \u00e9labor\u00e9. Bien s\u00fbr, il faut se plonger dans la documentation et les exemples, sous peine de patauger\u2026","rel":"","context":"Dans &quot;h\u00e9breu biblique&quot;","block_context":{"text":"h\u00e9breu biblique","link":"https:\/\/areopage.net\/blog\/category\/hebreu-biblique\/"},"img":{"alt_text":"2012148","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/12\/2012148-150x150.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/9463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=9463"}],"version-history":[{"count":39,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/9463\/revisions"}],"predecessor-version":[{"id":9506,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/9463\/revisions\/9506"}],"wp:attachment":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=9463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=9463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=9463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}