{"id":3405,"date":"2015-06-28T16:35:54","date_gmt":"2015-06-28T15:35:54","guid":{"rendered":"http:\/\/areopage.net\/blog\/?p=3405"},"modified":"2015-07-25T13:52:47","modified_gmt":"2015-07-25T12:52:47","slug":"nomina-sacra-et-septante-qui-et-quand","status":"publish","type":"post","link":"https:\/\/areopage.net\/blog\/2015\/06\/28\/nomina-sacra-et-septante-qui-et-quand\/","title":{"rendered":"Nomina sacra et Septante : qui et quand ?"},"content":{"rendered":"<div id=\"attachment_3420\" style=\"width: 410px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/06\/PBodmerX.png\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3420\" class=\"wp-image-3420 \" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/06\/PBodmerX.png?resize=400%2C164\" alt=\"PBodmerX\" width=\"400\" height=\"164\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/06\/PBodmerX.png?resize=300%2C123&amp;ssl=1 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/06\/PBodmerX.png?w=843&amp;ssl=1 843w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><p id=\"caption-attachment-3420\" class=\"wp-caption-text\">P. Bodmer XXIV (d\u00e9tail du Psaume 35) ; <a href=\"http:\/\/www.amazon.fr\/gp\/product\/B0014QWLF6\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=B0014QWLF6&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=PKKICX5XOGF43C2V\">Kasser 1967<\/a>, pl. 17<\/p><\/div>\n<p style=\"text-align: justify;\">Pour faire suite \u00e0 une question qui m&rsquo;a \u00e9t\u00e9 pos\u00e9e r\u00e9cemment, j&rsquo;apporte ici quelques pr\u00e9cisions. Au vrai, la r\u00e9ponse se trouve d\u00e9j\u00e0 indiqu\u00e9e dans un tableau de mon post <a href=\"http:\/\/areopage.net\/blog\/2014\/06\/29\/%CE%B9%CC%93%CE%B1%CF%89-%CE%B8%CE%B5%CE%BF%CF%82-%CE%BA%CF%85%CF%81%CE%B9%CE%BF%CF%82-le-nom-dans-la-lxx-originale\/\">\u0399\u0313\u03b1\u03c9\u0301, \u03b8\u03b5\u03bf\u0301\u03c2, \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 ? Le Nom dans la LXX \u00ab originale \u00bb\u2026<\/a>, ou encore dans mes ouvrages sur le nom divin dans le NT (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/2296035590\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2296035590&amp;linkCode=as2&amp;tag=encyclopaed09-21\">2007 : 52-53<\/a>) et le P52 (<a href=\"http:\/\/areopage.net\/PDF\/P52%20%28P.%20Rylands.Gr.457%29_NominaSacra_Fontaine.pdf\">2012 : 24<\/a>). Le sujet cependant ne cesse d&rsquo;interroger. Voyons donc de plus pr\u00e8s, en alliant synth\u00e8se \u00e0 simplicit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Mais pensons aux personnes press\u00e9es, et r\u00e9sumons en quelques mots la th\u00e8se soutenue :<strong> les <em>nomina sacra<\/em> apparaissent dans la Septante au IIe si\u00e8cle de notre \u00e8re, dans les copies chr\u00e9tiennes<\/strong>. Pr\u00e9c\u00e9demment, c&rsquo;est-\u00e0-dire avant l&rsquo;apparition du christianisme, la Septante \u00e9tait un document juif et le proc\u00e9d\u00e9 des nomina sacra n&rsquo;existait pas. Le plus sacr\u00e9 des mots, le nom divin, \u00e9tait transcrit en h\u00e9breu au sein du texte grec (h\u00e9breu carr\u00e9, pal\u00e9o-h\u00e9breu), ou transcrit en grec (phon\u00e9tis\u00e9 <em>Ia\u00f4<\/em>). Il n&rsquo;y avait pas de proc\u00e9d\u00e9 particulier pour \u00ab\u00a0Dieu\u00a0\u00bb, \u00ab\u00a0P\u00e8re\u00a0\u00bb, \u00ab\u00a0J\u00e9rusalem\u00a0\u00bb, \u00ab\u00a0fils\u00a0\u00bb ni bien s\u00fbr \u00ab\u00a0J\u00e9sus\/Josu\u00e9\u00a0\u00bb. Au premier si\u00e8cle et avec l&rsquo;adoption de la Septante par les chr\u00e9tiens (sp\u00e9cialement \u00e0 des fins apolog\u00e9tiques), les Juifs se d\u00e9sint\u00e9ressent de ce corpus et commandent des r\u00e9visions (Aquila, Symmaque, Th\u00e9odotion et d&rsquo;autres). Ils cessent donc de le copier. Ainsi, ce sont les chr\u00e9tiens qui copient d\u00e9sormais la Septante ; or ce qui interpelle d&#8217;embl\u00e9e, c&rsquo;est l&rsquo;usage nouveau de consid\u00e9rer certains mots plus sacr\u00e9s que d&rsquo;autres : <em>Seigneur, Dieu, J\u00e9sus, p\u00e8re, esprit, m\u00e8re, J\u00e9rusalem, fils, croix<\/em>. Pour dater l&rsquo;apparition de ce ph\u00e9nom\u00e8ne, il suffit de recenser l&rsquo;ensemble des t\u00e9moins de la Septante et y examiner l&rsquo;usage de ces \u00ab\u00a0mots sacr\u00e9s\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">La th\u00e8se que je soutiens ici n&rsquo;est pas vraiment une th\u00e8se en soi : c&rsquo;est un constat. Sa seule originalit\u00e9 est de soutenir que l&rsquo;origine des nomina sacra <em>est chr\u00e9tienne, <\/em>car certains sp\u00e9cialistes opinent pour une origine juive. Il est en effet difficile d&rsquo;attribuer un manuscrit \u00e0 une communaut\u00e9, juive ou chr\u00e9tienne, par l&rsquo;examen de la seule \u00e9criture (cf. <a href=\"http:\/\/www.sbl-site.org\/assets\/pdfs\/presidentialaddresses\/JBL123_1_1Epp2003.pdf\">Epp, JBL 123\/1, 2004 : 20<\/a>)&#8230; Pire, le traitement du nom est lui-m\u00eame un <em>crit\u00e8re<\/em> pour identifier ou non une communaut\u00e9 : on touche au raisonnement circulaire. Deux autres crit\u00e8res, non infaillibles bien s\u00fbr, sont le <em>mat\u00e9riau<\/em> utilis\u00e9 (parchemin, papyrus) et la <em>forme<\/em> du document (rouleau, codex).<\/p>\n<p style=\"text-align: justify;\">Partant de ce constat, on peut m\u00eame aller plus loin, et lier l&rsquo;\u00e9mergence des <em>nomina sacra<\/em> \u00e0 un ph\u00e9nom\u00e8ne de mim\u00e9tisme : quand ils abord\u00e8rent les copies juives de la Septante, que ces copies fussent des r\u00e9visions ou non, les chr\u00e9tiens remarqu\u00e8rent sans doute rapidement \u00e0 quel niveau de sacralit\u00e9 le nom divin \u00e9tait \u00e9lev\u00e9. Or, pour eux, le nom de Dieu n&rsquo;\u00e9tait pas le seul sacr\u00e9 : celui de <em>J\u00e9sus<\/em> l&rsquo;\u00e9tait aussi (puis <em>Dieu<\/em>, puis <em>fils<\/em>, puis <em>croix<\/em>, et ainsi de suite). Ils cr\u00e9\u00e8rent donc un syst\u00e8me de sacralisation de leur cr\u00fb : les <em>nomina sacra<\/em>. A mon sens, ce ph\u00e9nom\u00e8ne proc\u00e8de d&rsquo;une tension entre <em>imitation<\/em> et <em>rejet,<\/em> qu&rsquo;on peut dater <strong>vers 80 &#8211; 115 de notre \u00e8re<\/strong> (voir <a href=\"http:\/\/areopage.net\/PDF\/P52%20%28P.%20Rylands.Gr.457%29_NominaSacra_Fontaine.pdf\">Fontaine 2012 : 23-28<\/a>), qui a contribu\u00e9 \u00e0 la cr\u00e9ation \u00ab\u00a0d\u2019une culture et de symboles propres\u00a0\u00bb. Ainsi je souscrits \u00e0 cette analyse du SDB XII, col. 664 :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">(&#8230;) on peut estimer en cons\u00e9quence que le syst\u00e8me des nomina sacra a d\u00fb \u00eatre cr\u00e9\u00e9 en milieu s\u00e9mitique et non \u00e0 Alexandrie, vraisemblablement <strong>dans la communaut\u00e9 chr\u00e9tienne<\/strong> de J\u00e9rusalem, et qu&rsquo;il n&rsquo;a pu \u00eatre si universellement r\u00e9pandu que par son adoption rapide \u00e0 Alexandrie. <strong>Ce syst\u00e8me<\/strong>, qui dans sa forme primaire abr\u00e8ge des termes essentiellement chr\u00e9tiens, tels que J\u00e9sus, Christ, Croix, P\u00e8re, Esprit, <strong>peut \u00eatre consid\u00e9r\u00e9 comme une profession de foi<\/strong>.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Dans ce qui suit je propose de fournir les \u00e9l\u00e9ments bibliographiques n\u00e9cessaires \u00e0 l&rsquo;\u00e9tude de ce sujet : liste des t\u00e9moins de la Septante, et liste des manuscrits les plus pertinents.<\/p>\n<p style=\"text-align: justify;\"><strong><em>1. Les t\u00e9moins du texte de la Septante<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Obtenir une liste compl\u00e8te des t\u00e9moins du texte de la Septante n&rsquo;est pas une t\u00e2che ais\u00e9e. Je vous recommande en premier lieu de consulter les ouvrages bibliographiques sp\u00e9cialis\u00e9s :<\/p>\n<p style=\"text-align: justify;\">&#8211; <a href=\"https:\/\/books.google.fr\/books?id=kqIl3quF9FQC&amp;lpg=PR11&amp;ots=BG1PRda7Ad&amp;dq=bibliographie%20septante&amp;hl=fr&amp;pg=PA87#v=onepage&amp;q&amp;f=false\">Dogniez, <em>Bibliographie de la Septante 1970-1993<\/em> (Brill, 1995), p.87 ss<\/a><\/p>\n<p style=\"text-align: justify;\">&#8211; <a href=\"https:\/\/books.google.fr\/books?id=eNUUAAAAIAAJ&amp;lpg=PA69&amp;ots=B8hjrOyWxQ&amp;dq=Verzeichnis%20der%20griechischen%20Handschriften%20des%20ATs.&amp;hl=fr&amp;pg=PA68#v=onepage&amp;q&amp;f=false\">Jellicoe et al., <em>A Classified Bibliography of the Septuagint<\/em> (Brill, 1976), p.68 ss<\/a><\/p>\n<p style=\"text-align: justify;\">Cela a le m\u00e9rite de l&rsquo;exhaustivit\u00e9, au moins jusqu&rsquo;\u00e0 la date de publication de l&rsquo;ouvrage ou \u00e0 peu pr\u00e8s, mais \u00e0 moins de vouloir balayer tout ce qui a \u00e9t\u00e9 publi\u00e9, on peut se sentir un peu perdu. A cet effet, les dictionnaires et encyclop\u00e9dies de r\u00e9f\u00e9rence peuvent fournir de pr\u00e9cieuses synth\u00e8ses, en particulier <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0687192692\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0687192692&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=CLE76LBFHWZE5VPK\"><em>IDBSup<\/em> 807-815<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0300140053\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0300140053&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=MPJ5MIMJQNK6GHMJ\">ABD 5 : 1102-1104<\/a>, et <a href=\"https:\/\/en.wikipedia.org\/wiki\/Septuagint_manuscripts\">Wikipedia, \u00ab\u00a0Septuagint manuscripts\u00a0\u00bb<\/a>. On peut aussi consulter avec profit les manuels d&rsquo;introduction \u00e0 la Septante, qui souvent contiennent des rubriques consacr\u00e9s aux t\u00e9moins du texte, ainsi <a href=\"https:\/\/archive.org\/stream\/introductiontool00swet#page\/122\/mode\/2up\">Swete-Ottley 1968 : 122-170<\/a> ou <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0801036496\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0801036496&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=V5QGFAX62O3CZNTH\">Jobes-Silva 2000 : 57-68<\/a>, mais cela se r\u00e9v\u00e8le souvent insuffisant. De m\u00eame, les ouvrages d&rsquo;introduction \u00e0 la papyrologie ou \u00e0 la pal\u00e9ographie peuvent en recenser un certain nombre, voire fournir des planches ou des listes fort utiles (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/0195029240\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0195029240&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=GAMCVDHSDATE3PJS\">Metzger 1991 : 59ss<\/a>, <a href=\"https:\/\/books.google.fr\/books?id=70NCAQAAIAAJ&amp;hl=fr&amp;source=gbs_navlinks_s\">Devreesse 1954<\/a>, sp\u00e9cialement <a href=\"http:\/\/www.amazon.fr\/gp\/product\/8834369106\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=8834369106&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=FPB722JFASWP6ODL\">Montevecchi 1991 : 296-323<\/a>). Plus d\u00e9licat, mais non moins int\u00e9ressant, les <em>apparats critiques<\/em> ou les <em>\u00e9ditions<\/em> m\u00eame du texte contiennent de pr\u00e9cieuses listes, ainsi <a href=\"http:\/\/areopage.net\/blog\/2014\/07\/02\/text-history-of-the-greek-pentateuch-wevers-1974-1992\/\">Wewers<\/a>, <a href=\"https:\/\/books.google.fr\/books?id=ytFciPVntCoC&amp;printsec=frontcover&amp;hl=fr#v=onepage&amp;q&amp;f=false\">Holmes-Parsons<\/a>, <a href=\"https:\/\/fr.scribd.com\/collections\/3144183\/Brooke-McLean-Thackeray-The-Old-Testament-in-Greek-according-to-the-text-of-Codex-vaticanus-1906\">Brooke-McLean-Thackeray<\/a>, <a href=\"https:\/\/www.logos.com\/product\/4951\/gottingen-septuagint\">G\u00f6ttingen LXX<\/a>, etc.<\/p>\n<p style=\"text-align: justify;\">Enfin, on peut se reporter \u00e0 des catalogues papyrologiques &#8211; qui sont sans doute ce qui se fait de mieux en la mati\u00e8re : le plus connu est celui de <a href=\"https:\/\/books.google.fr\/books\/about\/Catalogue_des_papyrus_litt%C3%A9raires_juifs.html?id=V_d0QgAACAAJ&amp;redir_esc=y\">J. van Haelst, <em>Catalogue des papyrus litt\u00e9raires juifs et chr\u00e9tiens<\/em><\/a> (Paris, 1976 ; quelques r\u00e9f\u00e9rences disponibles sur <a href=\"http:\/\/www.papyrologie.paris-sorbonne.fr\/menu1\/collections\/pgrec\/vh.htm\">un site de la Sorbonne<\/a>). Mais il est difficile d&rsquo;acc\u00e8s. Heureusement, son contenu est disponible en ligne dans la <a href=\"http:\/\/www.trismegistos.org\/index2.php\"><em>Leuven Database of Ancient Books<\/em> <\/a>(hormis les r\u00e9f\u00e9rences post\u00e9rieures au IXe s.). De surcro\u00eet, l&rsquo;excellent article \u00ab\u00a0Septante\u00a0\u00bb dans le <strong><em>Suppl\u00e9ment au Dictionnaire de la Bible<\/em>, tome XII, col. 536-691 (1996)<\/strong>, met \u00e0 jour ce catalogue. La section \u00ab\u00a0noms divins\u00a0\u00bb (<strong>col. 661-664<\/strong>) liste d&rsquo;ailleurs les diverses m\u00e9thodes de rendre le t\u00e9tragramme (h\u00e9breu carr\u00e9, pal\u00e9o-h\u00e9breu, transcription phon\u00e9tique, etc.).<\/p>\n<p style=\"text-align: justify;\">On se reportera \u00e9galement \u00e0 la riche collection de la <a href=\"http:\/\/gallica.bnf.fr\/Search?ArianeWireIndex=index&amp;p=1&amp;lang=FR&amp;q=manuscrits+grecs&amp;x=17&amp;y=14\">BnF<\/a> (sp\u00e9cialement au <a href=\"http:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k2091387.r=robert+devreesse.langFR\">fonds Coislin<\/a> par Devreesse).<\/p>\n<p style=\"text-align: justify;\">Pour ceux qui souhaiteraient obtenir une liste commode, celle de Hurtado &#8211; extraite de son ouvrage <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0802828957\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0802828957&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=VJEBHFBVZTWT2VZQ\"><em>Earliest artifacts<\/em> (2006 : 209-229)<\/a> &#8211; est excellente : <strong><a href=\"http:\/\/areopage.net\/PDF\/Hurtado_II-IIIe%20s%20papyrus.pdf\">Hurtado, Christian Literary Texts in Manuscripts of Second &amp; Third Centuries<\/a><\/strong>. Tout aussi utile est la suivante : <strong><a href=\"http:\/\/areopage.net\/PDF\/PapyriFromTheRiseOfChristianityInEgypt.pdf\">Papyri from the Rise of Christianity in Egypt<\/a>. <\/strong>Pour ce type de r\u00e9f\u00e9rences, reportez-vous \u00e0 la rubrique <a href=\"http:\/\/areopage.net\/blog\/liens\/#pap\">Liens<\/a> de ce blog.<\/p>\n<p style=\"text-align: justify;\"><strong><em>2. D&rsquo;un proc\u00e9d\u00e9 scribal \u00e0 un autre<\/em><\/strong><\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Dans nos manuscrits de la Septante, le correspondant habituel du t\u00e9tragramme YHWH est \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2. Au t\u00e9moignage d&rsquo;Orig\u00e8ne (<em>In Ps.<\/em> II, 2 ; <em>PG<\/em>, XII, col. 1103) et de saint J\u00e9r\u00f4me (<em>Prologus galeatus<\/em>), les mss juifs de la Septante transcrivaient le t\u00e9tragramme en caract\u00e8res h\u00e9breux. Aujourd&rsquo;hui les fragments de mss pr\u00e9sentant cette particularit\u00e9 sont connus, d&rsquo;origine juive. D\u00e8s lors, on pourrait croire avec P. Kahle (<em>The Cairo Geniza<\/em>, Oxford 1959\/2, p.224) que l&rsquo;introduction de \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 pour \u00e9crire (\u00e0 distinguer de lire ou de prononcer) le t\u00e9tragramme est d&rsquo;origine chr\u00e9tienne. Exacte ou non, cette conclusion est \u00e0 distinguer de l&rsquo;usage juif hell\u00e9nistique de d\u00e9signer Dieu par le nom de \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2, usage tr\u00e8s probablement ant\u00e9rieur \u00e0 l&rsquo;\u00e8re chr\u00e9tienne et certain chez Philon (&#8230;). Il n&rsquo;y a pas de doute que \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 ait \u00e9t\u00e9 une forme lue, prononc\u00e9e et \u00e9crite dans des textes non bibliques, en somme le Qer\u00e9 grec du t\u00e9tragramme, en \u00c9gypte. <strong>Dans l&rsquo;\u00e9tat actuel de notre documentation, il est tentant de consid\u00e9rer la transcription du t\u00e9tragramme en caract\u00e8res h\u00e9breux comme origine dans la Septante<\/strong>. D\u00e9j\u00e0 R. Hanhart (&#8230;) avait \u00e9mis des r\u00e9serves sur une telle conclusion. Puis P.W. Skehan (&#8230;) montra que \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 devait \u00eatre originale chez les Proph\u00e8tes (donc au IIe s. av. J.-C.), mais non pour le Pentateuque plus ancien. Finalement A. Pietersma (&#8230;) a montr\u00e9 que \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 pouvait bien \u00eatre l&rsquo;usage primitif, non seulement le Qer\u00e9, mais le Ketib grec ; <strong>la substitution du t\u00e9tragramme en h\u00e9breu serait le r\u00e9sultat d&rsquo;une r\u00e9vision sur l&rsquo;h\u00e9breu<\/strong>.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Cet extrait du <em>SDB<\/em> XII, col. 661-662 r\u00e9sume bien les enjeux. J&rsquo;ai montr\u00e9 <a href=\"http:\/\/areopage.net\/blog\/2014\/06\/29\/%ce%b9%cc%93%ce%b1%cf%89-%ce%b8%ce%b5%ce%bf%cf%82-%ce%ba%cf%85%cf%81%ce%b9%ce%bf%cf%82-le-nom-dans-la-lxx-originale\/\">pr\u00e9c\u00e9demment<\/a> que les arguments de Pietersma \u00e9taient pour le moins discutables. On pourrait sans doute faire de m\u00eame avec ceux de Hanhart ou Skehan. Quoi qu&rsquo;il en soit, il est difficile d&rsquo;\u00eatre cat\u00e9gorique. Ce qui est certain, c&rsquo;est que les documents en notre possession incitent \u00e0 penser qu&rsquo;il y a deux phases : la premi\u00e8re, avec le nom en h\u00e9breu ; la seconde, avec \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2. Cependant, il n&rsquo;est pas impossible que \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 soit effectivement la forme originale car <strong>1)<\/strong> les traducteurs alexandrins \u00e9taient passablement hell\u00e9nis\u00e9s, et<strong> 2)<\/strong> certaines de leurs pratiques (cf. Exode 3.14, L\u00e9vitique 24.16) autant que des <a href=\"https:\/\/www.academia.edu\/10728293\/Gods_name_readable_but_unpronounceable_why\">consid\u00e9rations historiques<\/a> attestent d&rsquo;une certaine r\u00e9serve vis-\u00e0-vis du Nom.\u00a0 Le fait que la caract\u00e9ristique principale des r\u00e9visions <em>int\u00e9ressent le nom divin<\/em> est aussi un indice permettant de localiser ce qui a pu motiver les r\u00e9viseurs (entre autres, l&rsquo;adoption g\u00e9n\u00e9ralis\u00e9e de Seigneur ?). On ne peut donc exclure l&rsquo;hypoth\u00e8se en question, m\u00eame si aucun manuscrit trouv\u00e9 \u00e0 ce jour ne la soutient.<\/p>\n<p style=\"text-align: justify;\">Car il est facile de constater, quand on se donne la peine de consulter les manuscrits de la Septante, qu&rsquo;<strong>aucun manuscrit ant\u00e9rieur au IIe s. ne comporte de <em>nomina sacra<\/em><\/strong>. La liste qui suit se veut compl\u00e8te pour les t\u00e9moins ant\u00e9rieurs \u00e0 cette date (cette liste sera prochainement finalis\u00e9e). A partir du IIe s. les <em>nomina sacra<\/em> se g\u00e9n\u00e9ralisent et il n&rsquo;est plus pertinent de lister l&rsquo;ensemble des t\u00e9moins. Jusqu&rsquo;au Ve\/VIe s. &#8211; voire IXe s. &#8211; cependant, des curiosit\u00e9s peuvent appara\u00eetre (cf. <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2296035590\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2296035590&amp;linkCode=as2&amp;tag=encyclopaed09-21\">Fontaine 2007 : 50-54<\/a>, <a href=\"https:\/\/www.academia.edu\/6763536\/_Jesus_the_New_Testament_and_the_sacred_Tetragrammaton_%CE%9F_%CE%99%CE%B7%CF%83%CE%BF%CF%8D%CF%82_%CE%B7_%CE%9A%CE%B1%CE%B9%CE%BD%CE%AE_%CE%94%CE%B9%CE%B1%CE%B8%CE%AE%CE%BA%CE%B7_%CE%BA%CE%B1%CE%B9_%CF%84%CE%BF_%CE%B9%CE%B5%CF%81%CF%8C_%CE%A4%CE%B5%CF%84%CF%81%CE%B1%CE%B3%CF%81%CE%AC%CE%BC%CE%BC%CE%B1%CF%84%CE%BF_._Intl._Biblical_Conference_Biblical_Studies_West_and_East_Trends_Challenges_and_Prospects_Dpt._of_Theology_of_the_Ukrainian_Catholic_University_Sept._19_20_2013_Lviv_Ukraine\">Vasileiadis 2013 : 52-53<\/a>).<\/p>\n<p style=\"text-align: justify;\">J&rsquo;ai marqu\u00e9 d&rsquo;un \u00ab\u00a0&#8211;\u00a0\u00bb les t\u00e9moins pour lesquels je n&rsquo;ai pas la certitude d&rsquo;une pr\u00e9sence des <em>nomina sacra <\/em>; cependant les deux cas figurent au IIe s. ou apr\u00e8s : il est donc quasi certain que le proc\u00e9d\u00e9 existait.<\/p>\n<table width=\"546\">\n<tbody>\n<tr>\n<td width=\"83\"><strong>P\u00e9riode<\/strong><\/td>\n<td width=\"133\"><strong>D\u00e9signation<\/strong><\/td>\n<td width=\"94\"><strong><em>Nomina sacra<\/em><\/strong><\/td>\n<td width=\"236\"><strong>Commentaire<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-II\/-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxxmprssm.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">8\u1e24evXIIgr<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">t\u00e9tragramme en pal\u00e9o-h\u00e9breu<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-II\/-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxx7qex.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">7Q1<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-II\/-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxx7qepjer.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">7Q2<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxx4qlevb.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">4Q120<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">\u0399\u0391\u03a9<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxxjewpap\/PFou942.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Fouad 266a<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">\u03b8\u03b5\u03bf\u03c2 en entier<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxxpfou847.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Fouad 266c<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">\u03b8\u03b5\u03bf\u03c2 en entier<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/dss.collections.imj.org.il\/habakkuk\">1QpHab<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">t\u00e9tragramme en pal\u00e9o-h\u00e9breu\u00a0; commentaire d\u2019Habaquq<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/4Q127.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">4Q127<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">Paraphrase d\u2019Exode\u00a0?<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/4Q126.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">4Q126<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">Apparamment, \u039a\u03a5\u03a1\u0399\u039f(\u03a3) en entier<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-\u0399\/\u0399<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxx4qleva.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">4Q119<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I\/I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxx4qnum.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">4Q121<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">-I\/I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxxpfou848.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Fouad 266b<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">t\u00e9tragramme par une seconde main<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">I<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/POxy3522.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Oxy. L 3522<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">t\u00e9tragramme en pal\u00e9o-h\u00e9breu<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">I\/II<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/POxy4443x.JPG\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Oxy. LXV 4443<\/a><\/td>\n<td width=\"94\">Non<\/td>\n<td width=\"236\">\u03b8\u03b5\u03bf\u03c2, \u03c3\u03c9\u03c4\u03b7\u03c1\u03b9\u03b1\u03bd, \u03b1\u03bd\u03b8\u03c1\u03c9\u03c0\u03bf\u03c2 en entier<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/POxy0656.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Oxy. IV 656<\/a><\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\">Espace combl\u00e9 par \u039a\u03a5, par une seconde main, dans un espace pr\u00e9vu pour 4 lettres. D\u2019autres noms sacr\u00e9s ne sont pas abr\u00e9g\u00e9s\u00a0: \u03b8\u03b5\u03bf\u03c2, \u03c0\u03b1\u03c4\u03c1\u03bf\u03c2, et peut-\u00eatre \u03ba\u03c5\u03c1\u03b9\u03b5<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II<\/td>\n<td width=\"133\">P. Chest. Beatty V<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II<\/td>\n<td width=\"133\">P. Ant. 1.7<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II<\/td>\n<td width=\"133\">P. Baden 4.56<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rs\/rak\/lxxjewpap\/PBodl5.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Bodl. 5<\/a><\/td>\n<td width=\"94\">&#8211;<\/td>\n<td width=\"236\">\u03b8\u03b5\u03bf\u03c2, \u03b1\u03bd\u03b8\u03c1\u03c9\u03c0\u03bf\u03c2 en entier<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II\/III<\/td>\n<td width=\"133\">PSI 8.921v<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II\/III<\/td>\n<td width=\"133\"><a href=\"http:\/\/www.schoyencollection.com\/bible-collection-foreword\/greek-new-testament-septuagint\/greek-bible-joshua-ms-2648\">Sch\u00f8yen 2648<\/a><\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II\/III<\/td>\n<td width=\"133\"><a href=\"http:\/\/www.schoyencollection.com\/bible-collection-foreword\/greek-new-testament-septuagint\/greek-bible-leviticus-ms-2649\">Sch\u00f8yen 2649<\/a><\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II\/III<\/td>\n<td width=\"133\">P. Chest. Beatty VI<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II\/III<\/td>\n<td width=\"133\">P. Deissmann<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">II\/III<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/PYale1r.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Yale 1<\/a><\/td>\n<td width=\"94\">&#8211;<\/td>\n<td width=\"236\">le chiffre 318 est abr\u00e9g\u00e9 TIH contrairement \u00e0 l\u2019usage juif\u00a0; codex vraisemblablement chr\u00e9tien qui contenait des <em>nomina sacra<\/em><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">III<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/POxy1007b.JPG\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Oxy. L 1007<\/a><\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\">double yod pour le t\u00e9tragramme\u00a0; \u03b8\u03c2 abr\u00e9g\u00e9, mais non \u03b1\u03bd\u03b8\u03c1\u03c9\u03c0\u03bf\u03c2<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">III<\/td>\n<td width=\"133\"><a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/lxxjewpap\/POxy1075.jpg\" data-rel=\"lightbox-gallery-4cxTwEA8\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\">P. Oxy. VIII 1075<\/a><\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\">Espace de 3 \u00e0 4 lettres combl\u00e9 par \u039a\u03a5, par une seconde main<\/td>\n<\/tr>\n<tr>\n<td width=\"83\">III<\/td>\n<td width=\"133\">P. Berlin inv. 17212<\/td>\n<td width=\"94\">Oui<\/td>\n<td width=\"236\"><\/td>\n<\/tr>\n<tr>\n<td width=\"83\">III<\/td>\n<td width=\"133\">P. Berlin inv. 17213<\/td>\n<td width=\"94\">&#8211;<\/td>\n<td width=\"236\">Un espace plus large est pr\u00e9vu pour le nom divin (ou \u039a\u03a5\u03a1\u0399\u039f\u03a3 \u00e9crit enti\u00e8rement\u00a0?), mais est rest\u00e9 vide<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/areopage.net\/blog\/wp-content\/uploads\/2015\/06\/Liste-des-t\u00e9moins-de-la-Septante.pdf\">Tableau en PDF<\/a>. Comme on le voit, aucun des t\u00e9moins ant\u00e9rieurs au IIe si\u00e8cle ne comportent de <em>nomina sacra<\/em>. C&rsquo;est un indice fort pour <strong>leur invention chr\u00e9tienne, au cours du Ier s.<\/strong>. Leur analyse d\u00e9passe le cadre de ce post. Reportez-vous \u00e0 <a href=\"http:\/\/areopage.net\/PDF\/P52%20%28P.%20Rylands.Gr.457%29_NominaSacra_Fontaine.pdf\">Fontaine 2012<\/a> (et bibliographie). Une excellente pr\u00e9sentation des manuscrits (datation, format, \u00e9criture, particularit\u00e9s touchant notamment le t\u00e9tragramme) se trouve dans R.A. Kraft, \u00ab\u00a0The &lsquo;Textual Mechanics&rsquo; of Early Jewish LXX\/OG papyri and fragments\u00a0\u00bb, in <a href=\"http:\/\/www.amazon.fr\/gp\/product\/1584560827\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=1584560827&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=LQODNOMLRWA6NKZM\">McKendrick et O&rsquo;Sullivan \u00e9d., <em>The Bible As Book &#8211; The Transmission of the Greek Text<\/em> (Oak Knoll Press, 2003), pp.51-72<\/a>. Voir en ligne la page de <a href=\"http:\/\/ccat.sas.upenn.edu\/rak\/jewishpap.html\"><strong>Robert Kraft, Files and Information on Early Jewish and Early Christian Copies of Greek Jewish Scriptures<\/strong><\/a>. Voir aussi <a href=\"http:\/\/areopage.net\/blog\/2013\/08\/05\/paap-nomina-sacra-in-the-greek-papyri-of-the-first-five-centuries-a-d\/\">Paap, <em>Nomina Sacra in the Greek Papyri of the first five centuries<\/em> (Brill, 1959) : 6-7<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Pour faire suite \u00e0 une question qui m&rsquo;a \u00e9t\u00e9 pos\u00e9e r\u00e9cemment, j&rsquo;apporte ici quelques pr\u00e9cisions. Au vrai, la r\u00e9ponse se trouve d\u00e9j\u00e0 indiqu\u00e9e dans un tableau de mon post \u0399\u0313\u03b1\u03c9\u0301, \u03b8\u03b5\u03bf\u0301\u03c2, \u03ba\u03c5\u0301\u03c1\u03b9\u03bf\u03c2 ? Le Nom dans la LXX \u00ab originale \u00bb\u2026, ou encore dans mes ouvrages sur le nom divin dans le NT (2007 : [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10,356,294],"tags":[57,60,61,708,80,707,706,672],"class_list":["post-3405","post","type-post","status-publish","format-standard","hentry","category-paleographie","category-papyrologie","category-reflexions","tag-manuscrits","tag-nom-divin","tag-nomina-sacra","tag-papyrologie","tag-septante","tag-707","tag-706","tag-672"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-SV","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5777,"url":"https:\/\/areopage.net\/blog\/2017\/01\/29\/%ce%b9%ce%b1%cf%89-dans-le-4qpaplxxlevb-vasileiadis-2017\/","url_meta":{"origin":3405,"position":0},"title":"\u0399\u03b1\u03c9 dans le 4QpapLXXLevb (Vasileiadis, 2017)","author":"areopage","date":"29\/01\/2017","format":false,"excerpt":"Dans un article \u00e0 para\u00eetre dans la revue Vetus Testamentum et Hellas 4 (2017), \"The god Iao and his connection with the Biblical God with special emphasis on the manuscript 4QpapLXXLevb\", Pavlos D. Vasileiadis r\u00e9examine la th\u00e8se selon laquelle le\u00a0manuscrit 4Q120, ou 4QpapLXXLevb, r\u00e9sulterait d'une\u00a0tendance \u00e0 r\u00e9-h\u00e9bra\u00efser le texte de\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"https:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2017\/01\/2901172.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":32,"url":"https:\/\/areopage.net\/blog\/2013\/07\/03\/le-nom-divin-dans-les-premieres-copies-de-la-septante\/","url_meta":{"origin":3405,"position":1},"title":"Le nom divin dans les premi\u00e8res copies de la Septante","author":"areopage","date":"03\/07\/2013","format":false,"excerpt":"Ce sujet demeure plus que jamais d'actualit\u00e9, et suscite toujours des r\u00e9actions assez passionn\u00e9es. Pour certains, comme Hurtado ou R\u00f6sel, la pratique orale de substituer le t\u00e9tragramme par \u05d0\u05d3\u05e0\u05d9 (Adonay) a d\u00fb se refl\u00e9ter dans les premi\u00e8res copies de la Septante o\u00f9, suppose-t-on, \u03ba\u03cd\u03c1\u03b9\u03bf\u03c2 (Kyrios) a d\u00fb remplacer le nom\u2026","rel":"","context":"Dans &quot;pal\u00e9ographie&quot;","block_context":{"text":"pal\u00e9ographie","link":"https:\/\/areopage.net\/blog\/category\/paleographie\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4465,"url":"https:\/\/areopage.net\/blog\/2015\/12\/14\/review-de-f-shaw-the-earliest-non-mystical-jewish-use-of-%ce%b9%ce%b1%cf%89-2014\/","url_meta":{"origin":3405,"position":2},"title":"Review de F. Shaw, The Earliest Non-Mystical Jewish Use of \u0399\u03b1\u03c9 (2014)","author":"areopage","date":"14\/12\/2015","format":false,"excerpt":"L'ouvrage de Frank Shaw, The Earliest Non-Mystical Jewish Use of \u0399\u03b1\u03c9 (Peeters, 2014), est une monographie fondamentale sur l'histoire du nom divin, sp\u00e9cialement dans la Septante. Je livre sur Academia une review d\u00e9taill\u00e9e. Review de F. Shaw, The Earliest Non-Mystical Jewish Use of \u0399\u03b1\u03c9 (2014) Il s'agit d'une th\u00e8se de\u2026","rel":"","context":"Dans &quot;grec biblique&quot;","block_context":{"text":"grec biblique","link":"https:\/\/areopage.net\/blog\/category\/grec-biblique\/"},"img":{"alt_text":"1412151","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/12\/1412151-191x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5832,"url":"https:\/\/areopage.net\/blog\/2017\/02\/06\/formation-and-significance-of-the-biblical-christian-canon-bokedal2015\/","url_meta":{"origin":3405,"position":3},"title":"Formation and Significance of the Biblical Christian Canon (Bokedal,2015)","author":"areopage","date":"06\/02\/2017","format":false,"excerpt":"J'avais achet\u00e9 cet ouvrage de Tomas Bokedal simplement pour son chapitre 3 sur les nomina sacra, \"The nomina sacra : Hightlighting the Sacred Figures of the Text\" et sachez que cette partie de l'\u00e9tude est d\u00e9sormais g\u00e9n\u00e9reusement mis en ligne par son auteur. Mais au-del\u00e0 du chapitre, tout l'ouvrage est\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"https:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2017\/02\/0602171-198x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1980,"url":"https:\/\/areopage.net\/blog\/2014\/06\/20\/wessely-les-plus-anciens-monuments-du-christianisme-ecrits-sur-papyrus-19061924\/","url_meta":{"origin":3405,"position":4},"title":"Wessely \u2013 Les plus anciens monuments du christianisme \u00e9crits sur papyrus (1906,1924)","author":"areopage","date":"20\/06\/2014","format":false,"excerpt":"[scribd id=230553889 key=key-0rQQXLNV9v1ljwfB49vZ mode=book] Les deux volumes de Charles Wessely, tir\u00e9s de la Patrologia\u00a0Orientalis, pr\u00e9sentaient \u00e0 leur \u00e9poque (1906 et 1924) les plus anciens t\u00e9moignages papyrologiques int\u00e9ressant le christianisme ancien. On y trouve un grande vari\u00e9t\u00e9s\u00a0de documents : lettres chr\u00e9tiennes, fragments d'\u00e9vangiles canoniques, logia du Christ, adjurations\u00a0magiques... C'est extr\u00eamement int\u00e9ressant.\u2026","rel":"","context":"Dans &quot;grec biblique&quot;","block_context":{"text":"grec biblique","link":"https:\/\/areopage.net\/blog\/category\/grec-biblique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":118,"url":"https:\/\/areopage.net\/blog\/2013\/07\/24\/la-septante-%ce%ba%cf%8d%cf%81%ce%b9%ce%bf%cf%82-et-%d7%99%d7%94%d7%95%d7%94-l-hurtado-ou-la-re-hebraisation-du-monde-greco-romain\/","url_meta":{"origin":3405,"position":5},"title":"La Septante, \u03ba\u03cd\u03c1\u03b9\u03bf\u03c2 et \u05d9\u05d4\u05d5\u05d4 : L.Hurtado ou la r\u00e9-h\u00e9braisation du monde gr\u00e9co-romain","author":"areopage","date":"24\/07\/2013","format":false,"excerpt":"Le dernier post de L.Hurtado sur le nom divin et la Septante a suscit\u00e9 des r\u00e9actions assez \u00e9nergiques, et cela se comprend : Hurtado sur ce sujet semble vouloir ne pas s'embarasser des faits, et consid\u00e8re toute critique \u00e0 son \u00e9gard comme une insulte \u00e0 l'intelligence. On constate dans ses\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"https:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=3405"}],"version-history":[{"count":28,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3405\/revisions"}],"predecessor-version":[{"id":3576,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3405\/revisions\/3576"}],"wp:attachment":[{"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=3405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=3405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=3405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}