{"id":3976,"date":"2015-09-26T13:09:28","date_gmt":"2015-09-26T12:09:28","guid":{"rendered":"http:\/\/areopage.net\/blog\/?p=3976"},"modified":"2015-09-26T13:11:12","modified_gmt":"2015-09-26T12:11:12","slug":"theologie-du-judeo-christianisme-danielou-1974","status":"publish","type":"post","link":"http:\/\/areopage.net\/blog\/2015\/09\/26\/theologie-du-judeo-christianisme-danielou-1974\/","title":{"rendered":"Th\u00e9ologie du Jud\u00e9o-christianisme (Dani\u00e9lou, 1974)"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.amazon.fr\/gp\/product\/2718904836\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2718904836&amp;linkCode=as2&amp;tag=encyclopaed09-21\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3977 alignnone\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/09\/260915.png?resize=200%2C300\" alt=\"260915\" width=\"200\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/09\/260915.png?resize=200%2C300 200w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/09\/260915.png?w=234 234w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ce volume de <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2718904836\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2718904836&amp;linkCode=as2&amp;tag=encyclopaed09-21\">J. Dani\u00e9lou, <em>Th\u00e9ologie du Jud\u00e9o-christianisme<\/em><\/a> (Descl\u00e9e\/Cerf, 1974) est une \u00e9tude fondamentale pour qui veut comprendre le christianisme primitif. Disciple en livre un compte-rendu de lecture auquel je vous renvoie:<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/areopage.net\/blog\/wp-content\/uploads\/2015\/09\/Danielou_TJC_CompteRendu_Disciple.pdf\">D<\/a><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/06\/pdf.png\" data-rel=\"lightbox-gallery-lSi2sTcX\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1817\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/06\/pdf.png?resize=30%2C36\" alt=\"pdf\" width=\"30\" height=\"36\" \/><\/a><a href=\"http:\/\/areopage.net\/blog\/wp-content\/uploads\/2015\/09\/Danielou_TJC_CompteRendu_Disciple.pdf\">anielou_Th\u00e9ologie du Jud\u00e9o-christianisme (Cerf, 1974) &#8211; Compte-rendu de lecture, par Disciple<\/a><\/p>\n<p style=\"text-align: justify;\">Pour rappel, ce livre comporte 14 chapitres r\u00e9partis en 4 parties (Les sources \/ Le milieu intellectuel \/ Les doctrines \/ Les institutions) : 1. L&rsquo;h\u00e9ritage litt\u00e9raire du jud\u00e9o-christianisme, 2. Le jud\u00e9o-christianisme h\u00e9t\u00e9rodoxe, 3. L&rsquo;ex\u00e9g\u00e8se jud\u00e9o-chr\u00e9tienne, 4. L&rsquo;apocalyptique jud\u00e9o-chr\u00e9tienne, 5. Trinit\u00e9 et ang\u00e9lologie, 6. Les titres du Fils de Dieu, 7. L&rsquo;Incarnation, 8. La th\u00e9ologie de la r\u00e9demption, 9. Mysterium crucis, 10. L\u2019\u00c9glise, 11., Le mill\u00e9narisme, 12. Bapt\u00eame et eucharistie, 13. La communaut\u00e9 chr\u00e9tienne, et 14. La saintet\u00e9 personnelle.<\/p>\n<p style=\"text-align: justify;\">La critique de Disciple est s\u00e9v\u00e8re. En gardant \u00e0 l&rsquo;esprit la bonne qualit\u00e9 d&rsquo;ensemble de cette monographie, il convient d&rsquo;entendre les diff\u00e9rents probl\u00e8mes qu&rsquo;elle soul\u00e8ve.<\/p>\n<p style=\"text-align: justify;\">Sur la <strong>terminologie<\/strong>, faut-il encore parler de <em>jud\u00e9o-christianisme<\/em> ? Pas vraiment. Comme l&rsquo;indique Disciple, cette expression laisse \u00e0 croire que le mouvement des jud\u00e9o-chr\u00e9tiens aurait \u00e9t\u00e9 \u00ab\u00a0bancal\u00a0\u00bb &#8211; une sorte de communaut\u00e9 aux pratiques et doctrines non d\u00e9finies ou \u00e0 l&rsquo;\u00e9tat d&rsquo;\u00e9bauche, quand on sait que ce ne fut manifestement pas le cas. De plus <em>jud\u00e9o<\/em>-christianisme est une expression qui a \u00e9t\u00e9 forg\u00e9e par opposition \u00e0 <em>pagano<\/em>-christianisme. Or la situation au Ier s. n&rsquo;a pas \u00e9t\u00e9 binaire, comme on a tant\u00f4t pu le croire.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">La recherche actuelle reconna\u00eet qu&rsquo;il n&rsquo;est plus possible de parler de \u00ab\u00a0jud\u00e9o-christianisme\u00a0\u00bb, un concept moderne forg\u00e9 au XIXe si\u00e8cle par des th\u00e9ologiens chr\u00e9tiens, car il n\u00e9cessite un concept oppos\u00e9, celui de \u00ab\u00a0pagano-christianisme\u00a0\u00bb. Les composantes du mouvement chr\u00e9tien aux Ier-IIe si\u00e8cles ne se limitant pas \u00e0 deux, il para\u00eet pr\u00e9f\u00e9rable d&#8217;employer une autre terminologie moins marqu\u00e9e d&rsquo;un point de vue id\u00e9ologique : en faisant r\u00e9f\u00e9rence \u00e0 l\u2019ethnicit\u00e9 d&rsquo;origine des croyants en J\u00e9sus de Nazareth, comme par exemple l&rsquo;expression \u00ab\u00a0<strong>juda\u00efsme chr\u00e9tien<\/strong>\u00ab\u00a0. (&#8230;) Le mouvement des chr\u00e9tiens et celui des rabbins paraissent avoir construit leur conscience identitaire l&rsquo;un par rapport \u00e0 l&rsquo;autre. Ce ph\u00e9nom\u00e8ne de mim\u00e9tisme est notamment apparent dans leurs d\u00e9finitions r\u00e9ciproques du canon biblique. &#8211; <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2130563961\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2130563961&amp;linkCode=as2&amp;tag=encyclopaed09-21\">S.-Cl. Mimouni, <em>Le juda\u00efsme ancien, du VIe s. avant notre \u00e8re au IIIe s. de notre \u00e8re &#8211; Des pr\u00eatres aux rabbins<\/em>, PUF, 2012<\/a>, p.495<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><em>Juda\u00efsme chr\u00e9tien<\/em> me convient bien dans la mesure o\u00f9 c&rsquo;est reconna\u00eetre qu&rsquo;au fond le christianisme n&rsquo;est pas une nouveaut\u00e9 au sein du juda\u00efsme : c&rsquo;en est un prolongement, une modalit\u00e9. L\u00e0-dessus je renvoie \u00e0 l&rsquo;\u00e9tude, toujours utile, de <a href=\"http:\/\/www.amazon.fr\/gp\/product\/270180003X\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=270180003X&amp;linkCode=as2&amp;tag=encyclopaed09-21\">Marcel Simon, <em>Verus Isra\u00ebl<\/em> &#8211; <em>\u00c9tude sur les relations entre chr\u00e9tiens et Juifs dans l&rsquo;Empire romain<\/em>, 135-425<\/a> (\u00e9d. E. de Brocard, 1964), et aussi \u00e0 celle classique de <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0881250546\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0881250546&amp;linkCode=as2&amp;tag=encyclopaed09-21\">L. H. Schiffman, <em>Who was a Jew ? &#8211; Rabbinic and Halakhic Perspectives on the Jewish-Christian Schism<\/em><\/a> (Ktav Publishing House, 1985 ; \u00e9tude sur laquelle je reviendrai si le temps me le permet).<\/p>\n<p style=\"text-align: justify;\">Dani\u00e9lou est bien conscient de la diversit\u00e9 des situations lorsqu&rsquo;il expose la d\u00e9finition du jud\u00e9o-christianisme qu&rsquo;il retient dans son travail (pp.35-38). Disciple estime qu&#8217;employer cette expression \u00ab\u00a0jud\u00e9o-christianisme\u00a0\u00bb \u00ab\u00a0sert \u00e0 minorer l&rsquo;importance de la th\u00e9ologie primitive\u00a0\u00bb et t\u00e9moigne d&rsquo;un conception qui pr\u00f4ne \u00ab\u00a0un caract\u00e8re hybride, bancal, assis entre deux chaises, brouillon, ind\u00e9cis, composite, bricol\u00e9.\u00a0\u00bb C&rsquo;est en effet ce que le <em>vocable<\/em> sugg\u00e8re au premier abord. Mais la d\u00e9finition de Dani\u00e9lou ne va pas dans ce sens : parmi les trois d\u00e9finitions qu&rsquo;il d\u00e9crit, la troisi\u00e8me qu&rsquo;il adopte implique <em>une communaut\u00e9 de disciples de J\u00e9sus ayant rompu totalement avec le juda\u00efsme, mais continuant de penser \u00ab\u00a0dans ses cat\u00e9gories\u00a0\u00bb<\/em> (p.37). C&rsquo;est une d\u00e9finition assez fonctionnelle. Je n&rsquo;y vois rien de bancal ni d&rsquo;inachev\u00e9. Que des chr\u00e9tiens aient pu continuer \u00e0 penser dans des cat\u00e9gories juives est m\u00eame rassurant : apr\u00e8s tout, le christianisme n&rsquo;est qu&rsquo;une<em> certaine perspective<\/em> du juda\u00efsme, celle pr\u00e9cis\u00e9ment qui accepte J\u00e9sus dans le sous-ensemble du <em>messianisme<\/em>. Peut-\u00eatre Dani\u00e9lou est-il optimiste quand il soutient que \u00ab\u00a0Ce jud\u00e9o-christianisme a \u00e9t\u00e9 \u00e9videmment celui des chr\u00e9tiens venus du juda\u00efsme, <em>mais aussi de pa\u00efens convertis<\/em>\u00a0\u00bb (<em>ibidem<\/em>, je souligne). En effet, les pa\u00efens n&rsquo;ont gu\u00e8re pens\u00e9 dans des cat\u00e9gories juives ; cependant un Justin, malgr\u00e9 des approximations, prouve que ces \u00ab\u00a0cat\u00e9gories\u00a0\u00bb n&rsquo;\u00e9taient pas totalement inconnues des pa\u00efens convertis, du moins chez les lettr\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Concernant ces d\u00e9finitions, Mimouni y est revenu dans un article au nom \u00e9vocateur, <a href=\"https:\/\/www.academia.edu\/15765527\/_Pour_une_d%C3%A9finition_nouvelle_du_jud%C3%A9o-christianisme_ancien_dans_New_Testament_Studies_Cambridge_38_1992_p._161-186\">\u00ab\u00a0Pour une d\u00e9finition nouvelle du jud\u00e9o-christianisme ancien\u00a0\u00bb (NTS 1992, 38\/2, pp.161-186)<\/a>. Il souligne avec int\u00e9r\u00eat que les d\u00e9finitions propos\u00e9es sont \u00ab\u00a0trop larges\u00a0\u00bb, et que d&rsquo;ailleurs Dani\u00e9lou a \u00e9t\u00e9 forc\u00e9 de pr\u00e9ciser son propos par la suite, en fondant l\u2019identit\u00e9 jud\u00e9o-chr\u00e9tienne sur le crit\u00e8re de<em> l&rsquo;observance ou de la non-observance de la Loi mosa\u00efque<\/em> (cf. p.166) &#8211; ce qui l\u00e0-encore est loin d&rsquo;\u00eatre stupide, puisqu&rsquo;\u00e0 vrai dire le plus difficile \u00e0 comprendre ou \u00e0 admettre dans le \u00ab\u00a0christianisme primitif\u00a0\u00bb, c&rsquo;est <em>cet attachement paradoxal \u00e0 la pratique de la Torah<\/em>, observ\u00e9 chez de multiples communaut\u00e9s (situation de fait qui, \u00e0 elle seule, suffit \u00e0 justifier l&rsquo;existence du vocable \u00ab\u00a0jud\u00e9o-chr\u00e9tien\u00a0\u00bb). Au terme de la revue des pr\u00e9c\u00e9dentes d\u00e9finitions, et la consultation des t\u00e9moignages antiques, il en fournit une nouvelle (p.184) :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Le jud\u00e9o-christianisme ancien est une formulation r\u00e9cente d\u00e9signant des juifs qui ont reconnu la messianit\u00e9 de J\u00e9sus, qui ont reconnu ou qui n&rsquo;ont pas reconnu la divinit\u00e9 du Christ, mais qui tous continuent \u00e0 observer la Torah.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Y a-t-il truisme \u00e0 qualifier une doctrine des I\/IIe s. de \u00ab\u00a0jud\u00e9o-chr\u00e9tienne\u00a0\u00bb ? L\u00e0 encore, pas si simple. Pour preuve, on peut se reporter aux d\u00e9bats qui entourent la d\u00e9finition de la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Heresy_in_Judaism\"><em>minout<\/em><\/a> et des <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Minim\">minim<\/a> (cf. <a href=\"https:\/\/www.academia.edu\/15765527\/_Pour_une_d%C3%A9finition_nouvelle_du_jud%C3%A9o-christianisme_ancien_dans_New_Testament_Studies_Cambridge_38_1992_p._161-186\">Mimouni 1992 : 185<\/a>).<\/p>\n<p style=\"text-align: justify;\">Sur le probl\u00e8me de <strong>l&rsquo;orthodoxie et de l&rsquo;h\u00e9t\u00e9rodoxie<\/strong> \u00e0 cette \u00e9poque &#8211; vaste question &#8211; l&rsquo;\u00e9tude la plus embl\u00e9matique et la plus provocante est celle de <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0962364274\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0962364274&amp;linkCode=as2&amp;tag=encyclopaed09-21\">W. Bauer, <em>Orthodoxy and Heresy in Earliest Christianity<\/em><\/a> (Sigler Pr, 2e \u00e9d., 1996). Les vainqueurs \u00e9crivent-ils l&rsquo;histoire ? L&rsquo;orthodoxie est-elle seulement la doctrine de l&rsquo;un de ces mouvements, parmi tant d&rsquo;autres, qui a r\u00e9ussi \u00e0 marginaliser les autres ? C&rsquo;est \u00e0 peu de chose pr\u00e8s la th\u00e8se de Bauer, qui n&rsquo;est certes pas accept\u00e9e de tous, mais qui a eu bonne fortune. Quand on jette un \u0153il sur l&rsquo;histoire du jud\u00e9o-christianisme, ou du moins celle du juda\u00efsme chr\u00e9tien, la th\u00e8se est assez satisfaisante.<\/p>\n<p style=\"text-align: justify;\">Faut-il alors introduire la <strong>canonicit\u00e9<\/strong> comme crit\u00e8re\u00a0 d&rsquo;identification ? Quelle communaut\u00e9 accepte quel corpus, et qu&rsquo;en d\u00e9duit-on ?<\/p>\n<p style=\"text-align: justify;\">Dans l&rsquo;extrait de Mimouni ci-dessous, un point est important : clairement, les identit\u00e9s chr\u00e9tiennes et rabbiniques se sont forg\u00e9es <strong><em>l&rsquo;une par rapport \u00e0 l&rsquo;autre<\/em><\/strong>. L&rsquo;orthodoxie ne na\u00eet que parce qu&rsquo;elle affronte des courants qu&rsquo;elle estime <em>d\u00e9viants<\/em>. Ainsi na\u00eet l&rsquo;<em>h\u00e9r\u00e9sie<\/em>. Ainsi na\u00eet aussi, <em>a posteriori<\/em>, le dogme. Ce n&rsquo;est sans doute pas valable dans tous les domaines, mais force est de constater que le canon pr\u00e9cis\u00e9ment s&rsquo;est forg\u00e9 par opposition au marcionisme d&rsquo;une part, au gnosticisme d&rsquo;autre part, mais aussi, apr\u00e8s la destruction du Temple, alors que le texte massor\u00e9tique est d\u00e9finitivement standardis\u00e9 et que le \u00ab\u00a0canon massor\u00e9tique\u00a0\u00bb est cl\u00f4tur\u00e9 (<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Canon_%28Bible%29#Hypoth.C3.A8se_du_canon_de_Jamnia\">hypoth\u00e8se de Jamnia<\/a>). Aux rabbins qui cl\u00f4turaient leur canon et fixaient leur texte, les chr\u00e9tiens ont oppos\u00e9, <strong><em>par mim\u00e9tisme<\/em><\/strong>, un canon normatif et, \u00e0 d\u00e9faut d&rsquo;un texte tout \u00e0 fait stabilis\u00e9, une pratique \u00e9ditoriale et scribale clairement d\u00e9finie. Je me suis rendu compte de ce ph\u00e9nom\u00e8ne avec une certaine acuit\u00e9 lorsque j&rsquo;ai \u00e9tudi\u00e9 les <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nomina_sacra\">nomina sacra.<\/a><\/em> Pour plus de d\u00e9tails, reportez-vous \u00e0 mon <em><a href=\"http:\/\/areopage.net\/PDF\/P52%20%28P.%20Rylands.Gr.457%29_NominaSacra_Fontaine.pdf\">Le P52 contenait-il un nomen sacrum pour J\u00e9sus ?<\/a><\/em><\/p>\n<p style=\"text-align: justify;\">Concernant la <strong>doctrine trinitaire<\/strong>, \u00e9videmment Dani\u00e9lou importe dans le texte des concepts nic\u00e9ens intol\u00e9rables. C&rsquo;est la th\u00e9orie de l&rsquo;\u00e9volution appliqu\u00e9e aux sciences humaines : le dogme a \u00e9t\u00e9 fix\u00e9 au IVe s., par les tenants d&rsquo;une \u00c9glise h\u00e9rit\u00e9e des ap\u00f4tres. Les pr\u00e9mices sont donc \u00e0 chercher, et \u00e0 trouver, en amont. Et quand on cherche, on trouve. Et si on ne trouve pas, on imagine et on suppose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce volume de J. Dani\u00e9lou, Th\u00e9ologie du Jud\u00e9o-christianisme (Descl\u00e9e\/Cerf, 1974) est une \u00e9tude fondamentale pour qui veut comprendre le christianisme primitif. Disciple en livre un compte-rendu de lecture auquel je vous renvoie: Danielou_Th\u00e9ologie du Jud\u00e9o-christianisme (Cerf, 1974) &#8211; Compte-rendu de lecture, par Disciple Pour rappel, ce livre comporte 14 chapitres r\u00e9partis en 4 parties (Les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,294],"tags":[751,750,752,753],"class_list":["post-3976","post","type-post","status-publish","format-standard","hentry","category-lectures","category-reflexions","tag-danielou","tag-judeo-christianisme","tag-mimouni","tag-orthodoxieheterodoxie"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-128","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1980,"url":"http:\/\/areopage.net\/blog\/2014\/06\/20\/wessely-les-plus-anciens-monuments-du-christianisme-ecrits-sur-papyrus-19061924\/","url_meta":{"origin":3976,"position":0},"title":"Wessely \u2013 Les plus anciens monuments du christianisme \u00e9crits sur papyrus (1906,1924)","author":"areopage","date":"20\/06\/2014","format":false,"excerpt":"[scribd id=230553889 key=key-0rQQXLNV9v1ljwfB49vZ mode=book] Les deux volumes de Charles Wessely, tir\u00e9s de la Patrologia\u00a0Orientalis, pr\u00e9sentaient \u00e0 leur \u00e9poque (1906 et 1924) les plus anciens t\u00e9moignages papyrologiques int\u00e9ressant le christianisme ancien. On y trouve un grande vari\u00e9t\u00e9s\u00a0de documents : lettres chr\u00e9tiennes, fragments d'\u00e9vangiles canoniques, logia du Christ, adjurations\u00a0magiques... C'est extr\u00eamement int\u00e9ressant.\u2026","rel":"","context":"Dans &quot;grec biblique&quot;","block_context":{"text":"grec biblique","link":"http:\/\/areopage.net\/blog\/category\/grec-biblique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":251,"url":"http:\/\/areopage.net\/blog\/2013\/08\/01\/d-jaffe-et-matthieu-hebreu\/","url_meta":{"origin":3976,"position":1},"title":"D. Jaff\u00e9 et Matthieu h\u00e9breu","author":"areopage","date":"01\/08\/2013","format":false,"excerpt":"Dans un article qui reprend en grande partie le chapitre 4 de son ouvrage Le Talmud et les origines juives du christianisme (2007, pp.109-120), D. Jaff\u00e9 aborde la question de la langue originale de l'\u00e9vangile de Matthieu. Cet article de 2009 s'intitule \u00ab Les Sages du Talmud et l'\u00c9vangile selon\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6033,"url":"http:\/\/areopage.net\/blog\/2017\/04\/24\/nouveaux-papyri-bibliques-a-oxyrhynque\/","url_meta":{"origin":3976,"position":2},"title":"Nouveaux papyri bibliques \u00e0 Oxyrhynque","author":"areopage","date":"24\/04\/2017","format":false,"excerpt":"Les papyri d'Oxyrhynque ont livr\u00e9, au fil des ann\u00e9es, et m\u00eame des d\u00e9cennies, de nombreuses informations sur l'Egypte hell\u00e9nistique, la p\u00e9riode romaine, et les commencements du christianisme. Au rythme actuel, il faudra encore plus de\u00a0vingt ans pour percer les myst\u00e8res de cette collection, avec une s\u00e9rie d\u00e9passant les 100 volumes,\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2017\/04\/2404171-300x166.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":398,"url":"http:\/\/areopage.net\/blog\/2013\/08\/11\/theophile-dantioche-trois-livres-a-autolycus\/","url_meta":{"origin":3976,"position":3},"title":"Th\u00e9ophile d&rsquo;Antioche, Trois livres \u00e0 Autolycus","author":"areopage","date":"11\/08\/2013","format":false,"excerpt":"Les apologistes grecs du IIe si\u00e8cle comme Th\u00e9ophile d'Antioche ont beaucoup \u00e0 nous apprendre : sur leur compr\u00e9hension du christianisme, sur l'\u00e9tat du canon \u00e0 leur \u00e9poque, sur le milieu dans lequel ils \u00e9voluaient. Il \u00e9tait courant de d\u00e9fendre l'Antiquit\u00e9 du christianisme par l'appropriation de l'histoire juive ; de pourfendre\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"TAA_AA","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/08\/TAA_AA-194x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":5568,"url":"http:\/\/areopage.net\/blog\/2017\/01\/14\/legypte-ancienne-a-travers-les-papyrus-burnet-2003\/","url_meta":{"origin":3976,"position":4},"title":"L&rsquo;\u00c9gypte ancienne \u00e0 travers les papyrus (Burnet, 2003)","author":"areopage","date":"14\/01\/2017","format":false,"excerpt":"R\u00e9gis Burnet met g\u00e9n\u00e9reusement en ligne son anthologie L'\u00c9gypte ancienne \u00e0 travers les papyrus - Vie quotidienne (\u00c9ditions Flammarion, Pygmalion, 2003). Il s'agit d'un\u00a0recueil de textes tout \u00e0 fait passionnant qui invite \u00e0 d\u00e9couvrir l'\u00c9gypte par une s\u00e9lection de textes class\u00e9s par th\u00e8mes, couvrant la p\u00e9riode lagide (332-30 av. J.-C.)\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"140117","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2017\/01\/140117.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1343,"url":"http:\/\/areopage.net\/blog\/2014\/02\/01\/le-christ-juif-boyarin-2013\/","url_meta":{"origin":3976,"position":5},"title":"Le Christ juif (Boyarin, 2013)","author":"areopage","date":"01\/02\/2014","format":false,"excerpt":"Le Christ juif de Daniel Boyarin (Cerf, 2013) est la traduction fran\u00e7aise d'un ouvrage paru en 2012 sous le titre The Jewish Gospels.\u00a0The Story of the Jewish Christ.\u00a0J'ai achet\u00e9 cet ouvrage \u00e0 sa sortie il y a quelques mois, mais je ne me suis d\u00e9cid\u00e9 \u00e0 le lire que r\u00e9cemment.\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"3101141","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/01\/3101141-150x150.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=3976"}],"version-history":[{"count":18,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3976\/revisions"}],"predecessor-version":[{"id":3996,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3976\/revisions\/3996"}],"wp:attachment":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=3976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=3976"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=3976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}