{"id":3152,"date":"2015-04-19T19:12:42","date_gmt":"2015-04-19T18:12:42","guid":{"rendered":"http:\/\/areopage.net\/blog\/?p=3152"},"modified":"2015-04-20T19:00:59","modified_gmt":"2015-04-20T18:00:59","slug":"un-homme-de-lentre-deux-1-samuel-17-4","status":"publish","type":"post","link":"http:\/\/areopage.net\/blog\/2015\/04\/19\/un-homme-de-lentre-deux-1-samuel-17-4\/","title":{"rendered":"Un homme de \u00ab\u00a0l&rsquo;entre-deux\u00a0\u00bb (1 Samuel 17.4)"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904151.jpg\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3153\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904151.jpg?resize=300%2C243\" alt=\"1904151\" width=\"300\" height=\"243\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904151.jpg?resize=300%2C243 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904151.jpg?resize=900%2C730 900w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904151.jpg?w=1018 1018w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">L&rsquo;histoire de David et Goliath pose de nombreux probl\u00e8mes litt\u00e9raires, linguistiques, historiques, arch\u00e9ologiques ou textuels. On sait depuis longtemps que le texte massor\u00e9tique des livres de Samuel n&rsquo;est pas\u00a0de bonne qualit\u00e9, et qu&rsquo;en bien des endroits, il faut lui\u00a0pr\u00e9f\u00e9rer le texte de la Septante (<a href=\"http:\/\/www.jstor.org\/stable\/1518856\">A. Yadin 2004 : 375<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/B0000CHVY6\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=B0000CHVY6&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=7DAOAZCV4A5LSE35\">Roberts 1951 : 182<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0800610873\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0800610873&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=Z6MIDVKLQIJX6QXB\">Klein 1974 : 21-23<\/a>). \u00a0Au point de vue <strong>litt\u00e9raire<\/strong>, l&rsquo;\u00e9pisode de David et Goliath est pr\u00e9cis\u00e9ment un de ces passages o\u00f9 les diff\u00e9rences sont sensibles (le texte \u00e9tant 44% plus court dans la Septante, cf. <a href=\"https:\/\/books.google.fr\/books?id=5Sh7dBDD7ykC&amp;lpg=PA301&amp;ots=J3nYthx-Ld&amp;dq=lust%20story%20da%20hebrew%20greek&amp;hl=fr&amp;pg=PA301#v=onepage&amp;q&amp;f=false\">Tov 2012 : 301<\/a>\u00a0; cf. <a href=\"http:\/\/etheses.dur.ac.uk\/5911\/1\/Johnson-David_and_Goliath_PhD_Thesis-2012.pdf?DDD32+\">Johnson 2012a<\/a>), et donnent la nette impression que le texte massor\u00e9tique pr\u00e9sente une version courte \u00ab\u00a0expurg\u00e9e\u00a0\u00bb\u00a0(cf. <a href=\"https:\/\/www.academia.edu\/1515123\/Reconsidering_4QSama_and_the_Textual_Support_for_the_Long_and_Short_Versions_of_the_David_and_Goliath_Story\">Johnson 2012b<\/a>) pour des motifs th\u00e9ologiques (<a href=\"https:\/\/books.google.fr\/books?id=KsjUno1HmxgC&amp;lpg=PA200&amp;ots=YjvIqJyDLo&amp;dq=lust%20story%20da%20hebrew%20greek&amp;hl=fr&amp;pg=PA200#v=onepage&amp;q&amp;f=false\">Caquot et Robert 1994 : 200<\/a>). On peut \u00e9galement s&rsquo;enqu\u00e9rir de l&rsquo;intertextualit\u00e9 : faut-il voir des parall\u00e8les avec l&rsquo;<em>Iliade<\/em> (ex. 3.16-20, 86-94, 7.72-86, 92-93, 151, 226-243, 11.15,29) ? Ou bien, malgr\u00e9 les ressemblances superficielles, les parall\u00e8les sont-ils plut\u00f4t \u00e0 chercher du c\u00f4t\u00e9 des peuples environnants (cf. <a href=\"http:\/\/www.jstor.org\/stable\/41304213\">Frolov et Wright 2011<\/a>) ? Au point de vue <strong>historique<\/strong>, l&rsquo;<em>armure de Goliath<\/em> a suscit\u00e9 bien des interrogations : sa description est pr\u00e9cise (<strong>1 Samuel 17.4,5,7<\/strong>), puisqu&rsquo;il est question d&rsquo;un casque, d&rsquo;une cotte de mailles de 57 kg environ, d&rsquo;une lance, de jambi\u00e8res, et d&rsquo;un bouclier.\u00a0L&rsquo;illustration en exergue de ce post est donc un peu fantaisiste&#8230; Il faudrait plut\u00f4t se repr\u00e9senter la sc\u00e8ne ainsi :<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.jpg\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3159\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.jpg?resize=95%2C150\" alt=\"1904153\" width=\"95\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.jpg?resize=189%2C300 189w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.jpg?w=600 600w\" sizes=\"auto, (max-width: 95px) 100vw, 95px\" \/><\/a>\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904156.jpg\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3168\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904156.jpg?resize=300%2C150\" alt=\"1904156\" width=\"300\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904156.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904156.jpg?w=640 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.jpg\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3160\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.jpg?resize=185%2C122\" alt=\"1904155\" width=\"185\" height=\"122\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.jpg?resize=300%2C197 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.jpg?w=638 638w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/><\/a>\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.jpg\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3161\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.jpg?resize=200%2C120\" alt=\"1904154\" width=\"200\" height=\"120\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.jpg?resize=300%2C180 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.jpg?w=600 600w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Certains, comme I. Finkelstein, l&rsquo;ont trouv\u00e9e anachronique (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/2227472243\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2227472243&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=QWRBJQSZVW2G5B2K\">2006 : 186-187<\/a>\u00a0; SDB 7 : 1265); d&rsquo;autres plus nombreux y trouvent des indices probants de r\u00e9alisme (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/2755001755\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2755001755&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=5EEM7IBNSOWDJ3FX\">Richelle 2012 : 78-79<\/a>). De m\u00eame la pratique des <em>combats singuliers<\/em>\u00a0&#8211; la <a href=\"http:\/\/logeion.uchicago.edu\/index.html#\u03bc\u03bf\u03bd\u03bf\u03bc\u03b1\u03c7\u03af\u03b1\">\u03bc\u03bf\u03bd\u03bf\u03bc\u03b1\u03c7\u03b9\u0301\u03b1<\/a> &#8211; a \u00e9tonn\u00e9\u00a0:\u00a0qu&rsquo;un combat seul puisse d\u00e9terminer l&rsquo;issue d&rsquo;une bataille a paru invraisemblable, et de caract\u00e8re grec seulement (<a href=\"http:\/\/www.jstor.org\/stable\/1518856\">A. Yadin 1992 : 379<\/a>). Et pourtant la pratique semble\u00a0attest\u00e9e chez d&rsquo;autres peuples du Proche Orient (<a href=\"http:\/\/www.jstor.org\/discover\/10.2307\/42640724?uid=3738016&amp;uid=2480313103&amp;uid=2&amp;uid=3&amp;uid=60&amp;sid=21106060718471\">de Vaux 1959<\/a>,\u00a0<a href=\"http:\/\/www.amazon.fr\/gp\/product\/0232511551\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0232511551&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=N2LBFEIDN6TPHGMD\">de Vaux\u00a01971\u00a0:\u00a0122\u201335<\/a>),\u00a0de surcro\u00eet la connexion entre Grecs (ou plus pr\u00e9cis\u00e9ment les\u00a0<a href=\"http:\/\/fr.wikipedia.org\/wiki\/P%C3%A9lasges\">P\u00e9lasge<\/a>) et Philistins est \u00e9tablie (SDB 7 : 1237). Au point de vue <strong>arch\u00e9ologique<\/strong>, on pense avoir <a href=\"https:\/\/remnantofgiants.wordpress.com\/tag\/yosef-garfinkel\/\">retrouv\u00e9<\/a> <a href=\"https:\/\/remnantofgiants.wordpress.com\/2011\/05\/09\/finkelstein-vs-garfinkel\/\">le camp de la vall\u00e9e d&rsquo;Elah<\/a> mentionn\u00e9 en <strong>1 Samuel 17.1-2<\/strong> (\u00e0 <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Khirbet_Qeiyafa\">Khirbet\u00a0Qeiyafa<\/a>, cf. <a href=\"http:\/\/www.jstor.org\/discover\/10.5615\/bullamerschoorie.367.0073?uid=3738016&amp;uid=2480313103&amp;uid=2&amp;uid=3&amp;uid=60&amp;sid=21106058599461\">Leivin 2012<\/a>\u00a0; voir aussi\u00a0<a href=\"https:\/\/www.academia.edu\/457421\/Khirbet_Qeiyafa_An_Unsensational_Archaeological_and_Historical_Interpretation\">Fantalkin<\/a>, plus minimaliste).<\/p>\n<p>\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3154\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.png?resize=163%2C109\" alt=\"1904153\" width=\"163\" height=\"109\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.png?resize=300%2C201 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904153.png?w=501 501w\" sizes=\"auto, (max-width: 163px) 100vw, 163px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904152.jpg\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3155\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904152.jpg?resize=128%2C109\" alt=\"1904152\" width=\"128\" height=\"109\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904152.jpg?resize=300%2C255 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904152.jpg?w=829 829w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Et l&rsquo;on peut continuer\u00a0de d\u00e9tail en d\u00e9tail : ainsi, la mutilation de l&rsquo;ennemi (<strong>1 Samuel 17:41-46<\/strong>) est-elle aussi un \u00e9l\u00e9ment de r\u00e9alisme bien attest\u00e9 dans les sources (<a href=\"http:\/\/www.jstor.org\/stable\/27638359\">Lemos 2006 : 235<\/a>). \u00a0Au point de vue <strong>textuel<\/strong>, quelle <a href=\"http:\/\/www.biblestudymagazine.com\/extras-1\/2014\/10\/31\/clash-of-the-manuscripts-goliath-the-hebrew-text-of-the-old-testament\">taille<\/a> Goliath avait-il ? Six coud\u00e9es et un empan (<strong>1 Samuel 17.4<\/strong>, TM : \u05e9\u05c1\u05b5\u05e9\u05c1 \u05d0\u05b7\u05de\u05bc\u05d5\u05b9\u05ea \u05d5\u05b8\u05d6\u05b8\u05bd\u05e8\u05b6\u05ea) &#8211; c&rsquo;est-\u00e0-dire 3.06 m &#8211; ou 4 coud\u00e9es et un empan (LXX, \u03c4\u03b5\u03c3\u03c3\u1f71\u03c1\u03c9\u03bd \u03c0\u03ae\u03c7\u03b5\u03c9\u03bd \u03ba\u03b1\u1f76 \u03c3\u03c0\u03b9\u03b8\u03b1\u03bc\u1fc6\u03c2 ; =<strong>4Q51<\/strong>, ]\u05d0\u05af\u05e8\u05d1\u05e2[, <strong>AJ 6.171<\/strong>), soit 1.96 m (cf. <a href=\"http:\/\/www.maisonbible.net\/emm4636\/livres-historiques-encyclopedie-des-difficultes-bibliques-at-vol-2a-et-2b\">Kuen, EDB 2 : 414<\/a>, <a href=\"http:\/\/www.etsjets.org\/files\/JETS-PDFs\/48\/48-4\/JETS_48-4_701-714.pdf\">Hays 2005<\/a> et <a href=\"http:\/\/www.dougvandorn.com\/Hays%20to%20Billington%20a%20response.pdf\">2007<\/a>) ? Et qui l&rsquo;a tu\u00e9, David (<strong>1 Samuel 17.51<\/strong>) ou Elhanan (<strong>2 Samuel 21.19 \/ 1\u00a0Chroniques 20.5<\/strong>,\u00a0cf. <a href=\"http:\/\/www.maisonbible.net\/emm4636\/livres-historiques-encyclopedie-des-difficultes-bibliques-at-vol-2a-et-2b\">Kuen, EDB 2 : 416-417<\/a>,\u00a0<a href=\"http:\/\/m.wol.jw.org\/fr\/wol\/d\/r30\/lp-f\/1200001739#h=0:0-3:251\">EP 1 : 998-999<\/a>) ?<\/p>\n<p style=\"text-align: justify;\">On le voit, cet \u00e9pisode pourtant c\u00e9l\u00e8bre n&rsquo;en finit pas de faire couler de l&rsquo;encre. Ici je ne m&rsquo;int\u00e9resserai donc qu&rsquo;\u00e0 un petit d\u00e9tail <strong>linguistique<\/strong> :\u00a0la curieuse expression \u00ab\u00a0<strong>l&rsquo;homme de l&rsquo;entre-deux<\/strong>\u00a0\u00bb :\u00a0\u05d0\u05b4\u05bd\u05d9\u05e9\u05c1 \u05d4\u05b7\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd, que les traductions rendent couramment par \u00ab\u00a0champion\u00a0\u00bb. \u00a0Mais quel \u00ab\u00a0entre-deux\u00a0\u00bb, et pourquoi \u00ab\u00a0champion\u00a0\u00bb ?<\/p>\n<p style=\"text-align: justify;\">On peut d\u00e9j\u00e0 comparer les versions.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3167\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.png?resize=300%2C124\" alt=\"1904154\" width=\"300\" height=\"124\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.png?resize=300%2C124 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.png?resize=900%2C373 900w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904154.png?w=901 901w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Tandis que le Texte Massor\u00e9tique parle d&rsquo;un <strong><em>homme de l&rsquo;entre-deux<\/em><\/strong>, que certains rendent \u00ab\u00a0homme des intervalles\u00a0\u00bb (<em>vir intermedius<\/em>), la Septante porte\u00a0<strong><em>homme puissant<\/em><\/strong>, comme s&rsquo;il y avait \u05d7\u05d9\u05dc (<a href=\"https:\/\/archive.org\/stream\/leslivresdesamu00dhor#page\/146\/mode\/2up\">Dhorme 1910 : 147<\/a>), la Vulgate, <strong><em>b\u00e2tard<\/em><\/strong>, le Targum de Ps.-Jonathan, un <strong><em>homme fort<\/em> <\/strong>ou <strong><em>h\u00e9ros <\/em><\/strong>(\u05d2\u05b7\u05bc\u05d1\u05b0\u05e8\u05b8\u05d0), et la version syriaque de m\u00eame, <strong><em>homme fort, h\u00e9ros<\/em><\/strong> (\u0713\u0722\u0712\u072a\u0710 = \u05d2\u05b7\u05bc\u05d1\u05b0\u05e8\u05b8\u05d0).\u00a0Il appara\u00eet clairement que les traductions laissent \u00e0 d\u00e9sirer, et sont en fait\u00a0influenc\u00e9es par le verset 51 (\u05d2\u05bc\u05b4\u05d1\u05bc\u05d5\u05b9\u05e8\u05b8\u05dd, <em>leur homme fort<\/em>). Les rabbins n&rsquo;ont d&rsquo;ailleurs pas manqu\u00e9 de s&rsquo;interroger sur le sens de cette expression (<strong>b. Sota 8:1, IV.4.A<\/strong>). Leurs discussions tournent essentiellement autour de la signification du terme\u00a0\u05d1\u05e0\u05d9\u05dd, dont les diff\u00e9rentes vocalisations permettent, au gr\u00e9 des fantaisies, des sens plus ou moins inattendus : pour l&rsquo;un, Goliath \u00e9tait \u00ab\u00a0fa\u00e7onn\u00e9\u00a0\u00bb (<em>mebunneh<\/em>) sans honte ; pour l&rsquo;autre, il \u00e9tait celui qui \u00e9tait \u00ab\u00a0au milieu\u00a0\u00bb (<em>benoni<\/em>) de ses fr\u00e8res ; pour un autre encore, c&rsquo;\u00e9tait une vraie \u00ab\u00a0construction\u00a0\u00bb (<em>binyan<\/em>) &#8211; on pourrait dire un <em>colosse<\/em> -, pour un autre enfin, il \u00e9tait fils de cent p\u00e8res et d&rsquo;une m\u00e8re (<em>ben nane<\/em> [?])&#8230; Ils expliquent donc, peut-\u00eatre, le <em>b\u00e2tard<\/em> de la Vulgate, sans\u00a0toutefois \u00e9claircir notre \u05d0\u05b4\u05bd\u05d9\u05e9\u05c1 \u05d4\u05b7\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd&#8230;<\/p>\n<p style=\"text-align: justify;\">Comme l&rsquo;expression\u00a0\u05d0\u05b4\u05bd\u05d9\u05e9\u05c1 \u05d4\u05b7\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd ne figure qu&rsquo;en <strong>1 Samuel 17.4<\/strong> et <strong>1 Samuel 17.23<\/strong>,\u00a0il est assez\u00a0difficile d&rsquo;en d\u00e9terminer le sens. Il faut certes\u00a0en questionner la <em>vocalisation<\/em>, comme ont fait les rabbins, sans toutefois divaguer&#8230;\u00a0On notera simplement que la forme \u05d1\u05e0\u05d9\u05dd n&rsquo;est pas une forme nominale connue (ainsi <a href=\"http:\/\/www.amazon.fr\/gp\/product\/1906055793\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=1906055793&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=2LYIZAYTOMOPDQXD\">CDCH<\/a>, s.v. *\u05d1\u05e0\u05d9\u05dd), et il faut peut-\u00eatre lire \u05d1\u05d9\u05e0\u05d9\u05dd (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/1906055793\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=1906055793&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=2LYIZAYTOMOPDQXD\">CDCH : 50<\/a>) comme dans 1Q33 6.1 <em>et passim<\/em>. L&rsquo;interpr\u00e9tation la plus courante est celle de <em>l&rsquo;homme de l&rsquo;espace entre les deux lignes ennemies<\/em>, c&rsquo;est-\u00e0-dire le <em>h\u00e9ros<\/em>, le <em>champion<\/em> qui est d\u00e9sign\u00e9 pour les combats singuliers\u00a0&#8211;\u00a0l&rsquo;homme du\u00a0<a href=\"http:\/\/logeion.uchicago.edu\/index.html#\u03bc\u03b5\u03c4\u03b1\u03af\u03c7\u03bc\u03b9\u03bf\u03c2\">\u03bc\u03b5\u03c4\u03b1\u03af\u03c7\u03bc\u03b9\u03bf\u03c2<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3173\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.png?resize=300%2C155\" alt=\"1904155\" width=\"300\" height=\"155\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.png?resize=300%2C155 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.png?resize=900%2C466 900w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904155.png?w=940 940w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ainsi cette explication qu&rsquo;on lit dans le SDB 7 : 1264 (nous soulignons):<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Le sens de ce passage est clair ; le sort des deux peuples doit \u00eatre r\u00e9gl\u00e9 par un combat singulier; David s&rsquo;offre pour relever le d\u00e9fi. Son adversaire est appel\u00e9 \u05d0\u05b4\u05bd\u05d9\u05e9\u05c1 \u05d4\u05b7\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd, expression isol\u00e9e dans la Bible et que les versions n&rsquo;ont pas comprise. La solution la plus vraisemblable est de faire de\u00a0\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd un duel de\u00a0\u05d1\u05bc\u05b5\u05d9\u05df, \u00ab\u00a0l&rsquo;entre-deux\u00a0\u00bb, ce Philistin \u00e9tant \u00ab\u00a0<strong>l&rsquo;homme de l&rsquo;entre-deux<\/strong>\u00ab\u00a0, probablement <strong>celui qui livre un combat entre les deux arm\u00e9es rang\u00e9es en ligne<\/strong>, beaucoup plus que le membre d&rsquo;une troupe de choix qui s&rsquo;avance entre les deux fronts. Le terme se trouve jusqu&rsquo;\u00e0 14 fois dans la R\u00e8gle de la Guerre de Qumr\u00e2n en un sens qu&rsquo;il n&rsquo;est pas facile de d\u00e9terminer; est-ce l&rsquo;infanterie l\u00e9g\u00e8re, ou les hommes de la m\u00eal\u00e9e ? Mais la pr\u00e9sence de ce terme dans ce document prouve que son auteur a utilis\u00e9 un vocable archa\u00efque de l&rsquo;A.T. auquel il a donn\u00e9 un tout autre contenu.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">A Qumr\u00e2n pr\u00e9cis\u00e9ment,\u00a0le terme figure 27 fois avec semble-t-il et dans la grande majorit\u00e9 des cas\u00a0le\u00a0sens d&rsquo;<em>homme d&rsquo;infanterie<\/em>, sans qu&rsquo;on puisse\u00a0\u00eatre vraiment pr\u00e9cis (ex. <strong>1Q33 1.14, 3.1, 7, 6.1<\/strong>, etc.). Mais pas toujours. Dans le <strong>4Q427 f7 2.21<\/strong>\u00a0par exemple, on lit :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">[\u05d3\u05d1\u05e8\u05e0\u05d5 \u05dc\u05db\u05d4 \u05d5\u05dc\u05d5\u05af\u05d0\u05af <span style=\"color: #ff0000;\">\u05dc\u05d0\u05d9\u05e9 \u05d1\u05af\u05d9\u05af<\/span>[\u05e0\u05d9\u05dd &#8212; \u05d5\u05d4\u05d8\u05d9\u05ea\u05d4<\/p>\n<p style=\"text-align: justify;\">nous avons parl\u00e9 \u00e0 toi, et non \u00e0 <strong>un interm\u00e9diaire<\/strong><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Nous suivons ici Martinez et Tigchelaar (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/0802844936\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0802844936&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=HN43M67AUHBSA4SX\">DSS-SE 2 : 899<\/a>), qui traduisent ainsi :\u00a0<em>to you we have spoken and not to an interme[diary<\/em> \u2026\u00a0<a href=\"http:\/\/www.amazon.fr\/gp\/product\/2262020825\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2262020825&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=TDDDIHU5MQAWRDJH\">Wise, Abegg et Cook 2003 : 132<\/a>\u00a0de leur c\u00f4t\u00e9 rendent\u00a0ce passage ainsi : <em>nous Te parlons \u00e0 Toi et non \u00e0 un cham[pion (ou un interm\u00e9diaire)<\/em>. Bien qu&rsquo;ils choisissent <em>champion<\/em>\u00a0en premier lieu, s\u00fbrement par pure convention, la formulation m\u00eame (&#8230;\u05dc\u05db\u05d4 \u05d5\u05dc\u05d5\u05af\u05d0\u05af) insiste sur l&rsquo;absence d&rsquo;interm\u00e9diaire. Or le contexte est \u00e0 la louange de Dieu pour tous ses bienfaits, en dehors de tout\u00a0contexte militaire. On trouve d&rsquo;ailleurs un autre cas de ce sens atypique en <strong>1QHa 14.15b-16 <\/strong>&#8211; un\u00a0document difficile \u00e0 interpr\u00e9ter, et donc \u00e0 traduire, en raison des lacunes\u00a0:<\/p>\n<blockquote><p>\u05db\u05d9 \u05d4\u05d1\u05d9\u05d0\u05d5\u05ea\u05af\u05d4\u05af \u25cc[ &#8212; ]\u05e1\u05af\u05d5\u05d3\u05db\u05d4<\/p>\n<p>\u05dc\u05db\u05d5\u05dc \u05d0\u05e0\u05e9\u05d9 \u05e2\u05e6\u05ea\u05db\u05d4 \u05d5\u05d1\u05d2\u05d5\u05e8\u05dc \u05d9\u05d7\u05d3 \u05e2\u05dd \u05de\u05dc\u05d0\u05db\u05d9 \u05e4\u05e0\u05d9\u05dd. <span style=\"color: #ff0000;\">\u05d5\u05d0\u05d9\u05df \u05de\u05dc\u05d9\u05e5 \u05d1\u05e0\u05d9\u05dd<\/span> \u05dc\u05e7[ &#8212; \u05dc]\u05d4\u05af\u05e9\u05d9\u05d1<\/p>\n<p>car tu as fait venir\u00a0[&#8230;. et] ton\u00a0amiti\u00e9<\/p>\n<p>\u00e0 tous les hommes de ton conseil\u00a0et de l&rsquo;association de la communaut\u00e9 par le moyen des\u00a0anges-de-face : <strong><em>et il n&rsquo;y avait point d\u2019interm\u00e9diaire entre<\/em> <\/strong>tes sa[ints &#8230; pour] faire retourner<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Ici comme dans le 1QHa, il semble bien que l&rsquo;amiti\u00e9 divine (\u05e1\u05d5\u05b9\u05d3) r\u00e9pandue sur les \u00ab\u00a0privil\u00e9gi\u00e9s\u00a0\u00bb de la communaut\u00e9 de Qumr\u00e2n s&rsquo;entendait <em>sans\u00a0<\/em><i>interm\u00e9diaire,\u00a0<\/i>car les \u00ab\u00a0anges de la face\u00a0\u00bb qui y sont mentionn\u00e9s n&rsquo;\u00e9taient <em>pr\u00e9cis\u00e9ment pas<\/em> consid\u00e9r\u00e9s comme des interm\u00e9diaires (voir mon\u00a0<a href=\"http:\/\/areopage.net\/blog\/2014\/01\/22\/%D7%9E%D6%B7%D7%9C%D6%B0%D7%90%D6%B7%D7%9A%D6%B0-%D7%A4%D6%B8%D6%BC%D7%A0%D6%B8%D7%99%D7%95-lange-de-sa-face-isaie-63-9\/\">pr\u00e9c\u00e9dent post<\/a> \u00e0 ce sujet). L&#8217;emploi du terme\u00a0\u05de\u05dc\u05d9\u05e5, <em>interm\u00e9diaire, intercesseur<\/em>, <span style=\"color: #000000;\">aux c\u00f4t\u00e9s de\u00a0\u05d1\u05e0\u05d9\u05dd pourrait ainsi soutenir l&rsquo;\u00e9quation\u00a0\u05de\u05dc\u05d9\u05e5 \u05d1\u05e0\u05d9\u05dd = \u05d0\u05d9\u05e9 \u05d4\u05d1\u05e0\u05d9\u05dd.<\/span><\/p>\n<p style=\"text-align: justify;\">Il ressort qu&rsquo;\u00e0 c\u00f4t\u00e9 de l&rsquo;hypoth\u00e8se traditionnelle,\u00a0on peut aussi traduire\u00a0\u05d0\u05b4\u05bd\u05d9\u05e9\u05c1 \u05d4\u05b7\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd, <em>l&rsquo;homme qui fait le lien, qui se trouve entre deux (partis).\u00a0<\/em>C&rsquo;est un sens que nous n&rsquo;avons relev\u00e9 nulle part et qui semble assez clair dans les deux exemples cit\u00e9s. On pourrait presque dire \u00ab\u00a0m\u00e9diateur\u00a0\u00bb (et penser \u00e0 \u00ab\u00a0n\u00e9gociateur\u00a0\u00bb) &#8211;\u00a0et sans conteste Goliath avait un profil int\u00e9ressant pour le poste&#8230; C&rsquo;est d&rsquo;autant plus probable que ce terme\u00a0\u05de\u05dc\u05d9\u05e5 qui pourrait remplacer\u00a0\u05d0\u05d9\u05e9 vient d&rsquo;une racine\u00a0\u05dc\u05d5\u05bc\u05e5 signifiant <em>m\u00e9priser, railler, parler avec arrogance<\/em>. Or ce n&rsquo;est pas tant ce fait \u00e9tymologique qui nous int\u00e9resse, mais plut\u00f4t l&rsquo;insistance du r\u00e9cit \u00e0 pr\u00e9senter Goliath comme un \u00ab\u00a0challenger\u00a0\u00bb, un homme <em>redoutable<\/em> et <em>m\u00e9prisant<\/em>\u00a0qui harangue les troupes de Sa\u00fcl pendant quarante jours\u00a0(<strong>1 Samuel 17.8-10, 16, 23<\/strong>). Ne faut-il donc pas voir dans le\u00a0\u05d0\u05d9\u05e9 \u05d4\u05d1\u05e0\u05d9\u05dd ou le\u00a0\u05de\u05dc\u05d9\u05e5 \u05d1\u05e0\u05d9\u05dd un interm\u00e9diaire du genre arrogant, non pas un champion en tant que tel, encore fallait-il \u00eatre \u00ab\u00a0champion\u00a0\u00bb pour assumer son arrogance, mais un <em>homme de d\u00e9fi<\/em>\u00a0ou pseudo-ambassadeur ?<\/p>\n<p style=\"text-align: justify;\">A ces deux hypoth\u00e8ses, on peut en ajouter une troisi\u00e8me. Elle est fournie par Matthieu Richelle (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/2755001755\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2755001755&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=QKFIFS6PRNJSVQRI\">2012 : 78-79<\/a>) qui, apr\u00e8s avoir examin\u00e9 et nuanc\u00e9, voire r\u00e9fut\u00e9, les th\u00e8ses minimalistes de Finkelstein\u00a0sur cet \u00e9pisode, explique (nous soulignons) :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Plus r\u00e9cemment, J. Zorn a estim\u00e9 que la plupart des analyses de la tenue de Goliath partent du pr\u00e9suppos\u00e9 qu&rsquo;il \u00e9tait un fantassin, parce que la confrontation avec David a lieu \u00ab\u00a0\u00e0 pied\u00a0\u00bb. Lui-m\u00eame conclut que \u00ab\u00a0chaque partie de la panoplie de Goliath &#8211; son armure \u00e0 \u00e9cailles, son casque, ses jambi\u00e8res &#8211; est [un \u00e9l\u00e9ment de] cuirasse port\u00e9 par des <em>guerriers sur chars<\/em>, soit du Proche-Orient, soit de Gr\u00e8ce, et attest\u00e9 jusqu&rsquo;\u00e0 la toute fin de l&rsquo;\u00e2ge de bronze\u00a0\u00bb. Zorn fait ensuite de m\u00eame avec les armes du Philistin, et propose par ailleurs un rapprochement entre l&rsquo;affirmation qu&rsquo;un porteur se charge du bouclier (1 S 17.7) et le fait que sur un char, il se trouvait souvent plusieurs soldats, l&rsquo;un conduisant, l&rsquo;autre utilisant des armes offensives (arc&#8230;), et un autre encore assurant la protection \u00e0 l&rsquo;aide d&rsquo;un bouclier. Cela expliquerait l&rsquo;expression h\u00e9bra\u00efque myst\u00e9rieuse des v.4 et 23, que l&rsquo;on traduit par \u00ab\u00a0champion\u00a0\u00bb mais qui signifie litt\u00e9ralement : \u00ab\u00a0un homme de l&rsquo;entre-deux\u00a0\u00bb&#8230; La NBS \u00e9dition d&rsquo;\u00e9tude indique en note que cette formule \u00ab\u00a0d\u00e9signait probablement un soldat qui proposait aux ennemis un combat singulier devant se d\u00e9rouler sous les yeux des deux troupes adverses\u00a0\u00bb : <strong>c&rsquo;est l&rsquo;explication classique, mais il s&rsquo;agit clairement d&rsquo;une solution ad hoc<\/strong>. Zorn remarque que sur des reliefs \u00e9gyptiens, notamment ceux de Rams\u00e8s III c\u00e9l\u00e9brant sa victoire sur les Peuples de la Mer (vers 1178), on voit bien des chars portant trois soldats ; l'\u00a0\u00bbhomme de l&rsquo;entre-deux\u00a0\u00bb pourrait d\u00e8s lors \u00eatre le soldat attaquant, flanqu\u00e9 du conducteur et du porteur de bouclier. En un mot, <strong>Goliath aurait tr\u00e8s bien pu \u00eatre un combattant sur char, celui du \u00ab\u00a0milieu\u00a0\u00bb, l&rsquo;attaquant<\/strong>, et lors du duel avec David, on le retrouverait \u00ab\u00a0\u00e0 pied\u00a0\u00bb mais avec son armure habituelle et accompagn\u00e9 de son porteur de bouclier. Zorn estime ainsi que la description biblique est plausible en tant que souvenir authentique de la tenue d&rsquo;un combattant philistin du XIe s. av.J.-C.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Ainsi l&rsquo;\u00e9tude de <a href=\"http:\/\/www.arts.cornell.edu\/jrz3\/Reconsidering_Goliath.pdf\">J. Zorn, \u00ab\u00a0Reconsidering Goliath : An Iron Age I Philistine Charriot Warrior\u00a0\u00bb (BASOR 360, 2010 : 1-22)<\/a>\u00a0sugg\u00e8re un attaquant, <em>le troisi\u00e8me homme du char, celui du milieu<\/em>.<\/p>\n<p style=\"text-align: justify;\">Cet exemple est assez symptomatique des <em>hapax legomena<\/em>. Lorsque le corpus\u00a0ne pr\u00e9sente pas un usage particuli\u00e8rement probant, ou qui autorise plusieurs interpr\u00e9tations, le travail du lexicographe, et par-del\u00e0 de l&rsquo;ex\u00e9g\u00e8te, se complique significativement. Il faut alors creuser le contexte (un contexte militaire, un d\u00e9fi, un combat singulier), l&rsquo;histoire (le <em>modus operandi<\/em>\u00a0philistin\u00a0en mati\u00e8re militaire, la pr\u00e9sence de \u00ab\u00a0champions\u00a0\u00bb), les sources indirectes (versions, litt\u00e9rature rabbinique ou sectaire). Cet exemple de l&rsquo;<em>homme de l&rsquo;entre-deux<\/em> est un peu extr\u00eame car son sens se d\u00e9duit assez du contexte. Mais j&rsquo;ai \u00e9t\u00e9\u00a0agr\u00e9ablement surpris de voir qu&rsquo;on reconna\u00eet la nature r\u00e9elle de l&rsquo;interpr\u00e9tation classique : c&rsquo;est un sens <strong><em>ad hoc<\/em><\/strong>. Il est satisfaisant, certes. Ce n&rsquo;est pas pour autant que c&rsquo;est le bon.<\/p>\n<p style=\"text-align: justify;\">Retenons donc les sens suivants :<\/p>\n<p style=\"text-align: justify;\">&#8211; un homme plac\u00e9 <strong><em>entre<\/em> <\/strong>les lignes ennemies en cas de combat singulier,<\/p>\n<p style=\"text-align: justify;\">&#8211; un\u00a0attaquant situ\u00e9 <strong><em>au milieu<\/em><\/strong> du char,<\/p>\n<p style=\"text-align: justify;\">&#8211; un <strong><em>interm\u00e9diaire<\/em> <\/strong>(\u00e0 toutes fins utiles).<\/p>\n<p style=\"text-align: justify;\">J&rsquo;avoue que l&rsquo;hypoth\u00e8se de Zorn ne me convainc gu\u00e8re, mais je ne l&rsquo;exclus pas cat\u00e9goriquement. La premi\u00e8re hypoth\u00e8se convient aux deux passages des v.4 et 23 mais\u00a0ne conviendrait pas, je pense, aux exemples retrouv\u00e9s \u00e0 Qumr\u00e2n (quand la deuxi\u00e8me pourrait convenir, d&rsquo;o\u00f9 mes r\u00e9serves). Enfin, mon hypoth\u00e8se personnelle n&rsquo;est qu&rsquo;une extension de bon sens de la premi\u00e8re, et de ce qui ressort de Qumr\u00e2n : autrement dit\u00a0\u05d0\u05b4\u05bd\u05d9\u05e9\u05c1 \u05d4\u05b7\u05d1\u05bc\u05b5\u05e0\u05b7\u05d9\u05b4\u05dd, <em>l&rsquo;homme de l&rsquo;entre-deux<\/em>, c&rsquo;\u00e9tait l&rsquo;homme qui se rendait au-devant de l&rsquo;autre parti, <strong><em>\u00ab\u00a0<\/em><em>entre\u00a0\u00bb<\/em><\/strong> les deux partis. Autrement dit une sorte d&rsquo;interm\u00e9diaire, qu&rsquo;il f\u00fbt brutal ou diplomate&#8230;<\/p>\n<p style=\"text-align: justify;\">Pour conclure, une petite animation contant l&rsquo;histoire de David et Goliath. C&rsquo;est pour les enfants, mais on l&rsquo;est tous un peu&#8230;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/58576762\" width=\"500\" height=\"281\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Bien entendu, Bible Parser 2015 (dans sa v.706 \u00e0 para\u00eetre\u00a0prochainement) int\u00e8gre cette nouvelle \u00ab\u00a0expression idiomatique\u00a0\u00bb, aux c\u00f4t\u00e9s d&rsquo;outils pratiques pour tout savoir de la chronologie des rois d&rsquo;Isra\u00ebl et de Juda, des poids et mesures, du calendrier, des corrections scribales, etc.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904158.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3188\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904158.png?resize=178%2C54\" alt=\"1904158\" width=\"178\" height=\"54\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904158.png?resize=300%2C91 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904158.png?w=771 771w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\" \/><\/a>\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904159.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3194\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904159.png?resize=111%2C65\" alt=\"1904159\" width=\"111\" height=\"65\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904159.png?resize=300%2C175 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904159.png?w=707 707w\" sizes=\"auto, (max-width: 111px) 100vw, 111px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041510.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3190\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041510.png?resize=115%2C66\" alt=\"19041510\" width=\"115\" height=\"66\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041510.png?resize=300%2C172 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041510.png?resize=900%2C517 900w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041510.png?w=1014 1014w\" sizes=\"auto, (max-width: 115px) 100vw, 115px\" \/><\/a>\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041511.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3191\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041511.png?resize=221%2C62\" alt=\"19041511\" width=\"221\" height=\"62\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041511.png?resize=300%2C84 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/19041511.png?w=864 864w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/190415121.png\" data-rel=\"lightbox-gallery-g2Qsxrvo\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-3193\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/190415121.png?resize=156%2C88\" alt=\"19041512\" width=\"156\" height=\"88\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/190415121.png?resize=300%2C169 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/190415121.png?w=624 624w\" sizes=\"auto, (max-width: 156px) 100vw, 156px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;histoire de David et Goliath pose de nombreux probl\u00e8mes litt\u00e9raires, linguistiques, historiques, arch\u00e9ologiques ou textuels. On sait depuis longtemps que le texte massor\u00e9tique des livres de Samuel n&rsquo;est pas\u00a0de bonne qualit\u00e9, et qu&rsquo;en bien des endroits, il faut lui\u00a0pr\u00e9f\u00e9rer le texte de la Septante (A. Yadin 2004 : 375, Roberts 1951 : 182, Klein 1974 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,8,294],"tags":[684,683,682,73,80,85],"class_list":["post-3152","post","type-post","status-publish","format-standard","hentry","category-critique-textuelle","category-hebreu-biblique","category-reflexions","tag-1-samuel-17-23","tag-1-samuel-17-4","tag-david-et-goliath","tag-qumran","tag-septante","tag-texte-massoretique"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-OQ","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":136,"url":"http:\/\/areopage.net\/blog\/2013\/07\/25\/a-schenker-p-hugo-et-le-texte-grec-des-rois-lxx-vs-tm\/","url_meta":{"origin":3152,"position":0},"title":"A. Schenker, P. Hugo et le texte grec des Rois (LXX vs TM)","author":"areopage","date":"25\/07\/2013","format":false,"excerpt":"L'histoire est tr\u00e8s compliqu\u00e9e... et me d\u00e9passe par moments. Mais j'ai quand m\u00eame l'audace d'en faire \u00e9tat en quelques mots : toujours dans le S\u00f4fer Mah\u00eer (cf. pr\u00e9c\u00e9dent post), P. Hugo fait le point sur l'histoire du texte grec des Rois (\"Le grec ancien des livres des R\u00e8gnes. Une histoire\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":794,"url":"http:\/\/areopage.net\/blog\/2013\/10\/06\/comparer-la-septante-et-le-texte-massoretique-pour-les-nuls\/","url_meta":{"origin":3152,"position":1},"title":"Comparer la Septante et le Texte Massor\u00e9tique pour les nuls&#8230;","author":"areopage","date":"06\/10\/2013","format":false,"excerpt":"Ce n'est pas le titre d'un nouvel ouvrage jaune fluo, mais une fonctionnalit\u00e9 que la mise \u00e0 jour v.495 de Bible Parser vient d'introduire. C'est une fonctionnalit\u00e9 audacieuse, et il faudra excuser BP s'il ne fait qu'une partie du travail : vous signaler la pr\u00e9sence d'une variante, et vous indiquer\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"0610138","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/10\/0610138-300x155.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":110,"url":"http:\/\/areopage.net\/blog\/2013\/07\/23\/quand-dieu-parlait-grec\/","url_meta":{"origin":3152,"position":2},"title":"Quand Dieu parlait grec","author":"areopage","date":"23\/07\/2013","format":false,"excerpt":"Il vient de sortir et je l'ai aussit\u00f4t command\u00e9. Le dernier ouvrage de T.M. Law, When God spoke Greek me para\u00eet tout \u00e0 fait int\u00e9ressant (voir une pr\u00e9sentation ici). En effet, on oublie facilement que la premi\u00e8re bible des chr\u00e9tiens fut la bible grecque, la Septante. Au moins trois quart\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":132,"url":"http:\/\/areopage.net\/blog\/2013\/07\/25\/qohelet-et-les-disciples-des-sages-oglxx-vs-tm\/","url_meta":{"origin":3152,"position":3},"title":"Qoh\u00e9let et les disciples des sages (LXX vs TM)","author":"areopage","date":"25\/07\/2013","format":false,"excerpt":"Les nombreux auteurs qui s\u2019attellent au projet de la Biblia Hebraica Quinta - projet excitant en termes de critique textuelle s'il en est - font r\u00e9guli\u00e8rement \u00e9tat de leur trouvailles dans des articles ou des conf\u00e9rences. Dans le recueil d'articles en l'honneur d'Adrian Schenker, S\u00f4fer Mah\u00eer (Supplements to Vetus Testamentum,\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1147,"url":"http:\/\/areopage.net\/blog\/2013\/11\/28\/le-pentateuque-de-flavius-josephe\/","url_meta":{"origin":3152,"position":4},"title":"Le Pentateuque de Flavius Jos\u00e8phe","author":"areopage","date":"28\/11\/2013","format":false,"excerpt":"Flavius Jos\u00e8phe (c.37 - 100 AD) est un t\u00e9moin important, mais difficile, du texte de la Bible au premier si\u00e8cle. Il pr\u00e9c\u00e8de Jamnia, et il utilise un texte en h\u00e9breu. Ses citations bibliques devraient donc \u00eatre du plus grand int\u00e9r\u00eat. Malheureusement, il paraphrase plus le texte qui ne le cite,\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4188,"url":"http:\/\/areopage.net\/blog\/2015\/10\/27\/decouverte-dun-texte-proto-massoretique-500-ad\/","url_meta":{"origin":3152,"position":5},"title":"D\u00e9couverte d&rsquo;un texte proto-massor\u00e9tique (500 AD)","author":"areopage","date":"27\/10\/2015","format":false,"excerpt":"C'est une d\u00e9couverte historique. Un t\u00e9moin du texte biblique, vieux de 1500 ans, vient d'\u00eatre mis au jour. D'apr\u00e8s l'Autorit\u00e9 des Antiquit\u00e9s Isra\u00e9liennes (IAA) : this is the most ancient scroll from the five books of the Hebrew Bible to be found since the Dead Sea scrolls, most of which\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"http:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"271015","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/10\/271015-300x270.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":31,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"predecessor-version":[{"id":3208,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/3152\/revisions\/3208"}],"wp:attachment":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}