{"id":2506,"date":"2014-11-16T11:45:11","date_gmt":"2014-11-16T10:45:11","guid":{"rendered":"http:\/\/areopage.net\/blog\/?p=2506"},"modified":"2014-11-16T14:41:47","modified_gmt":"2014-11-16T13:41:47","slug":"du-bon-usage-des-numeros-strong","status":"publish","type":"post","link":"http:\/\/areopage.net\/blog\/2014\/11\/16\/du-bon-usage-des-numeros-strong\/","title":{"rendered":"Du bon usage des num\u00e9ros Strong"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711141.jpg\" data-rel=\"lightbox-gallery-fzr6H640\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2507\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711141.jpg?resize=150%2C150\" alt=\"1711141\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711141.jpg?resize=150%2C150 150w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711141.jpg?resize=144%2C144 144w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Les num\u00e9ros Strong donnent l&rsquo;impression de d\u00e9mocratiser l&rsquo;acc\u00e8s aux langues originales. Si cela peut contribuer \u00e0 les faire aimer, et apprendre, c&rsquo;est une excellente chose. Cependant, \u00e0\u00a0peu de frais, peu de r\u00e9sultats, et il est bien certain qu&rsquo;il ne suffit pas de piocher dans une concordance pour comprendre ce que signifie tel mot dans tel contexte. J&rsquo;ai d\u00e9j\u00e0 signal\u00e9 quelques inconv\u00e9nients du recours aux num\u00e9ros Strong dans mon <a href=\"http:\/\/www.areopage.net\/bphelp\/AnalyseMorphologique.html#caution_strong\">Du bon usage des num\u00e9ros Strong<\/a>. J&rsquo;y signales les probl\u00e8mes connus : James Strong travaillait <em>en anglais<\/em> sur le texte de la King James, fond\u00e9 sur le <em>Texte Re\u00e7u<\/em>. Donc, on ne pourra pas trouver d&rsquo;\u00e9quivalence parfaite avec les \u00e9ditions fran\u00e7aises, \u00e0 plus forte raison les \u00e9ditions r\u00e9centes qui ont un texte \u00e9clectique (en g\u00e9n\u00e9ral bas\u00e9 sur le GNT4 ou le NA27). On trouve des exemples du genre d&rsquo;erreurs auxquelles cela peut conduire en Luc 18.25 ou Jean\u00a09.8. De plus, les textes encod\u00e9s avec le syst\u00e8me des num\u00e9ros Strong ne le sont pas int\u00e9gralement, et certains mots sont laiss\u00e9s de c\u00f4t\u00e9 : toute extraction de donn\u00e9es \u00e0 des fins statistiques aura donc une pertinence limit\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Je n&rsquo;avais toutefois pas abord\u00e9\u00a0un autre volet des probl\u00e8mes li\u00e9s\u00a0aux num\u00e9ros Strong : la pseudo-ex\u00e9g\u00e8se, sujet un peu vaste \u00e0 mon go\u00fbt, et que des personnes comme <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2755001259\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2755001259&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=6OKZBQC5GUCMIE4E\">Romerowski<\/a> ont d\u00e9blay\u00e9 avec brio. Je suis donc ravi de voir qu&rsquo;une personne s&rsquo;y est attel\u00e9e en cinq parties : <a href=\"http:\/\/www.armchair-theology.net\/bible-study\/how-not-to-use-strongs-concordance\/\">How NOT to Use Strong&rsquo;s Concordance<\/a> &#8211;\u00a0<a href=\"http:\/\/www.armchair-theology.net\/bible-study\/how-not-to-use-strongs-concordance-part-2\/\">How NOT to Use Strong&rsquo;s Concordance\/2<\/a>\u00a0&#8211; <a href=\"http:\/\/www.armchair-theology.net\/bible-study\/how-to-properlyuse-strongs-concordance\/\">How to Properly Use Strong&rsquo;s Concordance<\/a> &#8211; <a href=\"http:\/\/www.armchair-theology.net\/bible-study\/strongs-concordance-a-good-example\/\">Strong&rsquo;s Concordance &#8211; A Good Example<\/a> &#8211; <a href=\"http:\/\/www.armchair-theology.net\/bible-study\/is-strongs-concordance-reliable\/\">Is Strong&rsquo;s Concordance Reliable ?<\/a><\/p>\n<p style=\"text-align: justify;\">Je vous recommande instamment d&rsquo;en prendre connaissance !<\/p>\n<p style=\"text-align: justify;\">Mais s&rsquo;il faut r\u00e9sumer en quelques mots :<\/p>\n<p style=\"text-align: justify;\"><strong>1.<\/strong> La concordance de Strong n&rsquo;est pas un dictionnaire. Elle ne d\u00e9finit pas les mots mais propose de courtes gloses, sorties de leur contexte. Or\u00a0un mot sorti de son contexte a peu, voire pas, de sens. Quand il y a plusieurs gloses, comment choisir ? Qui ne conna\u00eet pas la langue, ou n&rsquo;a pas une compr\u00e9hension fine du passage, ne pourra choisir efficacement. L&rsquo;int\u00e9r\u00eat est\u00a0donc nul et le danger, que j&rsquo;ai souvent observ\u00e9, c&rsquo;est de choisir au hasard ce qui convient mieux au sermon pr\u00e9par\u00e9. On pioche donc \u00e0 l&rsquo;envi, sans rigueur. Et plus c&rsquo;est anecdotique, \u00e9tymologique, cocasse ou inhabituel&#8230; mieux c&rsquo;est. Ce peut \u00eatre amusant, mais en aucun cas s\u00e9rieux.<\/p>\n<p style=\"text-align: justify;\"><strong>2.<\/strong> Le recours \u00e0 Strong incite \u00e0 tenter des rapprochements \u00e9tymologiques fallacieux (sur ce point, voir <a href=\"http:\/\/www.amazon.fr\/gp\/product\/B00DJFVGMO\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=B00DJFVGMO&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=H56STQZLYJN3G2Q5\">Carson<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0310479819\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0310479819&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=VFAHH3GD5PKIE72A\">Silva<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2755001259\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2755001259&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=6OKZBQC5GUCMIE4E\">Romerowski<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0830817514\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0830817514&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=KIR22TMIHI6JUUXN\">Cotterell et Turner<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0801020166\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0801020166&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=I67ACKAELUII3HRJ\">Black<\/a>, <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0334019540\/ref=as_li_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0334019540&amp;linkCode=as2&amp;tag=encyclopaed09-21&amp;linkId=AES725L6ZGWRN46C\">Barr<\/a>, etc.). D\u00e9composer un mot en ses unit\u00e9s historiques\u00a0ne revient pas \u00e0 red\u00e9couvrir un sens \u00ab\u00a0primitif\u00a0\u00bbqui expliquerait son usage actuel. Au mieux, c&rsquo;est inutile. Au pire, c&rsquo;est un contresens.<\/p>\n<p style=\"text-align: justify;\"><strong>3.<\/strong> Dot\u00e9 d&rsquo;un tel corpus pratique, l&rsquo;analyse statistique est tentante. Mais \u00e9tudier la fr\u00e9quence d&rsquo;un mot n&rsquo;est pas \u00e9tudier<em> le concept qu&rsquo;il d\u00e9signe<\/em> (accidentellement \u00e7\u00e0 et l\u00e0)<em> dans son entier<\/em>. D&rsquo;o\u00f9 l&rsquo;importance d&rsquo;\u00e9tudier <em>le sens<\/em> plut\u00f4t que le vocable utilis\u00e9 (et \u00e0 sa mani\u00e8re, Logos 6 commence \u00e0 contribuer \u00e0 cette approche avec <a href=\"https:\/\/www.youtube.com\/watch?v=BvG-uhT0HeU&amp;index=15&amp;list=PLXkjd_l1xkSQ5fM605M-F5xikKNGBdPvj\">Sense Lexicon<\/a> et ses <a href=\"https:\/\/www.youtube.com\/watch?v=-2HaWMbEtmw&amp;list=PLXkjd_l1xkSQ5fM605M-F5xikKNGBdPvj&amp;index=4\">Cultural Concepts<\/a>\u00a0; en fran\u00e7ais le <a href=\"http:\/\/www.xl6.com\/articles\/9782920147867-dictionnaire-des-mots-et-des-expressions-de-la-bible-avec-index-conceptuel\"><em>Dictionnaire des Mots et des Expressions de la Bible<\/em><\/a> par J. Cochrane aux <a href=\"http:\/\/www.deq.ca\/\">DEQ<\/a> peut rendre de bons services).<\/p>\n<p style=\"text-align: justify;\">Ne noircissons cependant pas le travail extraordinaire op\u00e9r\u00e9 par J. Strong : il est utile, encore aujourd&rsquo;hui, et tous les logiciels bibliques du march\u00e9 fonctionnent, en totalit\u00e9 ou en partie, gr\u00e2ce \u00e0 son syst\u00e8me ou \u00e0 un syst\u00e8me directement d\u00e9riv\u00e9 (Goodrick-Kohlenberger). Cependant, il faudra toujours se fier en premier lieu \u00e0 des outils de recherche lemmatique (dans lesquels le lemme est recherch\u00e9 plut\u00f4t qu&rsquo;un num\u00e9ro Strong), \u00e0 moins d&rsquo;\u00eatre assur\u00e9 de la fiabilit\u00e9 de l&rsquo;encodage. Parmi les initiatives appr\u00e9ciables, celles de <a href=\"http:\/\/morphgnt.org\/\">Tauber<\/a> pour le texte grec de Tishendorf (8e \u00e9d.) et de la SBL. Le site de <a href=\"https:\/\/unbound.biola.edu\/index.cfm?method=downloads.showDownloadMain\">Unbound<\/a> propose \u00e9galement de nombreux textes encod\u00e9s (NT, LXX, versions anglaises). Et pour l&rsquo;h\u00e9breu, <a href=\"http:\/\/sourceforge.net\/projects\/zefania-sharp\/files\/Bibles\/HEB\/\">Zefania<\/a> fournit une belle s\u00e9lection \u00e9galement.<\/p>\n<p style=\"text-align: justify;\">Notez que d\u00e9sormais <em>Bible Parser<\/em> prend le partie de ne jamais dissocier un verset de son contexte dans la consultation biblique. Le survol d&rsquo;un mot permet instantan\u00e9ment d&rsquo;en saisir le sens de base (et pour les amateurs, le num\u00e9ro Strong reste\u00a0indiqu\u00e9). Mais une fonction en option permet d&rsquo;afficher une traduction plus \u00ab\u00a0contextuelle\u00a0\u00bb (celle de Louis Segond pour le segment consid\u00e9r\u00e9), et l&rsquo;on a t\u00f4t fait de comprendre que les sens propos\u00e9s par Strong (double-clic) n\u00e9cessitent une prise en compte du contexte&#8230;<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711142.png\" data-rel=\"lightbox-gallery-fzr6H640\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2508\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711142.png?resize=150%2C150\" alt=\"1711142\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711142.png?resize=150%2C150 150w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711142.png?resize=144%2C144 144w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711142.png?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711142.png?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\u00a0.<\/p>\n<p style=\"text-align: justify;\">Les nouveaux <em>Dictionnaires<\/em>, actuellement en d\u00e9veloppement, permettront de balayer toutes les r\u00e9f\u00e9rences et tous les outils simultan\u00e9ment : concordance lemmatique, d\u00e9riv\u00e9s, \u00e9quivalents h\u00e9breux ou grecs, synonymes, expressions idiomatiques ou consacr\u00e9es, famille s\u00e9mantique, etc., avec notamment quelques graphiques illustrant les emplois (usage\/signification), les instances, les formes&#8230; Il n&rsquo;y aura plus d&rsquo;excuse \u00e0 l&rsquo;ex\u00e9g\u00e8se approximative, ou au\u00a0recours \u00e0 Strong seul&#8230;<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711143.png\" data-rel=\"lightbox-gallery-fzr6H640\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2509\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711143.png?resize=150%2C150\" alt=\"1711143\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711143.png?resize=150%2C150 150w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711143.png?resize=144%2C144 144w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711143.png?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711143.png?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711144.png\" data-rel=\"lightbox-gallery-fzr6H640\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2513\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711144.png?resize=150%2C150\" alt=\"1711144\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711144.png?resize=150%2C150 150w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711144.png?resize=144%2C144 144w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711144.png?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/11\/1711144.png?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Les num\u00e9ros Strong donnent l&rsquo;impression de d\u00e9mocratiser l&rsquo;acc\u00e8s aux langues originales. Si cela peut contribuer \u00e0 les faire aimer, et apprendre, c&rsquo;est une excellente chose. Cependant, \u00e0\u00a0peu de frais, peu de r\u00e9sultats, et il est bien certain qu&rsquo;il ne suffit pas de piocher dans une concordance pour comprendre ce que signifie tel mot dans tel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,294],"tags":[626],"class_list":["post-2506","post","type-post","status-publish","format-standard","hentry","category-grec-biblique","category-reflexions","tag-numeros-strong"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-Eq","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1091,"url":"http:\/\/areopage.net\/blog\/2013\/11\/19\/logos-5-bibliotheque-de-modules-libres\/","url_meta":{"origin":2506,"position":0},"title":"Logos 5 : Biblioth\u00e8que de Modules Libres","author":"areopage","date":"19\/11\/2013","format":false,"excerpt":"Logos 5 est sans conteste un logiciel biblique extr\u00eamement puissant, tant pour les fonctionnalit\u00e9s li\u00e9es aux langues bibliques, que pour la vari\u00e9t\u00e9 des corpus qu'il propose. Son challenger principal est Accordance 10, et je suis d'avis de ne pas choisir : pour une \u00e9tude s\u00e9rieuse de la Bible, les deux\u2026","rel":"","context":"Dans &quot;liens&quot;","block_context":{"text":"liens","link":"http:\/\/areopage.net\/blog\/category\/liens\/"},"img":{"alt_text":"2011135","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/11\/2011135-150x150.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1813,"url":"http:\/\/areopage.net\/blog\/2014\/06\/08\/les-peres-anteniceens-10-vol\/","url_meta":{"origin":2506,"position":1},"title":"Les P\u00e8res ant\u00e9nic\u00e9ens (10 vol.)","author":"areopage","date":"08\/06\/2014","format":false,"excerpt":"Je suis l'heureux propri\u00e9taire de cette collection des P\u00e8res ant\u00e9nic\u00e9ens depuis peu. \u00c9dit\u00e9e par A. Roberts et J. Donaldson, cette s\u00e9rie comprend la majorit\u00e9 des premiers \u00e9crits chr\u00e9tiens\u00a0jusqu'en l'an 325 AD : Ante-Nicene Fathers - The Writings of the Fathers Down to A.D. 325,\u00a0dont les P\u00e8res apostoliques,\u00a0Ir\u00e9n\u00e9e, Tatien, Justin, Tertullien,\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"0806141","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/06\/0806141-150x150.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4188,"url":"http:\/\/areopage.net\/blog\/2015\/10\/27\/decouverte-dun-texte-proto-massoretique-500-ad\/","url_meta":{"origin":2506,"position":2},"title":"D\u00e9couverte d&rsquo;un texte proto-massor\u00e9tique (500 AD)","author":"areopage","date":"27\/10\/2015","format":false,"excerpt":"C'est une d\u00e9couverte historique. Un t\u00e9moin du texte biblique, vieux de 1500 ans, vient d'\u00eatre mis au jour. D'apr\u00e8s l'Autorit\u00e9 des Antiquit\u00e9s Isra\u00e9liennes (IAA) : this is the most ancient scroll from the five books of the Hebrew Bible to be found since the Dead Sea scrolls, most of which\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"http:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"271015","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/10\/271015-300x270.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4276,"url":"http:\/\/areopage.net\/blog\/2015\/11\/12\/lutilisation-des-revisions-de-la-septante-morlet-2014\/","url_meta":{"origin":2506,"position":3},"title":"L&rsquo;utilisation des r\u00e9visions de la Septante&#8230; (Morlet, 2014)","author":"areopage","date":"12\/11\/2015","format":false,"excerpt":"Dans un ouvrage r\u00e9cent paru aux \u00e9ditions du Z\u00e8bre, La Bible juive dans l'Antiquit\u00e9 (Gounelle et Joosten \u00e9ds, 2014), S\u00e9bastien Morlet traite de L\u2019utilisation des r\u00e9visions de la Septante dans la premi\u00e8re litt\u00e9rature chr\u00e9tienne. Philologie, ex\u00e9g\u00e8se et pol\u00e9mique (pp. 117-140). J'ai d\u00e9j\u00e0 comment\u00e9 bri\u00e8vement une autre \u00e9tude de Morlet sur\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/11\/1111151.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":4121,"url":"http:\/\/areopage.net\/blog\/2015\/10\/18\/bible-parser-request-builder-bis\/","url_meta":{"origin":2506,"position":4},"title":"Bible Parser : Request Builder (bis)","author":"areopage","date":"18\/10\/2015","format":false,"excerpt":"Non sans un certain acharnement, Request Builder progresse. Il est d\u00e9sormais beaucoup plus facile \u00e0 prendre en main, et un peu plus rapide. Les r\u00e9sultats sont coloris\u00e9s, et il est possible d'enregistrer une requ\u00eate pour s'en servir ult\u00e9rieurement - ou encore consulter l'historique r\u00e9cent (une trentaine de requ\u00eates). Ce qui\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"1810153","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/10\/1810153-300x177.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":6229,"url":"http:\/\/areopage.net\/blog\/2017\/06\/18\/dialogue-de-timothee-et-aquila-morlet-2017\/","url_meta":{"origin":2506,"position":5},"title":"Dialogue de Timoth\u00e9e et Aquila (Morlet, 2017)","author":"areopage","date":"18\/06\/2017","format":false,"excerpt":"On ne disposait pas jusqu'\u00e0 pr\u00e9sent d'une traduction fran\u00e7aise de ce dialogue du VIe s. - c'est d\u00e9sormais chose faite : S. Morlet, Dialogue de Timoth\u00e9e et Aquila (Les Belles Lettres, 2017). La pol\u00e9mique religieuse repr\u00e9sente une page importante dans l\u2019histoire des relations entre juifs et chr\u00e9tiens. L\u2019Antiquit\u00e9 en a\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2017\/06\/1706171-191x300.png?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":6,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/2506\/revisions"}],"predecessor-version":[{"id":2516,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/2506\/revisions\/2516"}],"wp:attachment":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=2506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=2506"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}