{"id":1601,"date":"2014-04-27T18:23:42","date_gmt":"2014-04-27T17:23:42","guid":{"rendered":"http:\/\/areopage.net\/blog\/?p=1601"},"modified":"2014-05-22T18:23:55","modified_gmt":"2014-05-22T17:23:55","slug":"la-sorciere-den-dor-une-ventriloque","status":"publish","type":"post","link":"http:\/\/areopage.net\/blog\/2014\/04\/27\/la-sorciere-den-dor-une-ventriloque\/","title":{"rendered":"La sorci\u00e8re d&rsquo;En-Dor : une ventriloque ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604141.png\" data-rel=\"lightbox-gallery-cg60EP7e\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1602\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604141.png?resize=199%2C300\" alt=\"2604141\" width=\"199\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604141.png?resize=199%2C300 199w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604141.png?w=404 404w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Le r\u00e9cit de <strong>1 Samuel 28.3-24<\/strong> pr\u00e9sente un concentr\u00e9 de m\u00e9faits imputables au roi Sa\u00fcl qui sont bien connus. Mais quand on regarde le texte de plus pr\u00e8s, on d\u00e9couvre des difficult\u00e9s inattendues. Prenons d\u00e9j\u00e0 connaissance <em>in extenso<\/em> du r\u00e9cit, selon la version de <em>Darby<\/em> :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>3<\/strong> Samuel \u00e9tait mort, et tout Isra\u00ebl s&rsquo;\u00e9tait lament\u00e9 sur lui, et on l&rsquo;avait enterr\u00e9 \u00e0 Rama, dans sa ville. Et Sa\u00fcl avait \u00f4t\u00e9 du pays <strong><span style=\"color: #339966;\">les \u00e9vocateurs d&rsquo;esprits et les diseurs de bonne aventure<\/span><\/strong>.\u00a0<strong>4<\/strong> Et les Philistins s&rsquo;assembl\u00e8rent, et ils vinrent, et camp\u00e8rent \u00e0 Sunem; et Sa\u00fcl rassembla tout Isra\u00ebl, et ils camp\u00e8rent \u00e0 Guiboa.\u00a0<strong>5<\/strong> Et Sa\u00fcl vit le camp des Philistins, et il eut peur, et son c\u0153ur trembla tr\u00e8s-fort.\u00a0<strong>6<\/strong> Et Sa\u00fcl interrogea l&rsquo;\u00c9ternel, et l&rsquo;\u00c9ternel ne lui r\u00e9pondit pas, <strong><span style=\"color: #339966;\">ni par les songes, ni par l&rsquo;urim, ni par les proph\u00e8tes<\/span><\/strong>.\u00a0<strong>7<\/strong> Et Sa\u00fcl dit \u00e0 ses serviteurs: Cherchez-moi <strong><span style=\"color: #339966;\">une femme qui \u00e9voque les esprits<\/span><\/strong>, et j&rsquo;irai vers elle, et je la consulterai. Et ses serviteurs lui dirent: Voici, il y a \u00e0 En-Dor <strong><span style=\"color: #339966;\">une femme qui \u00e9voque les esprits<\/span><\/strong>.\u00a0<strong>8<\/strong> Et Sa\u00fcl se d\u00e9guisa et rev\u00eatit d&rsquo;autres v\u00eatements, et il s&rsquo;en alla, lui et deux hommes avec lui, et ils vinrent de nuit chez la femme. Et il dit: <strong><span style=\"color: #339966;\">Devine pour moi, je te prie, par un esprit, et fais-moi monter celui que je te dirai.<\/span><\/strong><strong>9<\/strong> Et la femme lui dit: Voici, tu sais ce que Sa\u00fcl a fait, qu&rsquo;il a retranch\u00e9 du pays <strong><span style=\"color: #339966;\">les \u00e9vocateurs d&rsquo;esprits et les diseurs de bonne aventure<\/span><\/strong>; et pourquoi dresses-tu un pi\u00e8ge \u00e0 mon \u00e2me pour me faire mourir?\u00a0<strong>10<\/strong> Et Sa\u00fcl lui jura par l&rsquo;\u00c9ternel, disant: L&rsquo;\u00c9ternel est vivant, s&rsquo;il t&rsquo;arrive aucun mal pour cette affaire!\u00a0<strong>11<\/strong> Et la femme dit: <strong><span style=\"color: #339966;\">Qui te ferai-je monter?<\/span><\/strong> Et il dit: <strong><span style=\"color: #339966;\">Fais-moi monte<\/span><span style=\"color: #339966;\">r<\/span><\/strong> Samuel.\u00a0<strong>12<\/strong> Et la femme vit Samuel, et elle poussa un grand cri; et la femme parla \u00e0 Sa\u00fcl, disant: Pourquoi m&rsquo;as-tu tromp\u00e9? et tu es Sa\u00fcl!\u00a0<strong>13<\/strong> Et le roi lui dit: Ne crains point; mais <strong><span style=\"color: #339966;\">que vois-tu?<\/span><\/strong> Et la femme dit \u00e0 Sa\u00fcl: <strong><span style=\"color: #339966;\">Je vois un dieu qui monte de la terre.<\/span><\/strong><strong>14<\/strong> Et il lui dit: <span style=\"color: #339966;\"><strong>Quelle est sa forme?<\/strong><\/span> Et elle dit: C&rsquo;est un vieillard qui monte, et il est envelopp\u00e9 d&rsquo;un manteau. Et Sa\u00fcl connut que c&rsquo;\u00e9tait Samuel; et il se baissa le visage contre terre et se prosterna.\u00a0<strong>15<\/strong> Et Samuel dit \u00e0 Sa\u00fcl: Pourquoi as-tu troubl\u00e9 mon repos en me faisant monter? Et Sa\u00fcl dit: Je suis dans une grande d\u00e9tresse; car les Philistins me font la guerre, et Dieu s&rsquo;est retir\u00e9 de moi, et ne me r\u00e9pond plus, ni par les proph\u00e8tes, ni par les songes; et je t&rsquo;ai appel\u00e9 pour me faire savoir ce que j&rsquo;ai \u00e0 faire.\u00a0<strong>16<\/strong> Et Samuel dit: Et pourquoi m&rsquo;interroges-tu, quand l&rsquo;\u00c9ternel s&rsquo;est retir\u00e9 de toi et qu&rsquo;il est devenu ton ennemi?\u00a0<strong>17<\/strong> Et l&rsquo;\u00c9ternel a fait pour lui-m\u00eame comme il l&rsquo;a dit par moi; et l&rsquo;\u00c9ternel a d\u00e9chir\u00e9 le royaume d&rsquo;entre tes mains et l&rsquo;a donn\u00e9 \u00e0 ton prochain, \u00e0 David;\u00a0<strong>18<\/strong> parce que tu n&rsquo;as pas \u00e9cout\u00e9 la voix de l&rsquo;\u00c9ternel et que tu n&rsquo;as pas ex\u00e9cut\u00e9 l&rsquo;ardeur de sa col\u00e8re contre Amalek: \u00e0 cause de cela, l&rsquo;\u00c9ternel t&rsquo;a fait ceci aujourd&rsquo;hui.\u00a0<strong>19<\/strong> Et l&rsquo;\u00c9ternel livrera aussi Isra\u00ebl avec toi en la main des Philistins; et demain, toi et tes fils, vous serez avec moi; l&rsquo;\u00c9ternel livrera aussi l&rsquo;arm\u00e9e d&rsquo;Isra\u00ebl en la main des Philistins.\u00a0<strong>20<\/strong> Et Sa\u00fcl aussit\u00f4t tomba \u00e0 terre de toute sa hauteur, et il fut extr\u00eamement effray\u00e9 des paroles de Samuel; m\u00eame il n&rsquo;y avait plus de force en lui, <strong><span style=\"color: #339966;\">car il n&rsquo;avait pas mang\u00e9 de pain de tout le jour et de toute la nuit<\/span><\/strong>.\u00a0<strong>21<\/strong> Et la femme vint \u00e0 Sa\u00fcl, et elle vit qu&rsquo;il \u00e9tait tr\u00e8s-troubl\u00e9, et elle lui dit: Voici, ta servante a \u00e9cout\u00e9 ta voix, et <span style=\"color: #0000ff;\">j&rsquo;ai mis ma vie dans ma main<\/span>, et j&rsquo;ai \u00e9cout\u00e9 les paroles que tu m&rsquo;as dites;\u00a0<strong>22<\/strong> et maintenant, je te prie, \u00e9coute, toi aussi, la voix de ta servante, et je mettrai devant toi une bouch\u00e9e de pain, et mange, et tu auras de la force pour aller ton chemin.\u00a0<strong>23<\/strong> Et il refusa et dit: Je ne mangerai point. Et ses serviteurs et la femme aussi le press\u00e8rent; et il \u00e9couta leur voix, et se leva de terre et s&rsquo;assit sur le lit.\u00a0<strong>24<\/strong> Et la femme avait dans la maison un veau gras, et elle se h\u00e2ta de le tuer; et elle prit de la farine et la p\u00e9trit, et en cuisit des pains sans levain,\u00a0<strong>25<\/strong> qu&rsquo;elle apporta devant Sa\u00fcl et devant ses serviteurs; et ils mang\u00e8rent; et ils se lev\u00e8rent, et s&rsquo;en all\u00e8rent cette m\u00eame nuit-l\u00e0.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Pour certains ex\u00e9g\u00e8tes, les difficult\u00e9s r\u00e9dactionnelles pos\u00e9es par ce r\u00e9cit sont patentes\u00a0: il y aurait deux r\u00e9cits qu&rsquo;un r\u00e9dacteur final aurait combin\u00e9s, voire juxtapos\u00e9s, sans grand souci d&rsquo;exactitude, en tentant seulement de gommer les \u00e9l\u00e9ments les plus pa\u00efens du r\u00e9cit initial\u00a0(<a href=\"https:\/\/archive.org\/stream\/revuedelhistoire87v88pari#page\/46\/mode\/2up\">Reinach, RHR 1923 : 46<\/a>) ; ou encore, le r\u00e9cit ne serait pas en place (il est chronologiquement situ\u00e9 \u00e0 la veille du combat de Guilboa quand le contexte indique que les Philistins sont loin), et serait plut\u00f4t \u00e0 ins\u00e9rer entre les chapitres 30 et 31 (<a href=\"http:\/\/books.google.fr\/books?id=KsjUno1HmxgC&amp;lpg=PA165&amp;vq=simple%20bo%C3%AEte&amp;hl=fr&amp;pg=PA333#v=onepage&amp;q&amp;f=false\">Caquot 1994 : 333<\/a>).<\/p>\n<p style=\"text-align: justify;\">Ce qui nous int\u00e9resse ici, ce sont les difficult\u00e9s lexicales. Au <strong>verset 3<\/strong>, il est question d&rsquo;<em>\u00e9vocateurs d&rsquo;esprits et diseurs de bonne aventure<\/em>. Cela recoupe l&rsquo;expression h\u00e9bra\u00efque\u00a0\u05d4\u05b8\u05d0\u05b9\u05d1\u05b9\u05d5\u05ea \u05d5\u05b0\u05d0\u05b6\u05ea\u05be\u05d4\u05b7\u05d9\u05b4\u05bc\u05d3\u05b0\u05bc\u05e2\u05b9\u05e0\u05b4\u05d9\u05dd (h\u0101\u2019\u014d\u1e07w\u014d\u1e6f w\u0259\u2019e\u1e6f-hayyid\u0259\u2018\u014dn\u00eem). Quand on consulte les traductions fran\u00e7aises, on ressent un certain embarras : <em>n\u00e9cromants et devins<\/em> (BJ), <em>ceux qui invoquent les esprits et spirites<\/em> (S21), <em>spirites et m\u00e9diums<\/em> (NBS), <em>la pratique de la divination<\/em> (TOB), <em>n\u00e9cromants et devins<\/em> (Pl\u00e9iade, Rabbinat). La version de Samuel Cahen renonce \u00e0 traduire : <em>oboth et iidonime <\/em>(et indique <em>n\u00e9cromanciens et devins<\/em> en note).\u00a0La Vulgate porte <em>magos et ariolos<\/em>. Dans le texte grec des LXX on trouve\u00a0\u03c4\u03bf\u1f7a\u03c2 \u1f10\u03b3\u03b3\u03b1\u03c3\u03c4\u03c1\u03b9\u03bc\u03cd\u03b8\u03bf\u03c5\u03c2 \u03ba\u03b1\u1f76 \u03c4\u03bf\u1f7a\u03c2 \u03b3\u03bd\u03ce\u03c3\u03c4\u03b1\u03c2 (les ventriloques et les connaisseurs ; cf.\u00a0<a href=\"http:\/\/www.amazon.fr\/gp\/product\/220405545X\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=220405545X&amp;linkCode=as2&amp;tag=encyclopaed09-21\"><em>Bible d\u2019Alexandrie<\/em>, 1997:394-396<\/a>, \u00ab\u00a0ventriloques et devins\u00a0\u00bb).<\/p>\n<p style=\"text-align: justify;\">Le terme \u05d4\u05b7\u05d9\u05b4\u05bc\u05d3\u05b0\u05bc\u05e2\u05b9\u05e0\u05b4\u05d9\u05dd\u00a0ne semble pas <em>a priori<\/em> poser de difficult\u00e9, puisqu&rsquo;on y reconna\u00eet d&#8217;embl\u00e9e la racine du verbe <em>savoir, conna\u00eetre<\/em> (\u05d9\u05d3\u05e2), d&rsquo;o\u00f9 <em>connaisseurs<\/em>, <em>devins<\/em>. On le rencontre 11 fois, toujours associ\u00e9 \u00e0 \u05d0\u05b9\u05d1\u05b9\u05d5\u05ea\u00a0(L\u00e9v 19.31, 20.6, 27, Deut 18.11, 1 Sam 28.3, 9, 2 Rois 21.6, 23.24, 2 Chron 33.6, Esa 8.19, 19.3 ; cf. <a href=\"http:\/\/www.amazon.fr\/gp\/product\/1565631331\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=1565631331&amp;linkCode=as2&amp;tag=encyclopaed09-21\">TLOT 2:510<\/a>, \u00ab\u00a0spirit of soothsaying\u00a0\u00bb, <em>esprit de divination<\/em>). En revanche, \u05d4\u05b8\u05d0\u05b9\u05d1\u05b9\u05d5\u05ea\u00a0\u00a0est plus d\u00e9licat. On reconna\u00eet tout aussi facilement que pour le pr\u00e9c\u00e9dent mot une racine famili\u00e8re (\u05d0\u05d1), qui sugg\u00e8re quelque chose comme <em>anc\u00eatre<\/em>, <em>esprit familier<\/em>. Mais la d\u00e9duction du sens par l&rsquo;\u00e9tymologie est p\u00e9rilleuse, ici plus qu&rsquo;ailleurs. Certains sugg\u00e8rent une racine commune \u00e0 l&rsquo;arabe <em>&lsquo;wb<\/em> (<em>revenir<\/em>, d&rsquo;o\u00f9 <em>revenant<\/em> ; cf. <a href=\"http:\/\/www.amazon.fr\/gp\/product\/9004096965\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=9004096965&amp;linkCode=as2&amp;tag=encyclopaed09-21\">HALOT 1:20<\/a>).<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604142.png\" data-rel=\"lightbox-gallery-cg60EP7e\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1614\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604142.png?resize=300%2C120\" alt=\"2604142\" width=\"300\" height=\"120\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604142.png?resize=300%2C120 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604142.png?resize=1024%2C410 1024w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604142.png?resize=900%2C360 900w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/2604142.png?w=1550 1550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Quand on examine les <a href=\"http:\/\/areopage.net\/blog\/wp-content\/uploads\/2014\/04\/Oboth.pdf\">17 instances<\/a> (ici, en <a href=\"http:\/\/biblearc.com#b5d60e21f994b1ebac54252f95943cd01c2f400b8a35918d296e8538fc6a982d\">h\u00e9breu<\/a>) o\u00f9 figure le mot, un passage attire l&rsquo;attention : <strong>Job 32.19<\/strong>.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">au dedans de moi, c&rsquo;est comme du vin sous pression,<br \/>\n<strong>comme des outres<\/strong> (\u05db\u05b0\u05bc\u05d0\u05b9\u05d1\u05b9\u05d5\u05ea) neuves qui vont \u00e9clater. (<em>NBS<\/em>)<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Ainsi, on est \u00e9tonn\u00e9 de voir que le terme s&#8217;emploie presque toujours pour parler de <em>ceux qui font profession d&rsquo;\u00e9voquer les esprits des morts<\/em>, autrement dit <em>les m\u00e9diums<\/em> ou <em>n\u00e9cromanciens<\/em>, \u00e0 l&rsquo;exception de cette instance o\u00f9 il est question d&rsquo;un <em>r\u00e9cipient<\/em>. C&rsquo;est ce qui fait dire \u00e0 des lexicographes (<a href=\"http:\/\/www.amazon.fr\/gp\/product\/0899576672\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0899576672&amp;linkCode=as2&amp;tag=encyclopaed09-21\">Baker\/Carpenter, CWSD-OT 2003:23<\/a>) :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">There is no convincing evidence that this particular reference has any occult connotations. Rather, the connection between the two divergent meanings of this Hebrew word is probably that a medium was seen as a \u00ab\u00a0container\u00a0\u00bb for a conjured spirit.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Si dans la grande majorit\u00e9 des cas, le terme\u00a0\u05d0\u05b9\u05d1\u05b9\u05d5\u05ea d\u00e9signe <em>des personnes<\/em>, quelquefois on peut comprendre qu&rsquo;il s&rsquo;agit<em> des objets et instruments<\/em> employ\u00e9s pour l&rsquo;\u00e9vocation. Ainsi en <strong>1 Samuel 28.7<\/strong>, il est question d&rsquo;une femme,\u00a0\u05d1\u05b7\u05bc\u05e2\u05b2\u05dc\u05b7\u05ea\u05be\u05d0\u05b9\u05d5\u05d1, <em>d\u00e9tentrice d&rsquo;un \u00f4b<\/em>. En <strong>L\u00e9vitique 20.27<\/strong>, la tournure\u00a0\u05d5\u05b0\u05d0\u05b4\u05d9\u05e9\u05c1 \u05d0\u05b9\u05d5\u05be\u05d0\u05b4\u05e9\u05b8\u05bc\u05c1\u05d4 \u05db\u05b4\u05bc\u05d9\u05be\u05d9\u05b4\u05d4\u05b0\u05d9\u05b6\u05d4 \u05d1\u05b8\u05d4\u05b6\u05dd \u05d0\u05b9\u05d5\u05d1,<em> si un homme ou une femme poss\u00e8de chez lui un \u00f4b<\/em> (que certains comprennent : <em>si un homme ou une femme a en lui l&rsquo;esprit d&rsquo;un mort<\/em>). En <strong>Isa\u00efe 29.4<\/strong>, une voix \u00e9touff\u00e9e, comme sortant de terre, se compare \u00e0 un <em>\u00f4b<\/em>. On pense alors moins \u00e0 un spectre qu&rsquo;au subterfuge d&rsquo;un objet, ou du m\u00e9dium lui-m\u00eame pratiquant la ventriloquie ; ce qui derechef peut se mettre en parall\u00e8le avec <strong>Isa\u00efe 8.19<\/strong> o\u00f9 il est question de <em>chuchotement et de murmure<\/em>. Cela fait dire \u00e0 Caquot (<a href=\"http:\/\/books.google.fr\/books?id=KsjUno1HmxgC&amp;lpg=PA165&amp;vq=simple%20bo%C3%AEte&amp;hl=fr&amp;pg=PA333#v=onepage&amp;q&amp;f=false\">1994 : 334<\/a>) :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">De ces attestations on peut conclure que le \u05d0\u05d5\u05d1 semble \u00eatre un objet utilis\u00e9 pour l&rsquo;\u00e9vocation des morts, peut-\u00eatre un instrument \u00e0 vent comme le biniou, avec lequel on appellerait le spectre ou qui parlerait en son nom.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Cette hypoth\u00e8se est possible, mais elle reste bien entendu une sp\u00e9culation : le texte de <em>L\u00e9vitique<\/em> peut s&rsquo;entendre d&rsquo;une personne <em>poss\u00e9d\u00e9e<\/em>, et ceux d&rsquo;<em>Isa\u00efe<\/em> comme une critique de cette pratique ill\u00e9gale (cf. <a href=\"http:\/\/www.amazon.fr\/gp\/product\/0802486495\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=0802486495&amp;linkCode=as2&amp;tag=encyclopaed09-21\">TWOT 17<\/a>\u00a0; \u00ab\u00a0Isaiah discredits these &lsquo;necromancers&rsquo; and implies by his choice of words that the sounds of spirits so raised are nothing more than ventriloquism\u00a0\u00bb).<\/p>\n<p style=\"text-align: justify;\">A de rares exceptions pr\u00e8s, \u05d0\u05d5\u05d1\u00a0\u00a0est toujours rendu par \u00ab\u00a0ventriloque\u00a0\u00bb dans la Septante (sauf en 2 Rois 21.6,\u00a0\u03b8\u03b5\u03bb\u03b7\u03c4\u1f74\u03bd et \u00a023.24,\u00a0\u03b8\u03b5\u03bb\u03b7\u03c4\u1f70\u03c2, o\u00f9 le choix du terme \u03b8\u03b5\u03bb\u03b7\u03c4\u03b7\u0301\u03c2 sugg\u00e8re l&rsquo;\u00e9tymologie \u05d0\u05d1\u05d4 &gt; \u05d0\u05d5\u05d1<span style=\"line-height: 1.5em;\">, <em>d\u00e9sirer<\/em>, cf. <a href=\"http:\/\/www.amazon.fr\/gp\/product\/9042922486\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=9042922486&amp;linkCode=as2&amp;tag=encyclopaed09-21\">Muraoka 2009:325<\/a>). On notera d&rsquo;ailleurs que J\u00e9r\u00f4me, en 1 Samuel 28.7, parle d&rsquo;une\u00a0<em>mulier habens pythonem<\/em>, c&rsquo;est-\u00e0-dire d&rsquo;une\u00a0<em>femme ayant un esprit de Python<\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\">Cette pratique de la ventriloquie par les n\u00e9cromants de l&rsquo;Antiquit\u00e9 fait dire au grand sp\u00e9cialiste A. Bouch\u00e9-Leclercq (<a href=\"https:\/\/archive.org\/stream\/histoiredeladivi01boucuoft#page\/338\/mode\/2up\"><em>Histoire de la divination dans l&rsquo;Antiquit\u00e9<\/em>, I : 338<\/a>):<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Du reste, ce serait une erreur de croire que les conjurations n\u00e9cromantiques dussent toujours avoir pour r\u00e9sultat l&rsquo;apparition visible et presque palpable d&rsquo;une ombre semblable \u00e0 la personne invoqu\u00e9e. On se contentait de moins. Souvent, on ne demandait aux morts que de faire entendre leurs voix et les n\u00e9cromants ventriloques ou <em>engastrimythes<\/em> arrivaient facilement \u00e0 produire l&rsquo;illusion d\u00e9sir\u00e9e, soit \u00e0 l&rsquo;insu du client, soit en se donnant pour les instruments des esprits.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Aucun des moyens l\u00e9gaux pour consulter la divinit\u00e9 \u00e9voqu\u00e9s au verset 6, (songe, <a title=\"1 Samuel 14.41 : \u05ea\u05b8\u05de\u05b4\u05d9\u05dd ou \u05ea\u05bb\u05bc\u05de\u05b4\u05bc\u05d9\u05dd ? (LXX vs TM)\" href=\"http:\/\/areopage.net\/blog\/2014\/03\/22\/1-samuel-14-41-%d7%aa%d6%b8%d7%9e%d6%b4%d7%99%d7%9d-ou-%d7%aa%d6%bb%d6%bc%d7%9e%d6%b4%d6%bc%d7%99%d7%9d-lxx-vs-tm\/\">ourim\/thummim<\/a>, proph\u00e8tes) ne proposait de <em>manifestation visible<\/em>. Les proc\u00e9d\u00e9s interdits par la Loi \u00e9taient en revanche nombreux et tout \u00e0 fait ax\u00e9s sur <em>la vision<\/em> et <em>l&rsquo;observation<\/em> : rhabdomancie, h\u00e9patoscopie, teraphim (mentionn\u00e9s en 1 Samuel 15.23 par ex.), astrologie ou hydromancie (cf. <a href=\"http:\/\/www.amazon.fr\/gp\/product\/2755001003\/ref=as_li_ss_tl?ie=UTF8&amp;camp=1642&amp;creative=19458&amp;creativeASIN=2755001003&amp;linkCode=as2&amp;tag=encyclopaed09-21\">GDB p.436<\/a>). Les proc\u00e9d\u00e9s diaboliques auraient, en ce cas, un caract\u00e8re fonci\u00e8rement visuel, et trompeur (cf. <strong>Gen\u00e8se 3.6, 2 Corinthiens 5.7, 11.14, 1 Jean 2.16<\/strong>). S&rsquo;\u00e9tonnera-t-on donc que la premi\u00e8re femme ait \u00e9t\u00e9 s\u00e9duite par un Satan faisant usage de ventriloquie ?<\/p>\n<p style=\"text-align: justify;\">De m\u00eame que le roi Sa\u00fcl trompe, ou essaie de tromper la sorci\u00e8re en se travestissant au moyen de haillons, de m\u00eame la sorci\u00e8re refuse dans un premier temps (<strong>verset 9<\/strong>) de r\u00e9v\u00e9ler sa v\u00e9ritable identit\u00e9 et son m\u00e9tier. Ce qui est cocasse, et m\u00eame tr\u00e8s curieux, c&rsquo;est que lorsque cette pythonisse se d\u00e9cide \u00e0 appeler \u00ab\u00a0Samuel\u00a0\u00bb pour le roi, elle pousse un grand cri (<strong>verset 12<\/strong>) quand il \u00ab\u00a0monte\u00a0\u00bb.\u00a0C&rsquo;est bien qu&rsquo;elle ne s&rsquo;y attendait pas, et que peut-\u00eatre, pour une fois, sa n\u00e9cromancie n&rsquo;est pas qu&rsquo;une simple supercherie (cf. <a href=\"http:\/\/www.maisonbible.net\/emm4636\/livres-historiques-encyclopedie-des-difficultes-bibliques-at-vol-2a-et-2b\">Kuen 2010 : 449<\/a>).<\/p>\n<p style=\"text-align: justify;\">Mais alors, les difficult\u00e9s surgissent en nombre. Pourquoi un juste proph\u00e8te comme Samuel r\u00e9pondrait-il \u00e0 l&rsquo;appel d&rsquo;une sorci\u00e8re ? Les Isra\u00e9lites croyaient-ils en une survie (m\u00eame diminu\u00e9e) apr\u00e8s la mort ?<\/p>\n<p style=\"text-align: justify;\">Les commentateurs ont propos\u00e9 bien des hypoth\u00e8ses : <strong>1)<\/strong> oui, Dieu aurait r\u00e9pondu \u00e0 la demande de Sa\u00fcl (alors qu&rsquo;il ne l&rsquo;a pas fait avant, cf. <strong>v.6<\/strong>), en permettant \u00e0 l&rsquo;esprit de Samuel de revenir (mais d&rsquo;o\u00f9 ?), <strong>2)<\/strong> c&rsquo;est en fait un d\u00e9mon qui a pris les traits de Samuel (mais alors, ce d\u00e9mon a dit la v\u00e9rit\u00e9 ! et quel int\u00e9r\u00eat y avait-il \u00e0 faire une telle pr\u00e9diction ? ; c&rsquo;est la position de la TMN qui porte \u00ab\u00a0Samuel\u00a0\u00bb entre guillemets ; mais incorporer cette interpr\u00e9tation d\u00e8s le texte\u00a0n&rsquo;est pas recommandable),<strong> 3)<\/strong> ou encore, la sorci\u00e8re aurait-elle jou\u00e9 sa com\u00e9die habituelle ?<\/p>\n<p style=\"text-align: justify;\">Chacune des hypoth\u00e8ses pose ses propres probl\u00e8mes. Il faudrait d&rsquo;abord se demander si cette croyance de survie <em>post-mortem<\/em> (dans le Sh\u00e9ol ?) existait bien \u00e0 l&rsquo;\u00e9poque (sur ce point, cf. <a href=\"https:\/\/archive.org\/stream\/lacroyancelavie00lodsgoog#page\/n9\/mode\/2up\">Lods, <em>La croyance \u00e0 la vie future et le culte des morts dans l&rsquo;antiquit\u00e9 isra\u00e9lite<\/em>, 1906<\/a> ; cf. <a href=\"https:\/\/archive.org\/stream\/lacroyancelavie00lodsgoog#page\/n263\/mode\/2up\">pp. 248 sq<\/a>). Il faudrait aussi r\u00e9soudre les difficult\u00e9s litt\u00e9raires (par ex. celle du <strong>verset 12<\/strong> : la sorci\u00e8re reconna\u00eet <em>Sa\u00fcl<\/em> lorsque\u00a0<em>Samuel<\/em> appara\u00eet : ??? On a propos\u00e9 d&rsquo;\u00e9mender le texte d&rsquo;apr\u00e8s quelques mss. grecs de la LXX qui portent <em>Sa\u00fcl<\/em>, mais je pense qu&rsquo;il faut le comprendre dans son \u00e9tat actuel), et analyser les motifs qui, au-del\u00e0 du texte, attestent de la vraisemblance du r\u00e9cit qui nous est rapport\u00e9 en fonction de ce qu&rsquo;on sait ou de ce qu&rsquo;on peut d\u00e9duire par ailleurs. Par exemple, le manteau que porte le vieillard qui passe pour Samuel renvoie clairement \u00e0 l&rsquo;\u00e9pisode de 1 Samuel 15.27-28. Mais un spectre en manteau, est-ce bien cr\u00e9dible ? Plus troublant, on trouve en <strong>1 Chroniques 10.13<\/strong> une divergence assez sensible entre TM et LXX :<\/p>\n<p style=\"text-align: justify;\"><strong>TM<\/strong> :\u00a0\u05d5\u05b7\u05d9\u05b8\u05bc\u05de\u05b8\u05ea \u05e9\u05b8\u05c1\u05d0\u05d5\u05bc\u05dc \u05d1\u05b0\u05bc\u05de\u05b7\u05e2\u05b2\u05dc\u05b9\u05d5 \u05d0\u05b2\u05e9\u05b6\u05c1\u05e8 \u05de\u05b8\u05e2\u05b7\u05dc \u05d1\u05b7\u05bc\u05d9\u05d4\u05d5\u05b8\u05d4 \u05e2\u05b7\u05dc\u05be\u05d3\u05b0\u05bc\u05d1\u05b7\u05e8 \u05d9\u05b0\u05d4\u05d5\u05b8\u05d4 \u05d0\u05b2\u05e9\u05b6\u05c1\u05e8 \u05dc\u05b9\u05d0\u05be\u05e9\u05b8\u05c1\u05de\u05b8\u05e8 <span style=\"color: #0000ff;\">\u05d5\u05b0\u05d2\u05b7\u05dd\u05be\u05dc\u05b4\u05e9\u05b0\u05c1\u05d0\u05b9\u05d5\u05dc \u05d1\u05b8\u05bc\u05d0\u05b9\u05d5\u05d1 \u05dc\u05b4\u05d3\u05b0\u05e8\u05b9\u05d5\u05e9\u05c1\u05c3<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>LXX<\/strong> :\u00a0\u03ba\u03b1\u1f76 \u1f00\u03c0\u1f73\u03b8\u03b1\u03bd\u03b5\u03bd \u03a3\u03b1\u03bf\u03c5\u03bb \u1f10\u03bd \u03c4\u03b1\u1fd6\u03c2 \u1f00\u03bd\u03bf\u03bc\u03af\u03b1\u03b9\u03c2 \u03b1\u1f50\u03c4\u03bf\u1fe6 \u03b1\u1f37\u03c2 \u1f20\u03bd\u1f79\u03bc\u03b7\u03c3\u03b5\u03bd \u03c4\u1ff7 \u03ba\u03c5\u03c1\u03af\u1ff3 \u03ba\u03b1\u03c4\u1f70 \u03c4\u1f78\u03bd \u03bb\u1f79\u03b3\u03bf\u03bd \u03ba\u03c5\u03c1\u03af\u03bf\u03c5 \u03b4\u03b9\u1f79\u03c4\u03b9 \u03bf\u1f50\u03ba \u1f10\u03c6\u03cd\u03bb\u03b1\u03be\u03b5\u03bd <span style=\"color: #0000ff;\">\u1f45\u03c4\u03b9 \u1f10\u03c0\u03b7\u03c1\u03ce\u03c4\u03b7\u03c3\u03b5\u03bd \u03a3\u03b1\u03bf\u03c5\u03bb \u1f10\u03bd \u03c4\u1ff7 \u1f10\u03b3\u03b3\u03b1\u03c3\u03c4\u03c1\u03b9\u03bc\u03cd\u03b8\u1ff3 \u03c4\u03bf\u1fe6 \u03b6\u03b7\u03c4\u1fc6\u03c3\u03b1\u03b9 \u03ba\u03b1\u1f76 \u1f00\u03c0\u03b5\u03ba\u03c1\u03af\u03bd\u03b1\u03c4\u03bf \u03b1\u1f50\u03c4\u1ff7 \u03a3\u03b1\u03bc\u03bf\u03c5\u03b7\u03bb \u1f41 \u03c0\u03c1\u03bf\u03c6\u03ae\u03c4\u03b7\u03c2<\/span><\/p>\n<p style=\"text-align: justify;\">Dans le Texte Massor\u00e9tique, il est question de la consultation seule de l&rsquo;esprit du mort (avec deux verbes : <em>interroger<\/em> et <em>chercher<\/em> [\u00e0 savoir]). La tournure\u00a0\u05dc\u05b4\u05d3\u05b0\u05e8\u05b9\u05d5\u05e9\u05c1 para\u00eet d&rsquo;ailleurs terminer la proposition un peu abruptement (litt. &#8230;<em>pour chercher <\/em>; qal infinitif construit). Dans la Septante au contraire, toute une pr\u00e9cision vient s&rsquo;ajouter \u00e0 ce qui pr\u00e9c\u00e8de :\u00a0\u03ba\u03b1\u1f76 \u1f00\u03c0\u03b5\u03ba\u03c1\u03af\u03bd\u03b1\u03c4\u03bf \u03b1\u1f50\u03c4\u1ff7 \u03a3\u03b1\u03bc\u03bf\u03c5\u03b7\u03bb \u1f41 \u03c0\u03c1\u03bf\u03c6\u03ae\u03c4\u03b7\u03c2, <em>et le proph\u00e8te Samuel lui r\u00e9pondit<\/em>. Il n&rsquo;y a donc pas d&rsquo;ambigu\u00eft\u00e9, puisque le texte authentifie clairement la r\u00e9ponse <em>par Samuel lui-m\u00eame<\/em>.<\/p>\n<p style=\"text-align: justify;\">D&rsquo;autres textes, comme l&rsquo;<strong>Eccl\u00e9siastique 46.13,20<\/strong> laissent entendre qu&rsquo;on pensait \u00e0 une r\u00e9elle apparition de Samuel :<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Samuel fut le bien\u2013aim\u00e9 de son Seigneur; proph\u00e8te du Seigneur, il \u00e9tablit la royaut\u00e9 et donna l&rsquo;onction aux chefs \u00e9tablis sur son peuple. (&#8230;) Apr\u00e8s s&rsquo;\u00eatre endormi il proph\u00e9tisa encore et annon\u00e7a au roi sa fin; du sein de la terre il \u00e9leva la voix pour proph\u00e9tiser, pour effacer l&rsquo;iniquit\u00e9 du peuple.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Dans le <em>Livre des Antiquit\u00e9s Bibliques<\/em> (ch. 64) de m\u00eame, l&rsquo;apparition est retranscrite (plus longuement que dans le texte biblique), et laisse supposer une vision r\u00e9elle. En l&rsquo;occurrence, le r\u00e9cit sert surtout \u00e0 att\u00e9nuer certaines difficult\u00e9s, comme pourquoi la sorci\u00e8re (qui, dit-on, a souvent vu Sa\u00fcl) ne reconna\u00eet pas Sa\u00fcl (son aspect est chang\u00e9 \u00e0 cause de la perte de la \u00ab\u00a0gloire de son r\u00e8gne\u00a0\u00bb, 64.4), pourquoi Samuel un juste r\u00e9pond \u00e0 une sorci\u00e8re (Dieu avait en fait confi\u00e9 un message \u00e0 Samuel de son vivant, 64.7), et surtout pourquoi la sorci\u00e8re pousse un grand cri (elle voit Samuel monter <em>accompagn\u00e9<\/em> de Sa\u00fcl, 64.5&#8230;).<\/p>\n<p style=\"text-align: justify;\">Mais on ne peut tirer grand-chose de ces enjolivements. Et quand on revient au r\u00e9cit initial, on per\u00e7oit quand m\u00eame plusieurs points d&rsquo;importance. D&rsquo;abord, \u00ab\u00a0faire monter\u00a0\u00bb un esprit est de prime abord incompatible avec la ventriloquie, \u00e0 moins de consid\u00e9rer que la sorci\u00e8re devenait alors, apr\u00e8s cette mont\u00e9e, poss\u00e9d\u00e9e de cet esprit revenant. En tout cas, l&rsquo;expression est consacr\u00e9e et se retrouve dans d&rsquo;autres textes de civilisations antiques (cf. <a href=\"https:\/\/archive.org\/stream\/choixdetextesrel00dhoruoft#page\/328\/mode\/2up\">Dhorme, <em>Choix de textes<\/em>, p. 338 l.19<\/a>).<\/p>\n<p style=\"text-align: justify;\">Ensuite, il y a bien le verbe <em><strong>voir<\/strong><\/em>\u00a0au verset 12 (\u05d5\u05b7\u05ea\u05b5\u05bc\u05e8\u05b6\u05d0 \u05d4\u05b8\u05d0\u05b4\u05e9\u05b8\u05bc\u05c1\u05d4 \u05d0\u05b6\u05ea\u05be\u05e9\u05b0\u05c1\u05de\u05d5\u05bc\u05d0\u05b5\u05dc). Mais c&rsquo;est <em>la sorci\u00e8re<\/em> qui voit. Et non Sa\u00fcl, qui demande : \u00ab\u00a0<strong>que vois-tu ?<\/strong>\u00a0\u00bb (<strong>verset 13<\/strong>), \u00ab\u00a0<strong>quelle est sa forme ?<\/strong>\u00a0\u00bb (<strong>verset 14<\/strong>). S&rsquo;ensuit (<strong>v. 15<\/strong> sq.) une conversation entre Samuel et Sa\u00fcl, mais qu&rsquo;il faut comprendre <em><strong>par l&rsquo;interm\u00e9diaire<\/strong><\/em> de la pythonisse. De toute fa\u00e7on, le r\u00e9cit pr\u00e9sente des curiosit\u00e9s (<strong>v. 14<\/strong> Sa\u00fcl se prosterne \u00e0 terre ; <strong>v. 20<\/strong>, il tombe de nouveau \u00e0 terre) qui en d\u00e9montrent le caract\u00e8re elliptique, suggestif et tr\u00e8s inhabituel. Il semble que Sa\u00fcl soit dans un \u00e9tat de d\u00e9tresse avanc\u00e9e (<strong>v.15<\/strong>) qui est accentu\u00e9e par son \u00e9tat \u00e0 jeun (<strong>v.20<\/strong>) et cette exp\u00e9rience nocturne (<strong>v.8<\/strong>). Ces \u00e9l\u00e9ments ont d&rsquo;ailleurs \u00e9t\u00e9 relev\u00e9s par quelques ex\u00e9g\u00e8tes pour caract\u00e9riser les antiques repas rituels pa\u00efens (cf. Caquot, p.337, et <a href=\"https:\/\/archive.org\/stream\/revuedelhistoire87v88pari#page\/48\/mode\/2up\">Reinach, p.49<\/a>\u00a0; Reinach d&rsquo;ailleurs s&rsquo;offusque de ce repas copieux dont le d\u00e9roul\u00e9 chronologique de nuit lui para\u00eet difficile).\u00a0Signalons au passage que ce r\u00e9cit contient une expression idiomatique au v.21 (\u00ab\u00a0mettre sa vie dans sa main\u00a0\u00bb) que peu de versions traduisent, et qui <em>signifie s&rsquo;exposer au danger<\/em>.<\/p>\n<p style=\"text-align: justify;\">Encore plus inhabituel, le verset 13 emploie le terme \u05d0\u05b1\u05dc\u05b9\u05d4\u05b4\u05d9\u05dd\u00a0\u00a0(dieu\/dieux\/Dieu) pour qualifier <em>le spectre<\/em> (cf. note de la NBS <em>ad loc<\/em>.). On remarque que le verbe qui d\u00e9pend de \u05d0\u05b1\u05dc\u05b9\u05d4\u05b4\u05d9\u05dd \u00a0est\u00a0\u05e2\u05b9\u05dc\u05b4\u05d9\u05dd, et qu&rsquo;il est conjugu\u00e9\u00a0<em>au pluriel<\/em>\u00a0contrairement \u00e0 l&rsquo;<a title=\"Nombres 12.15 ou le singulier collectif en h\u00e9breu biblique\" href=\"http:\/\/areopage.net\/blog\/2013\/09\/11\/nombres-12-15-ou-le-singulier-collectif-en-hebreu-biblique\/\">usage plus courant<\/a> : on pourrait donc traduire\u00a0\u05d0\u05b1\u05dc\u05b9\u05d4\u05b4\u05d9\u05dd \u05e8\u05b8\u05d0\u05b4\u05d9\u05ea\u05b4\u05d9 \u05e2\u05b9\u05dc\u05b4\u05d9\u05dd \u05de\u05b4\u05df\u05be\u05d4\u05b8\u05d0\u05b8\u05e8\u05b6\u05e5\u05c3, <em>je vois des dieux monter de la terre<\/em>. Mais si plusieurs esprits montent, du moins la description qui suit, au verset 14, ne parle que d&rsquo;un seul homme, un vieillard, muni d&rsquo;un manteau, et en lequel Sa\u00fcl reconna\u00eet Samuel. On ne peut donc rien tirer non plus de cette instance, unique, du vocable\u00a0\u05d0\u05b1\u05dc\u05b9\u05d4\u05b4\u05d9\u05dd \u00a0pour d\u00e9signer <em>l&rsquo;esprit d&rsquo;un mort<\/em>.\u00a0A moins de voir dans ce \u00ab\u00a0dieu\u00a0\u00bb un <em>d\u00e9mon<\/em> trompeur, ce que peut conforter le fait que Dieu n&rsquo;est plus avec Sa\u00fcl, mais avec David (<strong>1 Samuel 18.12 ; 28.16-17<\/strong>). Mais on retombe sur les difficult\u00e9s suivantes : pourquoi l&rsquo;oracle est-il v\u00e9ridique ? pourquoi 1 Chroniques 13.10 attribue-t-il l&rsquo;apparition \u00e0 Samuel ?<\/p>\n<p style=\"text-align: justify;\">Il est bien certain qu&rsquo;un tel r\u00e9cit interdit toute conclusion. J&rsquo;ai tendance \u00e0 penser que cette sorci\u00e8re usait ordinairement de ventriloquie (avec ou non usage d&rsquo;imposture), comme l&rsquo;indique le texte grec des Septante. Et rien de ce que dit le texte massor\u00e9tique ne s&rsquo;y oppose. On peut cependant s&rsquo;interroger sur les multiples difficult\u00e9s entourant cette <em>unique<\/em> \u00e9vocation d&rsquo;une pratique pourtant largement d\u00e9nonc\u00e9e (<strong>Deut\u00e9ronome 18.11, L\u00e9vitique 19.31, 20.6,20.27, 2 Rois 23.24<\/strong>). L&rsquo;\u00e9vocation de l&rsquo;esprit des morts \u00e9tait-elle r\u00e9pandue dans l&rsquo;Isra\u00ebl antique ? Croyait-on en une survie apr\u00e8s la mort ? Au final, que peut-on tirer positivement du r\u00e9cit de 1 Samuel 28.3-24 au regard de l&rsquo;\u00e9tat des morts ?<\/p>\n<p style=\"text-align: justify;\">Ces questions \u00e9pineuses restent ouvertes. L&rsquo;histoire de la sorci\u00e8re d&rsquo;En-Dor montre d\u00e9j\u00e0 que ces croyances existaient bel et bien, et qu&rsquo;elles sont parvenues jusqu&rsquo;\u00e0 nous dans un r\u00e9cit non exempt d&rsquo;asp\u00e9rit\u00e9s.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9cit de 1 Samuel 28.3-24 pr\u00e9sente un concentr\u00e9 de m\u00e9faits imputables au roi Sa\u00fcl qui sont bien connus. Mais quand on regarde le texte de plus pr\u00e8s, on d\u00e9couvre des difficult\u00e9s inattendues. Prenons d\u00e9j\u00e0 connaissance in extenso du r\u00e9cit, selon la version de Darby : 3 Samuel \u00e9tait mort, et tout Isra\u00ebl s&rsquo;\u00e9tait lament\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[497,499,498,500,501],"class_list":["post-1601","post","type-post","status-publish","format-standard","hentry","category-hebreu-biblique","tag-1-samuel-28-3-24","tag-divination","tag-sorciere-den-dor","tag-ventriloquie","tag-501"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-pP","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1426,"url":"http:\/\/areopage.net\/blog\/2014\/03\/22\/1-samuel-14-41-%d7%aa%d6%b8%d7%9e%d6%b4%d7%99%d7%9d-ou-%d7%aa%d6%bb%d6%bc%d7%9e%d6%b4%d6%bc%d7%99%d7%9d-lxx-vs-tm\/","url_meta":{"origin":1601,"position":0},"title":"1 Samuel 14.41 : \u05ea\u05b8\u05de\u05b4\u05d9\u05dd ou \u05ea\u05bb\u05bc\u05de\u05b4\u05bc\u05d9\u05dd ? (LXX vs TM)","author":"areopage","date":"22\/03\/2014","format":false,"excerpt":"La mani\u00e8re dont les Isra\u00e9lites consultaient l'oracle divin est \u00e0 la fois myst\u00e9rieuse et fascinante. Parmi d'autres proc\u00e9d\u00e9s (Lindblom 1962,\u00a0ABD 3:417-418, DBI 608-610, Jeffers 1996,\u00a0COS 1:421), les Ourim et Thummim n'ont cess\u00e9 d'intriguer des g\u00e9n\u00e9rations d'ex\u00e9g\u00e8tes et d'historiens. Le sujet \u00e9tant immense, je ne puis ici que renvoyer aux sources\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"http:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/03\/2203144.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/03\/2203144.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/03\/2203144.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/03\/2203144.png?resize=700%2C400 2x"},"classes":[]},{"id":1379,"url":"http:\/\/areopage.net\/blog\/2014\/02\/17\/le-livre-du-juste-josue-10-13-2-samuel-1-18\/","url_meta":{"origin":1601,"position":1},"title":"Le Livre du Juste (Josu\u00e9 10.13, 2 Samuel 1.18)","author":"areopage","date":"17\/02\/2014","format":false,"excerpt":"Josu\u00e9 10.13 :\u00a0\u05d4\u05b2\u05dc\u05b9\u05d0\u05be\u05d4\u05b4\u05d9\u05d0 \u05db\u05b0\u05ea\u05d5\u05bc\u05d1\u05b8\u05d4 \u05e2\u05b7\u05dc\u05be\u05e1\u05b5\u05e4\u05b6\u05e8 \u05d4\u05b7\u05d9\u05b8\u05bc\u05e9\u05b8\u05c1\u05e8 Cela n'est-il pas \u00e9crit dans le Livre du Juste ? 2 Samuel 1.18 :\u00a0\u05db\u05b0\u05ea\u05d5\u05bc\u05d1\u05b8\u05d4 \u05e2\u05b7\u05dc\u05be\u05e1\u05b5\u05e4\u05b6\u05e8 \u05d4\u05b7\u05d9\u05b8\u05bc\u05e9\u05b8\u05c1\u05e8\u05c3, ... il est \u00e9crit dans le Livre du Juste. La Bible fait mention d'un certain nombre de livres aujourd'hui perdus. Parmi ceux-ci des registres (historiques, juridiques), des chroniques\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"1602143","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/02\/1602143-194x300.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3152,"url":"http:\/\/areopage.net\/blog\/2015\/04\/19\/un-homme-de-lentre-deux-1-samuel-17-4\/","url_meta":{"origin":1601,"position":2},"title":"Un homme de \u00ab\u00a0l&rsquo;entre-deux\u00a0\u00bb (1 Samuel 17.4)","author":"areopage","date":"19\/04\/2015","format":false,"excerpt":"L'histoire de David et Goliath pose de nombreux probl\u00e8mes litt\u00e9raires, linguistiques, historiques, arch\u00e9ologiques ou textuels. On sait depuis longtemps que le texte massor\u00e9tique des livres de Samuel n'est pas\u00a0de bonne qualit\u00e9, et qu'en bien des endroits, il faut lui\u00a0pr\u00e9f\u00e9rer le texte de la Septante (A. Yadin 2004 : 375, Roberts\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"http:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"1904151","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/04\/1904151-300x243.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":108,"url":"http:\/\/areopage.net\/blog\/2013\/07\/22\/platon-le-mythe-de-latlantide-et-la-bible\/","url_meta":{"origin":1601,"position":3},"title":"Platon, le mythe de l&rsquo;Atlantide&#8230; et la Bible","author":"areopage","date":"22\/07\/2013","format":false,"excerpt":"La relecture du Tim\u00e9e et du Critias (Critias - L'Atlantide, Les Belles Lettres, 2002), o\u00f9 Platon \u00e9voque le mythe de l'Atlantide est pour moi l'occasion d'un constat. On conna\u00eet la post\u00e9rit\u00e9 exceptionnelle de ce mythe, qui a attir\u00e9 historiens, philosophes, et plus encore, amateurs de myst\u00e8res. J'en ai fait les\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1637,"url":"http:\/\/areopage.net\/blog\/2014\/05\/11\/le-blaspheme-contre-lesprit-matthieu-12-32-etc\/","url_meta":{"origin":1601,"position":4},"title":"Le blasph\u00e8me contre l&rsquo;Esprit (Matthieu 12.32, etc.)","author":"areopage","date":"11\/05\/2014","format":false,"excerpt":"J'ai toujours \u00e9t\u00e9 intrigu\u00e9 par ce p\u00e9ch\u00e9 impardonnable, le \"blasph\u00e8me contre l'esprit saint\" dont parle J\u00e9sus en Matthieu 12.32 (voir aussi Marc 3.28-29, 1 Jean 5.16). C'est une parole assez \u00e9nigmatique, qui n'est pas clairement explicit\u00e9e par ailleurs. L'interpr\u00e9tation traditionnelle se fonde essentiellement sur trois textes : H\u00e9breux 6.4-6, 10.26-29\u2026","rel":"","context":"Dans &quot;r\u00e9flexions&quot;","block_context":{"text":"r\u00e9flexions","link":"http:\/\/areopage.net\/blog\/category\/reflexions\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2176,"url":"http:\/\/areopage.net\/blog\/2014\/09\/09\/le-livre-desther-un-conte-de-fee\/","url_meta":{"origin":1601,"position":5},"title":"Le livre d&rsquo;Esther, un conte de f\u00e9e ?","author":"areopage","date":"09\/09\/2014","format":false,"excerpt":"Malgr\u00e9 des donn\u00e9es solidement fond\u00e9es dans l'Histoire (topographie du palais de Suse, protocole perse, existence de Mardoch\u00e9e...), de nombreux historiens contestent la valeur historique du livre d'Esther. Ainsi ce qu'on peut lire dans l'Introduction \u00e0 la Bible, I\u00a0(A. Robert et A. Feuillet dir., 2e \u00e9d., pp.690-692) : On inclinerait assez\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"Esther","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2014\/09\/Esther-150x150.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/1601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=1601"}],"version-history":[{"count":27,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/1601\/revisions"}],"predecessor-version":[{"id":1662,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/1601\/revisions\/1662"}],"wp:attachment":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=1601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=1601"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=1601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}