{"id":1178,"date":"2013-12-09T21:27:49","date_gmt":"2013-12-09T20:27:49","guid":{"rendered":"http:\/\/areopage.net\/blog\/?p=1178"},"modified":"2013-12-10T17:25:36","modified_gmt":"2013-12-10T16:25:36","slug":"vetus-latina","status":"publish","type":"post","link":"http:\/\/areopage.net\/blog\/2013\/12\/09\/vetus-latina\/","title":{"rendered":"Vetus Latina"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/12\/0912131.png\" data-rel=\"lightbox-gallery-YwDTz5tR\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-1179\" alt=\"0912131\" src=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/12\/0912131.png?resize=150%2C150\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/12\/0912131.png?resize=150%2C150 150w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/12\/0912131.png?zoom=2&amp;resize=150%2C150 300w, https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/12\/0912131.png?zoom=3&amp;resize=150%2C150 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Avant J\u00e9r\u00f4me, on se plaignait de la <em>vitiosissima varietas<\/em> (l&rsquo;extr\u00eame vari\u00e9t\u00e9) des manuscrits de la Bible (cf. <a title=\"Augustin, les versions latines et la Septante\" href=\"http:\/\/areopage.net\/blog\/2013\/10\/18\/augustin-les-versions-latines-et-la-septante\/\">Augustin<\/a> regrettant les divergences dans les versions latines ; cf. <a href=\"https:\/\/www.logos.com\/product\/1660\/anchor-yale-bible-dictionary\">ABD VI : 799-800<\/a>, <a href=\"https:\/\/www.logos.com\/product\/8801\/new-interpreters-dictionary-of-the-bible\">NIBD V : 765-769<\/a>). En effet, de tr\u00e8s nombreuses traductions (sur le grec), sans harmonie apparente, pullulaient. Il en reste encore des fragments. On les d\u00e9signe sous l&rsquo;appellation <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Vetus_Latina\">Vetus latina<\/a>.<\/p>\n<p style=\"text-align: justify;\">Dans la derni\u00e8re version <a href=\"http:\/\/areopage.net\/bpv.html\">4.9.6<\/a> de <a href=\"http:\/\/www.bibleparser.fr\/\">Bible Parser<\/a>, je vous propose de consulter simultan\u00e9ment des t\u00e9moins de la Vetus Latina (module VLA) : le <em>Codex\u00a0Vercellensis<\/em>, le <em>Codex\u00a0Veronensis<\/em>, le <em>Codex\u00a0Bobiensis<\/em>, et, pour comparer, la <em>Vulgate<\/em> et la partie latine du <em>Codex Bezae<\/em>. Notez que BP dispose aussi de la <em>Vulgate Cl\u00e9mentine<\/em> et de la <em>N\u00e9o-Vulgate<\/em>.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9dition la plus utilis\u00e9e est celle de <a href=\"http:\/\/www.exegesis.fr\/index.php?option=com_content&amp;view=category&amp;layout=blog&amp;id=65&amp;Itemid=100015\">Sabatier<\/a>. BP la propose \u00e9galement, en un volume PDF index\u00e9 (DVD 9).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avant J\u00e9r\u00f4me, on se plaignait de la vitiosissima varietas (l&rsquo;extr\u00eame vari\u00e9t\u00e9) des manuscrits de la Bible (cf. Augustin regrettant les divergences dans les versions latines ; cf. ABD VI : 799-800, NIBD V : 765-769). En effet, de tr\u00e8s nombreuses traductions (sur le grec), sans harmonie apparente, pullulaient. Il en reste encore des fragments. On [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[317,18,380,378,376,377,383,382,318,379,381],"class_list":["post-1178","post","type-post","status-publish","format-standard","hentry","category-actualites","tag-augustin","tag-bible-parser","tag-codex-bezae","tag-codex-bobiensis","tag-codex-vercellensis","tag-codex-veronensis","tag-jerome","tag-neo-vulgate","tag-vetus-latina","tag-vulgate","tag-vulgate-clementine"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3MfBZ-j0","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1034,"url":"http:\/\/areopage.net\/blog\/2013\/11\/03\/matthieu-11-12-et-le-texte-hebreu-de-shem-tob\/","url_meta":{"origin":1178,"position":0},"title":"Matthieu 11.12 et le texte h\u00e9breu de Shem Tob","author":"areopage","date":"03\/11\/2013","format":false,"excerpt":"Que faire quand un verset para\u00eet curieux, isol\u00e9, \u00a0paradoxal ? Je propose ici quelques pistes, qui ne sont pas exhaustives, avec Matthieu 11.12 \u00e0 l'esprit : 1. Texte et contexte - \u00e9tudier minutieusement le sens linguistique du verset, - puis analyser dans le contexte ce qui permet de comprendre le\u2026","rel":"","context":"Dans &quot;grec biblique&quot;","block_context":{"text":"grec biblique","link":"http:\/\/areopage.net\/blog\/category\/grec-biblique\/"},"img":{"alt_text":"0311132","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/11\/0311132-150x150.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":956,"url":"http:\/\/areopage.net\/blog\/2013\/10\/18\/augustin-les-versions-latines-et-la-septante\/","url_meta":{"origin":1178,"position":1},"title":"Augustin, les versions latines et la Septante","author":"areopage","date":"18\/10\/2013","format":false,"excerpt":"Dans le Suppl\u00e9ment aux Cahiers \u00c9vangile de d\u00e9cembre 2012 r\u00e9dig\u00e9 par Martine Dulaey, on trouve un tr\u00e8s bon floril\u00e8ge visant \u00e0 montrer comment Augustin (354 - 430 AD) abordait les \u00c9critures, avec quelle m\u00e9thode, quelle pens\u00e9e.\u00a0La partie la plus int\u00e9ressante \u00e0 mon sens est celle qui fait \u00e9tat de la\u2026","rel":"","context":"Dans &quot;lectures&quot;","block_context":{"text":"lectures","link":"http:\/\/areopage.net\/blog\/category\/lectures\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.editionsducerf.fr\/html\/livre\/couverture\/9\/couv9693g_200.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":3321,"url":"http:\/\/areopage.net\/blog\/2015\/05\/31\/bible-parser-2015-v-708\/","url_meta":{"origin":1178,"position":2},"title":"Bible Parser 2015 : v.708","author":"areopage","date":"31\/05\/2015","format":false,"excerpt":"La version 708 de Bible Parser 2015 r\u00e9serve bien des surprises. D'abord, et comme d'habitude, de nombreux bugs ont \u00e9t\u00e9 r\u00e9solus : dans l'interface, au niveau des commentaires, des apparats, de l'analyse morphologique, etc. Ensuite de nouveaux modules font leur apparition : la Peshitta (texte transcrit en h\u00e9breu vocalis\u00e9), les\u2026","rel":"","context":"Dans &quot;actualit\u00e9s&quot;","block_context":{"text":"actualit\u00e9s","link":"http:\/\/areopage.net\/blog\/category\/actualites\/"},"img":{"alt_text":"70823","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2015\/05\/70823-300x289.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1324,"url":"http:\/\/areopage.net\/blog\/2014\/01\/22\/%d7%9e%d6%b7%d7%9c%d6%b0%d7%90%d6%b7%d7%9a%d6%b0-%d7%a4%d6%b8%d6%bc%d7%a0%d6%b8%d7%99%d7%95-lange-de-sa-face-isaie-63-9\/","url_meta":{"origin":1178,"position":3},"title":"\u05de\u05b7\u05dc\u05b0\u05d0\u05b7\u05da\u05b0 \u05e4\u05b8\u05bc\u05e0\u05b8\u05d9\u05d5 = L&rsquo;ange de sa face ? (Isa\u00efe 63.9)","author":"areopage","date":"22\/01\/2014","format":false,"excerpt":"Le verset d'Isa\u00efe 63.9 est plus difficile \u00e0 comprendre et \u00e0 interpr\u00e9ter qu'il n'y para\u00eet de premier abord.\u00a0Comparons quelques versions courantes, \u00e0 partir du v.8 : 8\u00a0Il avait dit : \"Ils sont certes mon peuple, \/ des fils qui ne tromperont pas\". \/ Et il fut pour eux un sauveur\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"http:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":706,"url":"http:\/\/areopage.net\/blog\/2013\/09\/20\/deuteronome-27-4-sur-le-mont-ebal-ou-garizim-lxx-vs-tm\/","url_meta":{"origin":1178,"position":4},"title":"Deut\u00e9ronome 27.4 : sur le mont \u00c9bal ou Garizim ? (LXX vs TM)","author":"areopage","date":"20\/09\/2013","format":false,"excerpt":"On lit en Deut\u00e9ronome 27.4 : \u05d5\u05b0\u05d4\u05b8\u05d9\u05b8\u05d4 \u05d1\u05b0\u05bc\u05e2\u05b8\u05d1\u05b0\u05e8\u05b0\u05db\u05b6\u05dd \u05d0\u05b6\u05ea\u05be\u05d4\u05b7\u05d9\u05b7\u05bc\u05e8\u05b0\u05d3\u05b5\u05bc\u05df \u05ea\u05b8\u05bc\u05e7\u05b4\u05d9\u05de\u05d5\u05bc \u05d0\u05b6\u05ea\u05be\u05d4\u05b8\u05d0\u05b2\u05d1\u05b8\u05e0\u05b4\u05d9\u05dd \u05d4\u05b8\u05d0\u05b5\u05dc\u05b6\u05bc\u05d4 \u05d0\u05b2\u05e9\u05b6\u05c1\u05e8 \u05d0\u05b8\u05e0\u05b9\u05db\u05b4\u05d9 \u05de\u05b0\u05e6\u05b7\u05d5\u05b6\u05bc\u05d4 \u05d0\u05b6\u05ea\u05b0\u05db\u05b6\u05dd \u05d4\u05b7\u05d9\u05b9\u05bc\u05d5\u05dd \u05d1\u05b0\u05bc\u05d4\u05b7\u05e8 \u05e2\u05b5\u05d9\u05d1\u05b8\u05dc \u05d5\u05b0\u05e9\u05b7\u05c2\u05d3\u05b0\u05ea\u05b8\u05bc \u05d0\u05b9\u05d5\u05ea\u05b8\u05dd \u05d1\u05b7\u05bc\u05e9\u05b4\u05bc\u05c2\u05d9\u05d3\u05c3 Apr\u00e8s le passage du Jourdain, vous ferez donc l\u2019\u00e9rection de ces pierres, que je vous ordonne aujourd\u2019hui, sur le mont \u00c9bal et vous les enduirez de chaux. (Perret-Gentil)\u2026","rel":"","context":"Dans &quot;critique textuelle&quot;","block_context":{"text":"critique textuelle","link":"http:\/\/areopage.net\/blog\/category\/critique-textuelle\/"},"img":{"alt_text":"2009134","src":"https:\/\/i0.wp.com\/areopage.net\/blog\/wp-content\/uploads\/2013\/09\/2009134-300x238.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":886,"url":"http:\/\/areopage.net\/blog\/2013\/10\/11\/genese-3-6-%d7%a2%d6%b4%d7%9e%d6%b8%d6%bc%d7%94%d6%bc-qui-etait-avec-elle-ou-quand-il-fut-avec-elle\/","url_meta":{"origin":1178,"position":5},"title":"Gen\u00e8se 3.6 : \u05e2\u05b4\u05de\u05b8\u05bc\u05d4\u05bc, \u00ab\u00a0qui \u00e9tait avec elle\u00a0\u00bb ou \u00ab\u00a0quand il fut avec elle\u00a0\u00bb ?","author":"areopage","date":"11\/10\/2013","format":false,"excerpt":"Quand j'ai r\u00e9dig\u00e9 mon petit article intitul\u00e9 Gen\u00e8se 3.6c : Adam \u00e9tait-il pr\u00e9sent lors de la tentation ?, je ne me doutais pas qu'il susciterait des r\u00e9actions assez passionn\u00e9es. C'est qu'il y a toujours le volet linguistique, et le volet th\u00e9ologique. Souvent, on ignore l'un au profit de l'autre.\u00a0Nonobstant le\u2026","rel":"","context":"Dans &quot;h\u00e9breu biblique&quot;","block_context":{"text":"h\u00e9breu biblique","link":"http:\/\/areopage.net\/blog\/category\/hebreu-biblique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/comments?post=1178"}],"version-history":[{"count":6,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/1178\/revisions"}],"predecessor-version":[{"id":1188,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/posts\/1178\/revisions\/1188"}],"wp:attachment":[{"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/categories?post=1178"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/areopage.net\/blog\/wp-json\/wp\/v2\/tags?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}